{"text_format":"1","workbook":"xlsx","n_sheets":7,"sheets":["Parametros tecnológicos","Espectro MW","Modelo","Detalle","Resultados","Tablas Espectro MW","Datos"],"not_rendered":{"charts":1,"images":0,"macros":1,"external_links":1,"defined_names":57,"comments":4,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Parametros tecnológicos","index":0,"n_rows":81,"n_cols":13,"rows_kept":81,"cut":false,"hidden":false,"merged":[[3,2,3,3],[4,2,4,3],[5,2,5,3]]}
["Parámetros tecnológicos"]
[]
["Componente","Parametro","Incluir","Valor","Descripción","Referencia"]
["General","Tecnología","5G",null,"Tipologia de tecnologia presentada","NA"]
[null,"Dificultad de acceso",1,null,{"$f":"+IF(TipoEspecifico=1,\"Acceso Facil\",IF(TipoEspecifico=2,\"Acceso Dificil\",\"Complejo\"))","v":"Acceso Facil"},"NA"]
[null,"Tipo de red","Móvil",null,"Servicio móvil o fija"]
["Obra civil","Altura de torre","S",30," mts",{"$f":"+IF(C7=\"N\",\"\",IF(D7=\"\",\"\",IF(AND(D7>=12,D7<=18),\"12-18\",IF(AND(D7>=19,D7<=35),\"19-35\",IF(AND(D7>=36,D7<=45),\"36-45\",IF(AND(D7>=46,D7<=60),\"46-60\",IF(D7>60,90,\"Verificar\")))))))","v":"19-35"}]
[null,"Tipo de torre",null,"Convencional","Monopolo o convencional","NA"]
[null,"Eventos mantenimiento <= 2 años",null,0]
[null,"Eventos mantenimiento > 2 años",null,2,"Eventos mantenimiento correctivo por año"]
["Red de energia","Topología de terreno","S","Plano","Plano u ondulado",{"$f":"+\"Terreno \"&Tipo_Terreno","v":"Terreno Plano"}]
[null,"Distancia red de MT",null,500," mts lineales (500,750,1000,1500+)",{"$f":"+IF(D12=\"\",\"\",IF(D12<=500,500,IF(AND(D12>500,D12<=1000),1000,IF(D12>1000,1500,\"Verificar\"))))","v":500}]
[null,"KW - energía",null,25,"15 o 25 KW","NA"]
[null,"Eventos mantenimiento <= 2 años",null,0]
[null,"Eventos mantenimiento > 2 años",null,2]
[null,"Planta eléctrica ","S",25,"Tipo de planta BT (KW)"]
["4G / 5G / FWA","BW (MHz)","S",30,"Tecnología de acceso ",{"$f":"+TmcBw*SectorEnodeb*D25*IF(C6=\"Fija\",1,0.5)","v":585}]
[null,"Sectores",null,3,"Número de sectores"]
[null,"Eventos mantenimiento <= 2 años",null,0]
[null,"Eventos mantenimiento > 2 años",null,2]
[null,"Relacion contención / Porcentaje de uso",null,0.3,"Promedio red fija / Promedio red móvil"]
["Red de transmisión - MW","Diámetro de antena","S",1.2," mts","NA"]
[null,"Microondas",null,"28/30 MHz < 10 GHz","Equipos terminales enlace MW - HTSB"]
["Calidad / Capacidad","Calidad de servicio",null,"20 Mbps / 250 GB","Velocidad (Mbps) / Capacidad (GB)",{"$f":"+LEFT(Velocidad_Capacidad,2)","v":"20"}]
[null,"Eficiencia espectral",null,{"$f":"IF(Tipologia_Campo=\"TMC 4G\",IF(TipoRed=\"Fija\",VLOOKUP(Tipologia_Campo,$K$49:$M$54,3,0),VLOOKUP(Tipologia_Campo,$K$49:$M$54,2,0)),VLOOKUP(Tipologia_Campo,$K$49:$M$54,3,0))","v":13},"DL (Valor recomendado)"]
["Satelital","VSAT","S",null,"Incluir terminal en el modelo"]
["FWA","CPE","N",{"$f":"+IFERROR(ROUND(IF(C27=\"N\",\"\",Modelo!B13),0),\"\")","v":""},"Subscriptores / Hogares","NA"]
[{"$f":"+IF(Tipologia_Campo<>\"FTTH\",\"\",\"FTTH\")","v":""}]
[{"$f":"+IF(Tipologia_Campo<>\"FTTH\",\"\",\"Longitud Backhaul (Km)\")","v":""}]
[{"$f":"+IF(Tipologia_Campo<>\"FTTH\",\"\",\"Cantidad Postes\")","v":""}]
[{"$f":"+IF(Tipologia_Campo<>\"FTTH\",\"\",\"Splitters\")","v":""}]
[{"$f":"+IF(Tipologia_Campo<>\"FTTH\",\"\",\"Longitud Acometida (Metros / Hogar)\")","v":""}]
["Velocidad de transporte Mbps"]
["Parametros Energía Solar - Repetidora","Potencia (W)",{"$f":"+IF(Tipologia_Campo=\"Repetidora\",\"S\",\"N\")","v":"N"},null,"W"]
[null,"Costo",null,null,"W/USD"]
[null,"Factor Potencia de Diseño",null,null,"Int."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["4G - BW (MHz)",null,null,"4G - Enlace De Transmision Mw Htsb (Diametro de antena Mts)",null,null,"Tipo de planta",null,"Energia - Kw",null,"Tipologia","movil","fija"]
[null,null,null,null,null,null,null,null,null,null,"TMC 4G",1.7,13]
[10,null,null,1.2,null,null,"A",null,15,null,"FTTH",0,0]
[20,null,null,1.8,null,null,"B",null,25,null,"LTE No Lic BH Microondas",null,7]
[30,null,null,2.4,null,null,null,null,null,null,"LTE No Lic BH Satelital",null,7]
[null,null,null,3.7,null,null,null,null,null,null,"5G",null,13]
[null,null,null,null,null,null,null,null,null,null,"Repetidora"]
["Mto 4G",null,null,"WiFi LTE - Velocidad (Mbps) / Capacidad (Gb)",null,null,"Red de Energia - Tipo de terreno",null,"Equipos",null,"Clase torre"]
[1,null,null,"5 Mbps / 50 GB",null,null,"Ondulado",null,"5G (1+0+0) 10 MHz",null,"Monopolo"]
[2,null,null,"5 Mbps / 100 GB",null,null,"Plano",null,"5G (1+1+0) 10 MHz",null,"Convencional"]
[null,null,null,"5 Mbps / 150 GB",null,null,null,null,"5G (1+1+1) 10 MHz"]
[null,null,null,"5 Mbps / 200 GB",null,null,null,null,"5G (1+1+0) 20 MHz"]
[null,null,null,"5 Mbps / 250 GB",null,null,null,null,"5G (1+1+1) 20 MHz"]
["Sector enodeb",null,null,"10 Mbps / 50 GB",null,null,null,null,"5G (1+1+1) 30 MHz"]
[1,null,null,"10 Mbps / 100 GB"]
[2,null,null,"10 Mbps / 150 GB"]
[3,null,null,"10 Mbps / 200 GB"]
[null,null,null,"10 Mbps / 250 GB"]
[null,null,null,"20 Mbps / 50 GB"]
[null,null,null,"20 Mbps / 100 GB"]
[null,null,null,"20 Mbps / 150 GB"]
[null,null,null,"20 Mbps / 200 GB"]
["Equipos terminales enlace MW - HTSB",null,null,"20 Mbps / 250 GB"]
["28/30 MHz < 10 GHz"]
["28/30 MHz >10 GHz"]
["56 MHz < 10 GHz",null,null,"Planta electrica",null,null,"Incluir"]
["56 MHz > 10 GHz",null,null,5,null,null,"S"]
[null,null,null,15,null,null,"N"]
[null,null,null,25]
["Tipo dificultad acceso"]
[1]
[2,null,null,"Tipo de red"]
[3,null,null,"Fija"]
[null,null,null,"Móvil"]

{"sheet":"Espectro MW","index":1,"n_rows":9,"n_cols":3,"rows_kept":9,"cut":false,"hidden":false,"merged":[]}
["Calculo del Valor Anual de Contraprestaciones (VAC)"]
[]
["Variable","Descripción","Valor"]
["Valor publicado por el MINTIC",null,859584.41]
["Ancho de Banda (MHz)",null,28]
["Valores del factor de valoracióńn de banda (MHz)",7200,{"$f":"+IF(B6<=1000,1,IF(AND(B6>1000,B6<=3000),0.8,IF(AND(B6>3000,B6<=3700),0.7,IF(AND(B6>3700,B6<=7100),0.612,IF(AND(B6>7100,B6<=14000),0.544,IF(AND(B6>14000,B6<=20000),0.476,IF(AND(B6>20000,B6<=30000),0.408,IF(AND(B6>30000,B6<=70000),0.0375,IF(AND(B6>70000,B6<=300000),0.0055,0)))))))))","v":0.54400000000000004}]
["Valores del factor de distancia","Satisface la distancia mínima del CNABF ",{"$f":"+VLOOKUP(B7,'Tablas Espectro MW'!$A$43:$C$46,2,0)","v":0.9}]
["Valores del factor de priorizacióń","Cabeceras municipales que no se ubican en departamentos priorizados ",{"$f":"+VLOOKUP(B8,'Tablas Espectro MW'!$A$20:$B$23,2,0)","v":0.8}]
["Valor Anual de Contraprestaciones (Para un enlace simétrico - La resolución no es clara en como se aplica para cada segmento)",null,{"$f":"+(C4*(C5)*C6*C7)*C8*2","v":18854193.215692803}]

{"sheet":"Modelo","index":2,"n_rows":101,"n_cols":126,"rows_kept":101,"cut":false,"hidden":false,"merged":[[87,0,87,2],[76,0,76,2],[16,0,16,2],[17,0,17,2],[41,0,41,2],[57,0,57,2],[52,0,52,2]]}
["Modelo Financiero - MinTIC"]
[]
["Parámetros","Valor",null,"Concepto",{"$f":"+YEAR(B7)","v":2020},{"$f":"+E3+1","v":2021},2022,2023,2024,2025,2026,2027,2028,2029,2030]
["TRM",4000,null,"IPC",0.03,0.03,0.03,0.03,0.03,0.03,0.03,0.03,0.03,0.03,0.03]
["Valor del proyecto",{"$f":"+SUM(F9:DV10)","v":1701697651.8042638},null,"Acumulado",1,{"$f":"(1+E4)*E5","v":1.03},1.0609,1.092727,1.1255088100000001,1.1592740743000001,1.1940522965290001,1.2298738654248702,1.2667700813876164,1.3047731838292449,1.3439163793441222]
["Imprevistos",0.05,null,"Pagos anuales CAPEX",{"$f":"+SUMIF($F$8:$DW$8,E3,$F$9:$DV$9)","v":596915003.41457367},{"$f":"+SUMIF($F$8:$DV$8,F3,$F$9:$DV$9)","v":0},0,0,0,0,0,0,0,0,0]
["Fecha inicio obra","2020-05-28",null,"Pagos anuales OPEX",{"$f":"+SUMIF($F$8:$DV$8,E3,$F$10:$DV$10)","v":117931973.65226418},208290767.09483352,239882393.5969457,254284079.97150961,261912602.37065503,22480831.703481223,0,0,0,0,0]
["Fecha inicio funcionamiento","2020-07-01",null,null,null,{"$f":"+YEAR(F16)","v":2020},2020,2020,2020,2020,2020,2020,2020,2021,2021,2021,2021,2021,2021,2021,2021,2021,2021,2021,2021,2022,2022,2022,2022,2022,2022,2022,2022,2022,2022,2022,2022,{"$f":"+YEAR(AL16)","v":2023},2023,2023,2023,2023,2023,2023,2023,2023,2023,2023,2023,2024,2024,2024,2024,2024,2024,2024,2024,2024,2024,2024,2024,2025,2025,2025,2025,2025,2025,2025,2025,{"$f":"+YEAR(BR16)","v":2025},2025,2025,2025,2026,2026,2026,2026,2026,2026,2026,2026,2026,2026,2026,2026,2027,2027,2027,2027,2027,2027,2027,2027,2027,2027,2027,2027,2028,2028,2028,2028,{"$f":"+YEAR(CX16)","v":2028},2028,2028,2028,2028,2028,2028,2028,2029,2029,2029,2029,2029,2029,2029,2029,2029,2029,2029,2029,2030,2030,2030,2030,2030]
["Tiempo reconocimiento OPEX (meses)",56,null,null,"Flujo de Caja CAPEX",{"$f":"+SUM(F20:F26,F36:F40,F44:F46,F50:F52,F59:F61,F66:F74,F77:F86,F90:F91)","v":596915003.41457367},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(AL20:AL26,AL36:AL40,AL44:AL46,AL50:AL52,AL59:AL61,AL66:AL74,AL77:AL86,AL90:AL91)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(BR20:BR26,BR36:BR40,BR44:BR46,BR50:BR52,BR59:BR61,BR66:BR74,BR77:BR86,BR90:BR91)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(CX20:CX26,CX36:CX40,CX44:CX46,CX50:CX52,CX59:CX61,CX66:CX74,CX77:CX86,CX90:CX91)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Tiempo reconocimiento OPEX (Recomendado)",{"$f":"IF(IF((F9/(B11*B12-AVERAGEIF(G10:DV10,\">0\")))>120,120,(F9/(B11*B12-AVERAGEIF(G10:DV10,\">0\"))))<0,120,IF((F9/(B11*B12-AVERAGEIF(G10:DV10,\">0\")))>120,120,(F9/(B11*B12-AVERAGEIF(G10:DV10,\">0\")))))","v":4.8683764032282433},null,null,"Flujo de Caja OPEX",{"$f":"+SUM(F19,F27:F35,F43,F47:F48,F54:F57,F62:F65,F75,F89)+F11+F12","v":29845750.170728683},0,15247230.701415917,15247230.701415917,15247230.701415917,12060445.701415917,15142042.837935917,15142042.837935917,15596304.123073995,15596304.123073995,15596304.123073995,15596304.123073995,15596304.123073995,18615606.639923368,18615606.639923368,18615606.639923368,18615606.639923368,18615606.639923368,18615606.639923368,18615606.639923368,19174074.83912107,19174074.83912107,19174074.83912107,19174074.83912107,19174074.83912107,20573145.628762916,20573145.628762916,20573145.628762916,20573145.628762916,20573145.628762916,20573145.628762916,20573145.628762916,{"$f":"+SUM(AL19,AL27:AL35,AL43,AL47:AL48,AL54:AL57,AL62:AL65,AL75,AL89)+AL11+AL12","v":21190339.997625805},21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21190339.997625805,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,21826050.197554581,22480831.703481223,0,0,0,0,0,0,0,{"$f":"+SUM(BR19,BR27:BR35,BR43,BR47:BR48,BR54:BR57,BR62:BR65,BR75,BR89)+BR11+BR12","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(CX19,CX27:CX35,CX43,CX47:CX48,CX54:CX57,CX62:CX65,CX75,CX89)+CX11+CX12","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["ARPU",50000,null,null,"Gastos administrativos",{"$f":"+SUM(F19,F27:F35,F43,F47:F48,F54:F57,F62:F65,F75,F89)*4.7%","v":0},0,653254.18684279686,653254.18684279686,653254.18684279686,516719.1868427968,648747.50536279683,648747.50536279683,668209.93052368076,668209.93052368076,668209.93052368076,668209.93052368076,668209.93052368076,797070.59677800885,797070.59677800885,797070.59677800885,797070.59677800885,797070.59677800885,797070.59677800885,797070.59677800885,820982.714681349,820982.714681349,820982.714681349,820982.714681349,820982.714681349,880924.67194038897,880924.67194038897,880924.67194038897,880924.67194038897,880924.67194038897,880924.67194038897,880924.67194038897,{"$f":"+SUM(AL19,AL27:AL35,AL43,AL47:AL48,AL54:AL57,AL62:AL65,AL75,AL89)*4.7%","v":907352.41209860065},907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,907352.41209860065,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,934572.98446155887,962610.1739954059,0,0,0,0,0,0,0,{"$f":"+SUM(BR19,BR27:BR35,BR43,BR47:BR48,BR54:BR57,BR62:BR65,BR75,BR89)*4.7%","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(CX19,CX27:CX35,CX43,CX47:CX48,CX54:CX57,CX62:CX65,CX75,CX89)*4.7%","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Subscriptores / hogares",{"$f":"SubscriptoresSugeridos","v":2843.1},null,null,"Imprevistos",{"$f":"+SUM(F17:F91)*$B$6","v":29845750.170728683},0,694951.26259872003,694951.26259872003,694951.26259872003,549701.26259872003,690156.92059872008,690156.92059872008,710861.62821668165,710861.62821668165,710861.62821668165,710861.62821668165,710861.62821668165,859587.17552815157,859587.17552815157,859587.17552815157,859587.17552815157,859587.17552815157,859587.17552815157,859587.17552815157,885374.79079399619,885374.79079399619,885374.79079399619,885374.79079399619,885374.79079399619,949142.83043127274,949142.83043127274,949142.83043127274,949142.83043127274,949142.83043127274,949142.83043127274,949142.83043127274,{"$f":"+SUM(AL17:AL91)*$B$6","v":977617.11534421099},977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,977617.11534421099,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1006945.6288045374,1037153.9976686735,0,0,0,0,0,0,0,{"$f":"+SUM(BR17:BR91)*$B$6","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+SUM(CX17:CX91)*$B$6","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Subscriptores / hogares recomendados",{"$f":"IFERROR(IF(TipoRed=\"Fija\",ValocidadPromedioDL/(RelacionContencion*Velocidad),(ValocidadPromedioDL*RelacionContencion*3600*24*30)/(8000*Velocidad)),0)","v":2843.1},null,null,{"$f":"+DAY(F16)","v":1},1,2,2,2,3,3,4,4,4,7,7,8,8,9,9,9,10,10,11,11,11,14,14,15,15,16,16,16,17,17,18,18,18,21,21,22,22,23,23,23,24,24,25,3,{"$f":"+DAY(AY16)","v":3},{"$f":"+DAY(AZ16)","v":5},{"$f":"+DAY(BA16)","v":5},{"$f":"+DAY(BB16)","v":6},6,7,7,7,8,8,9,9,9,12,12,13,{"$f":"+DAY(BO16)","v":13},14,14,14,15,15,16,16,16,19,19,20,20,21,21,21,22,22,23,23,23,26,26,27,{"$f":"+DAY(CM16)","v":27},28,28,28,29,29,30,8,8,10,10,11,11,12,12,12,13,13,14,14,14,17,17,18,18,19,19,19,20,20,21,21,21,24,24,25]
["CAPEX total",{"$f":"+SUM(B20:B26,B36:B40,B44:B46,B50:B52,B59:B61,B66:B74,B78:B86,B90:B91)","v":596915003.41457367},null,null,1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25,26,27,28,29,30,31,32,33,34,35,36,37,38,39,40,41,42,43,44,45,46,47,48,49,50,51,52,53,54,55,56,57,58,59,60,61,62,63,64,65,66,67,68,69,70,71,72,73,74,75,76,77,78,79,80,81,82,83,84,85,86,87,88,89,90,91,92,93,94,95,96,97,98,99,100,101,102,103,104,105,106,107,108,109,110,111,112,113,114,115,116,117,118,119,120,121]
["Costo total por Usuario",{"$f":"B5/SubscriptoresSugeridos","v":598535.9824854082},null,null,null,0,1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21,22,23,24,25,26,27,28,29,30,31,32,33,34,35,36,37,38,39,40,41,42,43,44,45,46,47,48,49,50,51,52,53,54,55,56,57,58,59,60,61,62,63,64,65,66,67,68,69,70,71,72,73,74,75,76,77,78,79,80,81,82,83,84,85,86,87,88,89,90,91,92,93,94,95,96,97,98,99,100,101,102,103,104,105,106,107,108,109,110,111,112,113,114,115,116,117,118,119,120]
["CONCEPTO","CAPEX","OPEX","Periodo de Inicio","Periodos a reconocer",{"$f":"+DATE(YEAR($B$7),MONTH(B7),1)","v":"2020-05-01"},{"$f":"+IF(AND(MONTH(F16)=12,OR(YEAR(F16)=2023,YEAR(F16)=2027)),F16+Datos!$A$11-22,F16+Datos!$A$11)","v":"2020-06-01"},{"$f":"+IF(AND(MONTH(G16)=12,OR(YEAR(G16)=2023,YEAR(G16)=2027)),G16+Datos!$A$11-22,G16+Datos!$A$11)","v":"2020-07-02"},{"$f":"+IF(AND(MONTH(H16)=12,OR(YEAR(H16)=2023,YEAR(H16)=2027)),H16+Datos!$A$11-22,H16+Datos!$A$11)","v":"2020-08-02"},{"$f":"+IF(AND(MONTH(I16)=12,OR(YEAR(I16)=2023,YEAR(I16)=2027)),I16+Datos!$A$11-22,I16+Datos!$A$11)","v":"2020-09-02"},{"$f":"+IF(AND(MONTH(J16)=12,OR(YEAR(J16)=2023,YEAR(J16)=2027)),J16+Datos!$A$11-22,J16+Datos!$A$11)","v":"2020-10-03"},{"$f":"+IF(AND(MONTH(K16)=12,OR(YEAR(K16)=2023,YEAR(K16)=2027)),K16+Datos!$A$11-22,K16+Datos!$A$11)","v":"2020-11-03"},{"$f":"+IF(AND(MONTH(L16)=12,OR(YEAR(L16)=2023,YEAR(L16)=2027)),L16+Datos!$A$11-22,L16+Datos!$A$11)","v":"2020-12-04"},{"$f":"+IF(AND(MONTH(M16)=12,OR(YEAR(M16)=2023,YEAR(M16)=2027)),M16+Datos!$A$11-22,M16+Datos!$A$11)","v":"2021-01-04"},{"$f":"+IF(AND(MONTH(N16)=12,OR(YEAR(N16)=2023,YEAR(N16)=2027)),N16+Datos!$A$11-22,N16+Datos!$A$11)","v":"2021-02-04"},{"$f":"+IF(AND(MONTH(O16)=12,OR(YEAR(O16)=2023,YEAR(O16)=2027)),O16+Datos!$A$11-22,O16+Datos!$A$11)","v":"2021-03-07"},{"$f":"+IF(AND(MONTH(P16)=12,OR(YEAR(P16)=2023,YEAR(P16)=2027)),P16+Datos!$A$11-22,P16+Datos!$A$11)","v":"2021-04-07"},{"$f":"+IF(AND(MONTH(Q16)=12,OR(YEAR(Q16)=2023,YEAR(Q16)=2027)),Q16+Datos!$A$11-22,Q16+Datos!$A$11)","v":"2021-05-08"},{"$f":"+IF(AND(MONTH(R16)=12,OR(YEAR(R16)=2023,YEAR(R16)=2027)),R16+Datos!$A$11-22,R16+Datos!$A$11)","v":"2021-06-08"},{"$f":"+IF(AND(MONTH(S16)=12,OR(YEAR(S16)=2023,YEAR(S16)=2027)),S16+Datos!$A$11-22,S16+Datos!$A$11)","v":"2021-07-09"},{"$f":"+IF(AND(MONTH(T16)=12,OR(YEAR(T16)=2023,YEAR(T16)=2027)),T16+Datos!$A$11-22,T16+Datos!$A$11)","v":"2021-08-09"},{"$f":"+IF(AND(MONTH(U16)=12,OR(YEAR(U16)=2023,YEAR(U16)=2027)),U16+Datos!$A$11-22,U16+Datos!$A$11)","v":"2021-09-09"},{"$f":"+IF(AND(MONTH(V16)=12,OR(YEAR(V16)=2023,YEAR(V16)=2027)),V16+Datos!$A$11-22,V16+Datos!$A$11)","v":"2021-10-10"},{"$f":"+IF(AND(MONTH(W16)=12,OR(YEAR(W16)=2023,YEAR(W16)=2027)),W16+Datos!$A$11-22,W16+Datos!$A$11)","v":"2021-11-10"},{"$f":"+IF(AND(MONTH(X16)=12,OR(YEAR(X16)=2023,YEAR(X16)=2027)),X16+Datos!$A$11-22,X16+Datos!$A$11)","v":"2021-12-11"},{"$f":"+IF(AND(MONTH(Y16)=12,OR(YEAR(Y16)=2023,YEAR(Y16)=2027)),Y16+Datos!$A$11-22,Y16+Datos!$A$11)","v":"2022-01-11"},{"$f":"+IF(AND(MONTH(Z16)=12,OR(YEAR(Z16)=2023,YEAR(Z16)=2027)),Z16+Datos!$A$11-22,Z16+Datos!$A$11)","v":"2022-02-11"},{"$f":"+IF(AND(MONTH(AA16)=12,OR(YEAR(AA16)=2023,YEAR(AA16)=2027)),AA16+Datos!$A$11-22,AA16+Datos!$A$11)","v":"2022-03-14"},{"$f":"+IF(AND(MONTH(AB16)=12,OR(YEAR(AB16)=2023,YEAR(AB16)=2027)),AB16+Datos!$A$11-22,AB16+Datos!$A$11)","v":"2022-04-14"},{"$f":"+IF(AND(MONTH(AC16)=12,OR(YEAR(AC16)=2023,YEAR(AC16)=2027)),AC16+Datos!$A$11-22,AC16+Datos!$A$11)","v":"2022-05-15"},{"$f":"+IF(AND(MONTH(AD16)=12,OR(YEAR(AD16)=2023,YEAR(AD16)=2027)),AD16+Datos!$A$11-22,AD16+Datos!$A$11)","v":"2022-06-15"},{"$f":"+IF(AND(MONTH(AE16)=12,OR(YEAR(AE16)=2023,YEAR(AE16)=2027)),AE16+Datos!$A$11-22,AE16+Datos!$A$11)","v":"2022-07-16"},{"$f":"+IF(AND(MONTH(AF16)=12,OR(YEAR(AF16)=2023,YEAR(AF16)=2027)),AF16+Datos!$A$11-22,AF16+Datos!$A$11)","v":"2022-08-16"},{"$f":"+IF(AND(MONTH(AG16)=12,OR(YEAR(AG16)=2023,YEAR(AG16)=2027)),AG16+Datos!$A$11-22,AG16+Datos!$A$11)","v":"2022-09-16"},{"$f":"+IF(AND(MONTH(AH16)=12,OR(YEAR(AH16)=2023,YEAR(AH16)=2027)),AH16+Datos!$A$11-22,AH16+Datos!$A$11)","v":"2022-10-17"},{"$f":"+IF(AND(MONTH(AI16)=12,OR(YEAR(AI16)=2023,YEAR(AI16)=2027)),AI16+Datos!$A$11-22,AI16+Datos!$A$11)","v":"2022-11-17"},{"$f":"+IF(AND(MONTH(AJ16)=12,OR(YEAR(AJ16)=2023,YEAR(AJ16)=2027)),AJ16+Datos!$A$11-22,AJ16+Datos!$A$11)","v":"2022-12-18"},{"$f":"+IF(AND(MONTH(AK16)=12,OR(YEAR(AK16)=2023,YEAR(AK16)=2027)),AK16+Datos!$A$11-22,AK16+Datos!$A$11)","v":"2023-01-18"},{"$f":"+IF(AND(MONTH(AL16)=12,OR(YEAR(AL16)=2023,YEAR(AL16)=2027)),AL16+Datos!$A$11-22,AL16+Datos!$A$11)","v":"2023-02-18"},{"$f":"+IF(AND(MONTH(AM16)=12,OR(YEAR(AM16)=2023,YEAR(AM16)=2027)),AM16+Datos!$A$11-22,AM16+Datos!$A$11)","v":"2023-03-21"},{"$f":"+IF(AND(MONTH(AN16)=12,OR(YEAR(AN16)=2023,YEAR(AN16)=2027)),AN16+Datos!$A$11-22,AN16+Datos!$A$11)","v":"2023-04-21"},{"$f":"+IF(AND(MONTH(AO16)=12,OR(YEAR(AO16)=2023,YEAR(AO16)=2027)),AO16+Datos!$A$11-22,AO16+Datos!$A$11)","v":"2023-05-22"},{"$f":"+IF(AND(MONTH(AP16)=12,OR(YEAR(AP16)=2023,YEAR(AP16)=2027)),AP16+Datos!$A$11-22,AP16+Datos!$A$11)","v":"2023-06-22"},{"$f":"+IF(AND(MONTH(AQ16)=12,OR(YEAR(AQ16)=2023,YEAR(AQ16)=2027)),AQ16+Datos!$A$11-22,AQ16+Datos!$A$11)","v":"2023-07-23"},{"$f":"+IF(AND(MONTH(AR16)=12,OR(YEAR(AR16)=2023,YEAR(AR16)=2027)),AR16+Datos!$A$11-22,AR16+Datos!$A$11)","v":"2023-08-23"},{"$f":"+IF(AND(MONTH(AS16)=12,OR(YEAR(AS16)=2023,YEAR(AS16)=2027)),AS16+Datos!$A$11-22,AS16+Datos!$A$11)","v":"2023-09-23"},{"$f":"+IF(AND(MONTH(AT16)=12,OR(YEAR(AT16)=2023,YEAR(AT16)=2027)),AT16+Datos!$A$11-22,AT16+Datos!$A$11)","v":"2023-10-24"},{"$f":"+IF(AND(MONTH(AU16)=12,OR(YEAR(AU16)=2023,YEAR(AU16)=2027)),AU16+Datos!$A$11-22,AU16+Datos!$A$11)","v":"2023-11-24"},{"$f":"+IF(AND(MONTH(AV16)=12,OR(YEAR(AV16)=2023,YEAR(AV16)=2027)),AV16+Datos!$A$11-22,AV16+Datos!$A$11)","v":"2023-12-25"},{"$f":"+IF(AND(MONTH(AW16)=12,OR(YEAR(AW16)=2023,YEAR(AW16)=2027)),AW16+Datos!$A$11-22,AW16+Datos!$A$11)","v":"2024-01-03"},{"$f":"+IF(AND(MONTH(AX16)=12,OR(YEAR(AX16)=2023,YEAR(AX16)=2027)),AX16+Datos!$A$11-22,AX16+Datos!$A$11)","v":"2024-02-03"},{"$f":"+IF(AND(MONTH(AY16)=12,OR(YEAR(AY16)=2023,YEAR(AY16)=2027)),AY16+Datos!$A$11-22,AY16+Datos!$A$11)","v":"2024-03-05"},{"$f":"+IF(AND(MONTH(AZ16)=12,OR(YEAR(AZ16)=2023,YEAR(AZ16)=2027)),AZ16+Datos!$A$11-22,AZ16+Datos!$A$11)","v":"2024-04-05"},{"$f":"+IF(AND(MONTH(BA16)=12,OR(YEAR(BA16)=2023,YEAR(BA16)=2027)),BA16+Datos!$A$11-22,BA16+Datos!$A$11)","v":"2024-05-06"},{"$f":"+IF(AND(MONTH(BB16)=12,OR(YEAR(BB16)=2023,YEAR(BB16)=2027)),BB16+Datos!$A$11-22,BB16+Datos!$A$11)","v":"2024-06-06"},{"$f":"+IF(AND(MONTH(BC16)=12,OR(YEAR(BC16)=2023,YEAR(BC16)=2027)),BC16+Datos!$A$11-22,BC16+Datos!$A$11)","v":"2024-07-07"},{"$f":"+IF(AND(MONTH(BD16)=12,OR(YEAR(BD16)=2023,YEAR(BD16)=2027)),BD16+Datos!$A$11-22,BD16+Datos!$A$11)","v":"2024-08-07"},{"$f":"+IF(AND(MONTH(BE16)=12,OR(YEAR(BE16)=2023,YEAR(BE16)=2027)),BE16+Datos!$A$11-22,BE16+Datos!$A$11)","v":"2024-09-07"},{"$f":"+IF(AND(MONTH(BF16)=12,OR(YEAR(BF16)=2023,YEAR(BF16)=2027)),BF16+Datos!$A$11-22,BF16+Datos!$A$11)","v":"2024-10-08"},{"$f":"+IF(AND(MONTH(BG16)=12,OR(YEAR(BG16)=2023,YEAR(BG16)=2027)),BG16+Datos!$A$11-22,BG16+Datos!$A$11)","v":"2024-11-08"},{"$f":"+IF(AND(MONTH(BH16)=12,OR(YEAR(BH16)=2023,YEAR(BH16)=2027)),BH16+Datos!$A$11-22,BH16+Datos!$A$11)","v":"2024-12-09"},{"$f":"+IF(AND(MONTH(BI16)=12,OR(YEAR(BI16)=2023,YEAR(BI16)=2027)),BI16+Datos!$A$11-22,BI16+Datos!$A$11)","v":"2025-01-09"},{"$f":"+IF(AND(MONTH(BJ16)=12,OR(YEAR(BJ16)=2023,YEAR(BJ16)=2027)),BJ16+Datos!$A$11-22,BJ16+Datos!$A$11)","v":"2025-02-09"},{"$f":"+IF(AND(MONTH(BK16)=12,OR(YEAR(BK16)=2023,YEAR(BK16)=2027)),BK16+Datos!$A$11-22,BK16+Datos!$A$11)","v":"2025-03-12"},{"$f":"+IF(AND(MONTH(BL16)=12,OR(YEAR(BL16)=2023,YEAR(BL16)=2027)),BL16+Datos!$A$11-22,BL16+Datos!$A$11)","v":"2025-04-12"},{"$f":"+IF(AND(MONTH(BM16)=12,OR(YEAR(BM16)=2023,YEAR(BM16)=2027)),BM16+Datos!$A$11-22,BM16+Datos!$A$11)","v":"2025-05-13"},{"$f":"+IF(AND(MONTH(BN16)=12,OR(YEAR(BN16)=2023,YEAR(BN16)=2027)),BN16+Datos!$A$11-22,BN16+Datos!$A$11)","v":"2025-06-13"},{"$f":"+IF(AND(MONTH(BO16)=12,OR(YEAR(BO16)=2023,YEAR(BO16)=2027)),BO16+Datos!$A$11-22,BO16+Datos!$A$11)","v":"2025-07-14"},{"$f":"+IF(AND(MONTH(BP16)=12,OR(YEAR(BP16)=2023,YEAR(BP16)=2027)),BP16+Datos!$A$11-22,BP16+Datos!$A$11)","v":"2025-08-14"},{"$f":"+IF(AND(MONTH(BQ16)=12,OR(YEAR(BQ16)=2023,YEAR(BQ16)=2027)),BQ16+Datos!$A$11-22,BQ16+Datos!$A$11)","v":"2025-09-14"},{"$f":"+IF(AND(MONTH(BR16)=12,OR(YEAR(BR16)=2023,YEAR(BR16)=2027)),BR16+Datos!$A$11-22,BR16+Datos!$A$11)","v":"2025-10-15"},{"$f":"+IF(AND(MONTH(BS16)=12,OR(YEAR(BS16)=2023,YEAR(BS16)=2027)),BS16+Datos!$A$11-22,BS16+Datos!$A$11)","v":"2025-11-15"},{"$f":"+IF(AND(MONTH(BT16)=12,OR(YEAR(BT16)=2023,YEAR(BT16)=2027)),BT16+Datos!$A$11-22,BT16+Datos!$A$11)","v":"2025-12-16"},{"$f":"+IF(AND(MONTH(BU16)=12,OR(YEAR(BU16)=2023,YEAR(BU16)=2027)),BU16+Datos!$A$11-22,BU16+Datos!$A$11)","v":"2026-01-16"},{"$f":"+IF(AND(MONTH(BV16)=12,OR(YEAR(BV16)=2023,YEAR(BV16)=2027)),BV16+Datos!$A$11-22,BV16+Datos!$A$11)","v":"2026-02-16"},{"$f":"+IF(AND(MONTH(BW16)=12,OR(YEAR(BW16)=2023,YEAR(BW16)=2027)),BW16+Datos!$A$11-22,BW16+Datos!$A$11)","v":"2026-03-19"},{"$f":"+IF(AND(MONTH(BX16)=12,OR(YEAR(BX16)=2023,YEAR(BX16)=2027)),BX16+Datos!$A$11-22,BX16+Datos!$A$11)","v":"2026-04-19"},{"$f":"+IF(AND(MONTH(BY16)=12,OR(YEAR(BY16)=2023,YEAR(BY16)=2027)),BY16+Datos!$A$11-22,BY16+Datos!$A$11)","v":"2026-05-20"},{"$f":"+IF(AND(MONTH(BZ16)=12,OR(YEAR(BZ16)=2023,YEAR(BZ16)=2027)),BZ16+Datos!$A$11-22,BZ16+Datos!$A$11)","v":"2026-06-20"},{"$f":"+IF(AND(MONTH(CA16)=12,OR(YEAR(CA16)=2023,YEAR(CA16)=2027)),CA16+Datos!$A$11-22,CA16+Datos!$A$11)","v":"2026-07-21"},{"$f":"+IF(AND(MONTH(CB16)=12,OR(YEAR(CB16)=2023,YEAR(CB16)=2027)),CB16+Datos!$A$11-22,CB16+Datos!$A$11)","v":"2026-08-21"},{"$f":"+IF(AND(MONTH(CC16)=12,OR(YEAR(CC16)=2023,YEAR(CC16)=2027)),CC16+Datos!$A$11-22,CC16+Datos!$A$11)","v":"2026-09-21"},{"$f":"+IF(AND(MONTH(CD16)=12,OR(YEAR(CD16)=2023,YEAR(CD16)=2027)),CD16+Datos!$A$11-22,CD16+Datos!$A$11)","v":"2026-10-22"},{"$f":"+IF(AND(MONTH(CE16)=12,OR(YEAR(CE16)=2023,YEAR(CE16)=2027)),CE16+Datos!$A$11-22,CE16+Datos!$A$11)","v":"2026-11-22"},{"$f":"+IF(AND(MONTH(CF16)=12,OR(YEAR(CF16)=2023,YEAR(CF16)=2027)),CF16+Datos!$A$11-22,CF16+Datos!$A$11)","v":"2026-12-23"},{"$f":"+IF(AND(MONTH(CG16)=12,OR(YEAR(CG16)=2023,YEAR(CG16)=2027)),CG16+Datos!$A$11-22,CG16+Datos!$A$11)","v":"2027-01-23"},{"$f":"+IF(AND(MONTH(CH16)=12,OR(YEAR(CH16)=2023,YEAR(CH16)=2027)),CH16+Datos!$A$11-22,CH16+Datos!$A$11)","v":"2027-02-23"},{"$f":"+IF(AND(MONTH(CI16)=12,OR(YEAR(CI16)=2023,YEAR(CI16)=2027)),CI16+Datos!$A$11-22,CI16+Datos!$A$11)","v":"2027-03-26"},{"$f":"+IF(AND(MONTH(CJ16)=12,OR(YEAR(CJ16)=2023,YEAR(CJ16)=2027)),CJ16+Datos!$A$11-22,CJ16+Datos!$A$11)","v":"2027-04-26"},{"$f":"+IF(AND(MONTH(CK16)=12,OR(YEAR(CK16)=2023,YEAR(CK16)=2027)),CK16+Datos!$A$11-22,CK16+Datos!$A$11)","v":"2027-05-27"},{"$f":"+IF(AND(MONTH(CL16)=12,OR(YEAR(CL16)=2023,YEAR(CL16)=2027)),CL16+Datos!$A$11-22,CL16+Datos!$A$11)","v":"2027-06-27"},{"$f":"+IF(AND(MONTH(CM16)=12,OR(YEAR(CM16)=2023,YEAR(CM16)=2027)),CM16+Datos!$A$11-22,CM16+Datos!$A$11)","v":"2027-07-28"},{"$f":"+IF(AND(MONTH(CN16)=12,OR(YEAR(CN16)=2023,YEAR(CN16)=2027)),CN16+Datos!$A$11-22,CN16+Datos!$A$11)","v":"2027-08-28"},{"$f":"+IF(AND(MONTH(CO16)=12,OR(YEAR(CO16)=2023,YEAR(CO16)=2027)),CO16+Datos!$A$11-22,CO16+Datos!$A$11)","v":"2027-09-28"},{"$f":"+IF(AND(MONTH(CP16)=12,OR(YEAR(CP16)=2023,YEAR(CP16)=2027)),CP16+Datos!$A$11-22,CP16+Datos!$A$11)","v":"2027-10-29"},{"$f":"+IF(AND(MONTH(CQ16)=12,OR(YEAR(CQ16)=2023,YEAR(CQ16)=2027)),CQ16+Datos!$A$11-22,CQ16+Datos!$A$11)","v":"2027-11-29"},{"$f":"+IF(AND(MONTH(CR16)=12,OR(YEAR(CR16)=2023,YEAR(CR16)=2027)),CR16+Datos!$A$11-22,CR16+Datos!$A$11)","v":"2027-12-30"},{"$f":"+IF(AND(MONTH(CS16)=12,OR(YEAR(CS16)=2023,YEAR(CS16)=2027)),CS16+Datos!$A$11-22,CS16+Datos!$A$11)","v":"2028-01-08"},{"$f":"+IF(AND(MONTH(CT16)=12,OR(YEAR(CT16)=2023,YEAR(CT16)=2027)),CT16+Datos!$A$11-22,CT16+Datos!$A$11)","v":"2028-02-08"},{"$f":"+IF(AND(MONTH(CU16)=12,OR(YEAR(CU16)=2023,YEAR(CU16)=2027)),CU16+Datos!$A$11-22,CU16+Datos!$A$11)","v":"2028-03-10"},{"$f":"+IF(AND(MONTH(CV16)=12,OR(YEAR(CV16)=2023,YEAR(CV16)=2027)),CV16+Datos!$A$11-22,CV16+Datos!$A$11)","v":"2028-04-10"},{"$f":"+IF(AND(MONTH(CW16)=12,OR(YEAR(CW16)=2023,YEAR(CW16)=2027)),CW16+Datos!$A$11-22,CW16+Datos!$A$11)","v":"2028-05-11"},{"$f":"+IF(AND(MONTH(CX16)=12,OR(YEAR(CX16)=2023,YEAR(CX16)=2027)),CX16+Datos!$A$11-22,CX16+Datos!$A$11)","v":"2028-06-11"},{"$f":"+IF(AND(MONTH(CY16)=12,OR(YEAR(CY16)=2023,YEAR(CY16)=2027)),CY16+Datos!$A$11-22,CY16+Datos!$A$11)","v":"2028-07-12"},{"$f":"+IF(AND(MONTH(CZ16)=12,OR(YEAR(CZ16)=2023,YEAR(CZ16)=2027)),CZ16+Datos!$A$11-22,CZ16+Datos!$A$11)","v":"2028-08-12"},{"$f":"+IF(AND(MONTH(DA16)=12,OR(YEAR(DA16)=2023,YEAR(DA16)=2027)),DA16+Datos!$A$11-22,DA16+Datos!$A$11)","v":"2028-09-12"},{"$f":"+IF(AND(MONTH(DB16)=12,OR(YEAR(DB16)=2023,YEAR(DB16)=2027)),DB16+Datos!$A$11-22,DB16+Datos!$A$11)","v":"2028-10-13"},{"$f":"+IF(AND(MONTH(DC16)=12,OR(YEAR(DC16)=2023,YEAR(DC16)=2027)),DC16+Datos!$A$11-22,DC16+Datos!$A$11)","v":"2028-11-13"},{"$f":"+IF(AND(MONTH(DD16)=12,OR(YEAR(DD16)=2023,YEAR(DD16)=2027)),DD16+Datos!$A$11-22,DD16+Datos!$A$11)","v":"2028-12-14"},{"$f":"+IF(AND(MONTH(DE16)=12,OR(YEAR(DE16)=2023,YEAR(DE16)=2027)),DE16+Datos!$A$11-22,DE16+Datos!$A$11)","v":"2029-01-14"},{"$f":"+IF(AND(MONTH(DF16)=12,OR(YEAR(DF16)=2023,YEAR(DF16)=2027)),DF16+Datos!$A$11-22,DF16+Datos!$A$11)","v":"2029-02-14"},{"$f":"+IF(AND(MONTH(DG16)=12,OR(YEAR(DG16)=2023,YEAR(DG16)=2027)),DG16+Datos!$A$11-22,DG16+Datos!$A$11)","v":"2029-03-17"},{"$f":"+IF(AND(MONTH(DH16)=12,OR(YEAR(DH16)=2023,YEAR(DH16)=2027)),DH16+Datos!$A$11-22,DH16+Datos!$A$11)","v":"2029-04-17"},{"$f":"+IF(AND(MONTH(DI16)=12,OR(YEAR(DI16)=2023,YEAR(DI16)=2027)),DI16+Datos!$A$11-22,DI16+Datos!$A$11)","v":"2029-05-18"},{"$f":"+IF(AND(MONTH(DJ16)=12,OR(YEAR(DJ16)=2023,YEAR(DJ16)=2027)),DJ16+Datos!$A$11-22,DJ16+Datos!$A$11)","v":"2029-06-18"},{"$f":"+IF(AND(MONTH(DK16)=12,OR(YEAR(DK16)=2023,YEAR(DK16)=2027)),DK16+Datos!$A$11-22,DK16+Datos!$A$11)","v":"2029-07-19"},{"$f":"+IF(AND(MONTH(DL16)=12,OR(YEAR(DL16)=2023,YEAR(DL16)=2027)),DL16+Datos!$A$11-22,DL16+Datos!$A$11)","v":"2029-08-19"},{"$f":"+IF(AND(MONTH(DM16)=12,OR(YEAR(DM16)=2023,YEAR(DM16)=2027)),DM16+Datos!$A$11-22,DM16+Datos!$A$11)","v":"2029-09-19"},{"$f":"+IF(AND(MONTH(DN16)=12,OR(YEAR(DN16)=2023,YEAR(DN16)=2027)),DN16+Datos!$A$11-22,DN16+Datos!$A$11)","v":"2029-10-20"},{"$f":"+IF(AND(MONTH(DO16)=12,OR(YEAR(DO16)=2023,YEAR(DO16)=2027)),DO16+Datos!$A$11-22,DO16+Datos!$A$11)","v":"2029-11-20"},{"$f":"+IF(AND(MONTH(DP16)=12,OR(YEAR(DP16)=2023,YEAR(DP16)=2027)),DP16+Datos!$A$11-22,DP16+Datos!$A$11)","v":"2029-12-21"},{"$f":"+IF(AND(MONTH(DQ16)=12,OR(YEAR(DQ16)=2023,YEAR(DQ16)=2027)),DQ16+Datos!$A$11-22,DQ16+Datos!$A$11)","v":"2030-01-21"},{"$f":"+IF(AND(MONTH(DR16)=12,OR(YEAR(DR16)=2023,YEAR(DR16)=2027)),DR16+Datos!$A$11-22,DR16+Datos!$A$11)","v":"2030-02-21"},{"$f":"+IF(AND(MONTH(DS16)=12,OR(YEAR(DS16)=2023,YEAR(DS16)=2027)),DS16+Datos!$A$11-22,DS16+Datos!$A$11)","v":"2030-03-24"},{"$f":"+IF(AND(MONTH(DT16)=12,OR(YEAR(DT16)=2023,YEAR(DT16)=2027)),DT16+Datos!$A$11-22,DT16+Datos!$A$11)","v":"2030-04-24"},{"$f":"+IF(AND(MONTH(DU16)=12,OR(YEAR(DU16)=2023,YEAR(DU16)=2027)),DU16+Datos!$A$11-22,DU16+Datos!$A$11)","v":"2030-05-25"}]
[{"$f":"+'Parametros tecnológicos'!C4","v":"5G"},null,null,null,null,{"$f":"+IF($A17=\"\",\"\",$B17+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C17,0))","v":0},{"$f":"+(IF($A17=\"\",\"\",IF($D17>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E17<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D17,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C17))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A17=\"\",\"\",IF($D17>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E17<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D17,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C17))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A17=\"\",\"\",IF($D17>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E17<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D17,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C17))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A17=\"\",\"\",IF($D17>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E17<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D17,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C17))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["4G / 5G / FWA",null,null,null,null,0,{"$f":"+(IF($A18=\"\",\"\",IF($D18>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E18<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D18,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C18))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A18=\"\",\"\",IF($D18>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E18<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D18,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C18))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A18=\"\",\"\",IF($D18>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E18<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D18,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C18))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A18=\"\",\"\",IF($D18>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E18<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D18,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C18))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Consumo Combustible / Mensual",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A19,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)","v":2809113.16},5,{"$f":"+MesesReconocimiento","v":56},0,{"$f":"+(IF($A19=\"\",\"\",IF($D19>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E19<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D19+IF($D19<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C19))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,2809113.16,2809113.16,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2893386.5548,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,2980188.1514440002,3069593.7959873201,{"$f":"+(IF($A19=\"\",\"\",IF($D19>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E19<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D19+IF($D19<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C19))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":3069593.7959873201},3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3069593.7959873201,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3161681.60986694,3256532.0581629481,0,0,0,0,0,0,0,0,{"$f":"+(IF($A19=\"\",\"\",IF($D19>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E19<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D19+IF($D19<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C19))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A19=\"\",\"\",IF($D19>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E19<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D19+IF($D19<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C19))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Digital EnodeB",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A20,Relacion,TmcBw,RangoSectorEnodeb,SectorEnodeb)","v":76824981.915378869},null,null,56,{"$f":"+IF($A20=\"\",\"\",IF($D20=F$15,$B20+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C20,0),0))","v":76824981.915378869},{"$f":"+IF($A20=\"\",\"\",IF($D20=G$15,$B20+IF(MONTH($B$8)-MONTH($B$7)+$E$14=F$14,$C20,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A20=\"\",\"\",IF($D20=BS$15,$B20+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BR$14,$C20,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Antena De Transmision",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A21,Relacion,DiametroAntenaMts)","v":5501720},null,null,56,5501720,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Equipos terminales enlace MW - HTSB",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A22,Detalle,MWEquiposHTSB)","v":162609440},null,null,56,162609440,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Instalación Enodeb Tipo1",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A23,Relacion,TmcBw,Tipo,TipoEspecifico)","v":14587755.857000001},null,null,56,14587755.857000001,{"$f":"+IF($A23=\"\",\"\",IF($D23=G$15,$B23+IF(MONTH($B$8)-MONTH($B$7)+$E$14=F$14,$C23,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A23=\"\",\"\",IF($D23=CX$15,$B23+IF(MONTH($B$8)-MONTH($B$7)+$E$14=CW$14,$C23,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Instalación Enodeb Tipo2",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A24,Relacion,TmcBw,Tipo,TipoEspecifico)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A24=\"\",\"\",IF($D24=BS$15,$B24+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BR$14,$C24,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Instalación Enodeb Tipo3",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A25,Relacion,TmcBw,Tipo,TipoEspecifico)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Licencias",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A26,Relacion,TmcBw,RangoSectorEnodeb,SectorEnodeb)","v":36785280},null,null,56,36785280,{"$f":"+IF($A26=\"\",\"\",IF($D26=G$15,$B26+IF(MONTH($B$8)-MONTH($B$7)+$E$14=F$14,$C26,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Correctivo Enlace De Transmision Mw /Evento",null,{"$f":"+IF(EventosMmto=\"\",0,SUMIFS(ValoresMercado,Conceptos,A27,Tipo,TipoEspecifico)/(12/EventosMmtoEquipos))","v":333333.33333333331},null,{"$f":"+MesesReconocimiento","v":56},0,{"$f":"+(IF($A27=\"\",\"\",IF($D27>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E27<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D27+IF($D27<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C27))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))*IF(G$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,353633.33333333331,353633.33333333331,353633.33333333331,353633.33333333331,353633.33333333331,353633.33333333331,353633.33333333331,364242.33333333331,{"$f":"+(IF($A27=\"\",\"\",IF($D27>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E27<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D27+IF($D27<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C27))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))*IF(AM$15<=24,MmtoGarantia3,1)","v":364242.33333333331},364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,364242.33333333331,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,375169.60333333333,386424.69143333333,0,0,0,0,0,0,0,0,{"$f":"+(IF($A27=\"\",\"\",IF($D27>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E27<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D27+IF($D27<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C27))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))*IF(BS$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A27=\"\",\"\",IF($D27>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E27<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D27+IF($D27<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C27))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))*IF(CY$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Correctivo Enodeb Estimado / Evento",null,{"$f":"+IF(EventosMmto=\"\",0,SUMIFS(ValoresMercado,Conceptos,A28,Tipo,TipoEspecifico)/(12/EventosMmtoEquipos))","v":500000},null,{"$f":"+MesesReconocimiento","v":56},0,{"$f":"+(IF($A28=\"\",\"\",IF($D28>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E28<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D28+IF($D28<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C28))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))*IF(G$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,530450,530450,530450,530450,530450,530450,530450,546363.5,{"$f":"+(IF($A28=\"\",\"\",IF($D28>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E28<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D28+IF($D28<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C28))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))*IF(AM$15<=24,MmtoGarantia3,1)","v":546363.5},546363.5,546363.5,546363.5,546363.5,546363.5,546363.5,546363.5,546363.5,546363.5,546363.5,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,562754.40500000003,579637.03714999999,0,0,0,0,0,0,0,0,{"$f":"+(IF($A28=\"\",\"\",IF($D28>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E28<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D28+IF($D28<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C28))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))*IF(BS$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A28=\"\",\"\",IF($D28>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E28<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D28+IF($D28<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C28))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))*IF(CY$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Correctivo Planta Electrica / Evento",null,{"$f":"+IF(EventosMmto=\"\",0,SUMIFS(ValoresMercado,Conceptos,A29,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)/(12/EventosMmtoEquipos))","v":202149.8659115179},null,56,0,{"$f":"+(IF($A29=\"\",\"\",IF($D29>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E29<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D29+IF($D29<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C29))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))*IF(G$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,214460.79274552932,214460.79274552932,214460.79274552932,214460.79274552932,214460.79274552932,214460.79274552932,214460.79274552932,220894.61652789521,{"$f":"+(IF($A29=\"\",\"\",IF($D29>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E29<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D29+IF($D29<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C29))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))*IF(AM$15<=24,MmtoGarantia3,1)","v":220894.61652789521},220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,220894.61652789521,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,227521.45502373209,234347.09867444405,0,0,0,0,0,0,0,0,{"$f":"+(IF($A29=\"\",\"\",IF($D29>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E29<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D29+IF($D29<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C29))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))*IF(BS$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A29=\"\",\"\",IF($D29>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E29<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D29+IF($D29<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C29))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))*IF(CY$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Correctivo Transferencia Y Control / Evento",null,{"$f":"+IF(EventosMmto=\"\",0,SUMIFS(ValoresMercado,Conceptos,A30,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)/(12/EventosMmtoEquipos))","v":166666.66666666666},null,56,0,{"$f":"+(IF($A30=\"\",\"\",IF($D30>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E30<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D30+IF($D30<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C30))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))*IF(G$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,176816.66666666666,176816.66666666666,176816.66666666666,176816.66666666666,176816.66666666666,176816.66666666666,176816.66666666666,182121.16666666666,{"$f":"+(IF($A30=\"\",\"\",IF($D30>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E30<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D30+IF($D30<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C30))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))*IF(AM$15<=24,MmtoGarantia3,1)","v":182121.16666666666},182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,182121.16666666666,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,187584.80166666667,193212.34571666666,0,0,0,0,0,0,0,0,{"$f":"+(IF($A30=\"\",\"\",IF($D30>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E30<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D30+IF($D30<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C30))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))*IF(BS$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A30=\"\",\"\",IF($D30>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E30<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D30+IF($D30<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C30))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))*IF(CY$15<=24,MmtoGarantia3,1)","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Digital Enodeb Soporte Fabricante /Anual",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A31,Tipo,TipoEspecifico)/12","v":246909.65362483228},null,56,0,{"$f":"+(IF($A31=\"\",\"\",IF(G$15>12,IF($D31>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C31))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(H$15>12,IF($D31>MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(H$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=G$14,$C31))))*HLOOKUP(YEAR(H$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(I$15>12,IF($D31>MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(I$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=H$14,$C31))))*HLOOKUP(YEAR(I$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(J$15>12,IF($D31>MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(J$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=I$14,$C31))))*HLOOKUP(YEAR(J$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(K$15>12,IF($D31>MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(K$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=J$14,$C31))))*HLOOKUP(YEAR(K$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(L$15>12,IF($D31>MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(L$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=K$14,$C31))))*HLOOKUP(YEAR(L$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(M$15>12,IF($D31>MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(M$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=L$14,$C31))))*HLOOKUP(YEAR(M$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(N$15>12,IF($D31>MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(N$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=M$14,$C31))))*HLOOKUP(YEAR(N$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(O$15>12,IF($D31>MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(O$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=N$14,$C31))))*HLOOKUP(YEAR(O$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(P$15>12,IF($D31>MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(P$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=O$14,$C31))))*HLOOKUP(YEAR(P$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(Q$15>12,IF($D31>MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(Q$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=P$14,$C31))))*HLOOKUP(YEAR(Q$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(R$15>12,IF($D31>MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(R$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Q$14,$C31))))*HLOOKUP(YEAR(R$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(S$15>12,IF($D31>MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(S$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=R$14,$C31))))*HLOOKUP(YEAR(S$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(T$15>12,IF($D31>MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(T$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=S$14,$C31))))*HLOOKUP(YEAR(T$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(U$15>12,IF($D31>MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(U$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=T$14,$C31))))*HLOOKUP(YEAR(U$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(V$15>12,IF($D31>MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(V$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=U$14,$C31))))*HLOOKUP(YEAR(V$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(W$15>12,IF($D31>MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(W$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=V$14,$C31))))*HLOOKUP(YEAR(W$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(X$15>12,IF($D31>MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(X$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=W$14,$C31))))*HLOOKUP(YEAR(X$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(Y$15>12,IF($D31>MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(Y$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=X$14,$C31))))*HLOOKUP(YEAR(Y$16),$E$3:$O$5,3,0),0)))","v":254316.94323357724},{"$f":"+(IF($A31=\"\",\"\",IF(Z$15>12,IF($D31>MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(Z$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Y$14,$C31))))*HLOOKUP(YEAR(Z$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AA$15>12,IF($D31>MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Z$14,$C31))))*HLOOKUP(YEAR(AA$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AB$15>12,IF($D31>MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AA$14,$C31))))*HLOOKUP(YEAR(AB$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AC$15>12,IF($D31>MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AB$14,$C31))))*HLOOKUP(YEAR(AC$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AD$15>12,IF($D31>MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AC$14,$C31))))*HLOOKUP(YEAR(AD$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AE$15>12,IF($D31>MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AD$14,$C31))))*HLOOKUP(YEAR(AE$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AF$15>12,IF($D31>MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AE$14,$C31))))*HLOOKUP(YEAR(AF$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AG$15>12,IF($D31>MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AF$14,$C31))))*HLOOKUP(YEAR(AG$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AH$15>12,IF($D31>MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AG$14,$C31))))*HLOOKUP(YEAR(AH$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AI$15>12,IF($D31>MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AH$14,$C31))))*HLOOKUP(YEAR(AI$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AJ$15>12,IF($D31>MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AI$14,$C31))))*HLOOKUP(YEAR(AJ$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AK$15>12,IF($D31>MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AJ$14,$C31))))*HLOOKUP(YEAR(AK$16),$E$3:$O$5,3,0),0)))","v":261946.45153058454},{"$f":"+(IF($A31=\"\",\"\",IF(AL$15>12,IF($D31>MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AK$14,$C31))))*HLOOKUP(YEAR(AL$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AM$15>12,IF($D31>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C31))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AN$15>12,IF($D31>MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AM$14,$C31))))*HLOOKUP(YEAR(AN$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AO$15>12,IF($D31>MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AN$14,$C31))))*HLOOKUP(YEAR(AO$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AP$15>12,IF($D31>MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AO$14,$C31))))*HLOOKUP(YEAR(AP$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AQ$15>12,IF($D31>MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AP$14,$C31))))*HLOOKUP(YEAR(AQ$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AR$15>12,IF($D31>MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AQ$14,$C31))))*HLOOKUP(YEAR(AR$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AS$15>12,IF($D31>MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AR$14,$C31))))*HLOOKUP(YEAR(AS$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AT$15>12,IF($D31>MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AS$14,$C31))))*HLOOKUP(YEAR(AT$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AU$15>12,IF($D31>MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AT$14,$C31))))*HLOOKUP(YEAR(AU$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AV$15>12,IF($D31>MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AU$14,$C31))))*HLOOKUP(YEAR(AV$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AW$15>12,IF($D31>MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AV$14,$C31))))*HLOOKUP(YEAR(AW$16),$E$3:$O$5,3,0),0)))","v":269804.84507650213},{"$f":"+(IF($A31=\"\",\"\",IF(AX$15>12,IF($D31>MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AW$14,$C31))))*HLOOKUP(YEAR(AX$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(AY$15>12,IF($D31>MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AX$14,$C31))))*HLOOKUP(YEAR(AY$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(AZ$15>12,IF($D31>MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(AZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AY$14,$C31))))*HLOOKUP(YEAR(AZ$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BA$15>12,IF($D31>MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AZ$14,$C31))))*HLOOKUP(YEAR(BA$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BB$15>12,IF($D31>MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BA$14,$C31))))*HLOOKUP(YEAR(BB$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BC$15>12,IF($D31>MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BB$14,$C31))))*HLOOKUP(YEAR(BC$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BD$15>12,IF($D31>MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BC$14,$C31))))*HLOOKUP(YEAR(BD$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BE$15>12,IF($D31>MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BD$14,$C31))))*HLOOKUP(YEAR(BE$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BF$15>12,IF($D31>MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BE$14,$C31))))*HLOOKUP(YEAR(BF$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BG$15>12,IF($D31>MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BF$14,$C31))))*HLOOKUP(YEAR(BG$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BH$15>12,IF($D31>MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BG$14,$C31))))*HLOOKUP(YEAR(BH$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BI$15>12,IF($D31>MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BH$14,$C31))))*HLOOKUP(YEAR(BI$16),$E$3:$O$5,3,0),0)))","v":277898.9904287972},{"$f":"+(IF($A31=\"\",\"\",IF(BJ$15>12,IF($D31>MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BI$14,$C31))))*HLOOKUP(YEAR(BJ$16),$E$3:$O$5,3,0),0)))","v":286235.96014166111},{"$f":"+(IF($A31=\"\",\"\",IF(BK$15>12,IF($D31>MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BJ$14,$C31))))*HLOOKUP(YEAR(BK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BL$15>12,IF($D31>MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BK$14,$C31))))*HLOOKUP(YEAR(BL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BM$15>12,IF($D31>MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BL$14,$C31))))*HLOOKUP(YEAR(BM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BN$15>12,IF($D31>MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BM$14,$C31))))*HLOOKUP(YEAR(BN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BO$15>12,IF($D31>MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BN$14,$C31))))*HLOOKUP(YEAR(BO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BP$15>12,IF($D31>MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BO$14,$C31))))*HLOOKUP(YEAR(BP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BQ$15>12,IF($D31>MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BP$14,$C31))))*HLOOKUP(YEAR(BQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BR$15>12,IF($D31>MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BQ$14,$C31))))*HLOOKUP(YEAR(BR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BS$15>12,IF($D31>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C31))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BT$15>12,IF($D31>MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BS$14,$C31))))*HLOOKUP(YEAR(BT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BU$15>12,IF($D31>MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BT$14,$C31))))*HLOOKUP(YEAR(BU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BV$15>12,IF($D31>MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BU$14,$C31))))*HLOOKUP(YEAR(BV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BW$15>12,IF($D31>MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BV$14,$C31))))*HLOOKUP(YEAR(BW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BX$15>12,IF($D31>MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BW$14,$C31))))*HLOOKUP(YEAR(BX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BY$15>12,IF($D31>MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BX$14,$C31))))*HLOOKUP(YEAR(BY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(BZ$15>12,IF($D31>MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(BZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BY$14,$C31))))*HLOOKUP(YEAR(BZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CA$15>12,IF($D31>MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BZ$14,$C31))))*HLOOKUP(YEAR(CA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CB$15>12,IF($D31>MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CA$14,$C31))))*HLOOKUP(YEAR(CB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CC$15>12,IF($D31>MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CB$14,$C31))))*HLOOKUP(YEAR(CC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CD$15>12,IF($D31>MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CC$14,$C31))))*HLOOKUP(YEAR(CD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CE$15>12,IF($D31>MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CD$14,$C31))))*HLOOKUP(YEAR(CE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CF$15>12,IF($D31>MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CE$14,$C31))))*HLOOKUP(YEAR(CF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CG$15>12,IF($D31>MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CF$14,$C31))))*HLOOKUP(YEAR(CG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CH$15>12,IF($D31>MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CG$14,$C31))))*HLOOKUP(YEAR(CH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CI$15>12,IF($D31>MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CH$14,$C31))))*HLOOKUP(YEAR(CI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CJ$15>12,IF($D31>MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CI$14,$C31))))*HLOOKUP(YEAR(CJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CK$15>12,IF($D31>MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CJ$14,$C31))))*HLOOKUP(YEAR(CK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CL$15>12,IF($D31>MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CK$14,$C31))))*HLOOKUP(YEAR(CL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CM$15>12,IF($D31>MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CL$14,$C31))))*HLOOKUP(YEAR(CM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CN$15>12,IF($D31>MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CM$14,$C31))))*HLOOKUP(YEAR(CN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CO$15>12,IF($D31>MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CN$14,$C31))))*HLOOKUP(YEAR(CO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CP$15>12,IF($D31>MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CO$14,$C31))))*HLOOKUP(YEAR(CP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CQ$15>12,IF($D31>MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CP$14,$C31))))*HLOOKUP(YEAR(CQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CR$15>12,IF($D31>MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CQ$14,$C31))))*HLOOKUP(YEAR(CR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CS$15>12,IF($D31>MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CR$14,$C31))))*HLOOKUP(YEAR(CS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CT$15>12,IF($D31>MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CS$14,$C31))))*HLOOKUP(YEAR(CT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CU$15>12,IF($D31>MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CT$14,$C31))))*HLOOKUP(YEAR(CU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CV$15>12,IF($D31>MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CU$14,$C31))))*HLOOKUP(YEAR(CV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CW$15>12,IF($D31>MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CV$14,$C31))))*HLOOKUP(YEAR(CW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CX$15>12,IF($D31>MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CW$14,$C31))))*HLOOKUP(YEAR(CX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CY$15>12,IF($D31>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C31))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(CZ$15>12,IF($D31>MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(CZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CY$14,$C31))))*HLOOKUP(YEAR(CZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DA$15>12,IF($D31>MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CZ$14,$C31))))*HLOOKUP(YEAR(DA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DB$15>12,IF($D31>MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DA$14,$C31))))*HLOOKUP(YEAR(DB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DC$15>12,IF($D31>MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DB$14,$C31))))*HLOOKUP(YEAR(DC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DD$15>12,IF($D31>MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DC$14,$C31))))*HLOOKUP(YEAR(DD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DE$15>12,IF($D31>MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DD$14,$C31))))*HLOOKUP(YEAR(DE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DF$15>12,IF($D31>MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DE$14,$C31))))*HLOOKUP(YEAR(DF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DG$15>12,IF($D31>MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DF$14,$C31))))*HLOOKUP(YEAR(DG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DH$15>12,IF($D31>MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DG$14,$C31))))*HLOOKUP(YEAR(DH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DI$15>12,IF($D31>MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DH$14,$C31))))*HLOOKUP(YEAR(DI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DJ$15>12,IF($D31>MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DI$14,$C31))))*HLOOKUP(YEAR(DJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DK$15>12,IF($D31>MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DJ$14,$C31))))*HLOOKUP(YEAR(DK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DL$15>12,IF($D31>MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DK$14,$C31))))*HLOOKUP(YEAR(DL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DM$15>12,IF($D31>MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DL$14,$C31))))*HLOOKUP(YEAR(DM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DN$15>12,IF($D31>MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DM$14,$C31))))*HLOOKUP(YEAR(DN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DO$15>12,IF($D31>MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DN$14,$C31))))*HLOOKUP(YEAR(DO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DP$15>12,IF($D31>MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DO$14,$C31))))*HLOOKUP(YEAR(DP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DQ$15>12,IF($D31>MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DP$14,$C31))))*HLOOKUP(YEAR(DQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DR$15>12,IF($D31>MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DQ$14,$C31))))*HLOOKUP(YEAR(DR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DS$15>12,IF($D31>MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DR$14,$C31))))*HLOOKUP(YEAR(DS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DT$15>12,IF($D31>MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DS$14,$C31))))*HLOOKUP(YEAR(DT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DU$15>12,IF($D31>MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DT$14,$C31))))*HLOOKUP(YEAR(DU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A31=\"\",\"\",IF(DV$15>12,IF($D31>MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion))+1,0,IF($E31<=(MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion)))-$D31+IF($D31<>\"\",1,0),0,IF(DV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DU$14,$C31))))*HLOOKUP(YEAR(DV$16),$E$3:$O$5,3,0),0)))","v":0}]
["Mto Enlace De Transmision Mw Soporte Fabricante /Anual",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A32,Tipo,TipoEspecifico)/12","v":83333.333333333328},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,85833.333333333328,85833.333333333328,85833.333333333328,85833.333333333328,85833.333333333328,85833.333333333328,85833.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,88408.333333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,91060.583333333328,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,93792.400833333333,96606.172858333332,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Preventivo Transferencia Y Control / Anual",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A33,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)/12","v":25000},null,56,0,{"$f":"+(IF($A33=\"\",\"\",IF(G$15>12,IF($D33>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E33<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D33+IF($D33<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C33))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0),0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,25750,25750,25750,25750,25750,25750,25750,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,26522.5,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,27318.174999999999,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28137.720250000002,28981.851857500002,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Preventivoplanta Electrica / Anual",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A34,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)/12","v":230630.16666666666},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,237549.07166666666,237549.07166666666,237549.07166666666,237549.07166666666,237549.07166666666,237549.07166666666,237549.07166666666,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,244675.54381666664,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,252015.81013116665,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,259576.2844351017,267363.57296815474,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Sistema De Seguridad Electronica",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A35)/12","v":806980.10166666668},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,831189.50471666665,831189.50471666665,831189.50471666665,831189.50471666665,831189.50471666665,831189.50471666665,831189.50471666665,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,856125.18985816662,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,881808.94555391173,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,908263.21392052912,935511.11033814494,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Planta Electrica",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A36,Tipo,TipoEspecifico,Relacion,PlantaElectrica)","v":66997840},null,null,56,{"$f":"+IF($A36=\"\",\"\",IF($D36=F$15,$B36+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C36,0),0))","v":66997840},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A36=\"\",\"\",IF($D36=BR$15,$B36+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C36,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Rectificador Y Baterias Para Enodob",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A37,Relacion,TmcBw,RangoSectorEnodeb,SectorEnodeb)","v":26695200},null,null,56,{"$f":"+IF($A37=\"\",\"\",IF($D37=F$15,$B37+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C37,0),0))","v":26695200},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Sistema De Seguridad Electronica",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A38,Tipo,TipoEspecifico)","v":21061031.199999999},null,null,56,21061031.199999999,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Transferencia Y Control",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A39,Tipo,TipoEspecifico,Relacion,KW_EnergiaValor)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["CPE",{"$f":"+IF('Parametros tecnológicos'!C27=\"S\",Detalle!P966,0)","v":0},null,null,56,0,0,0,{"$f":"+IF($A40=\"\",\"\",IF($D40=I$15,$B40+IF(MONTH($B$8)-MONTH($B$7)+$E$14=H$14,$C40,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A40=\"\",\"\",IF($D40=CT$15,$B40+IF(MONTH($B$8)-MONTH($B$7)+$E$14=CS$14,$C40,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Energia Solar - Repetidora",{"$f":"+IF('Parametros tecnológicos'!$C$34=\"S\",Detalle!$P$967,0)","v":0},null,null,56,{"$f":"+IF($A41=\"\",\"\",IF($D41=F$15,$B41+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C41,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A41=\"\",\"\",IF($D41=BS$15,$B41+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BR$14,$C41,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["OBRA CIVIL",null,null,null,56,0,{"$f":"+(IF($A42=\"\",\"\",IF($D42>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E42<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D42,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C42))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A42=\"\",\"\",IF($D42>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E42<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D42,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C42))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A42=\"\",\"\",IF($D42>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E42<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D42,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C42))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A42=\"\",\"\",IF($D42>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E42<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D42,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C42))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Arriendo",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A43,Tipo,TipoEspecifico,Relacion,'Parametros tecnológicos'!$F$7)","v":7067789.5},null,56,0,{"$f":"+(IF($A43=\"\",\"\",IF($D43>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E43<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D43+IF($D43<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C43))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},7067789.5,7067789.5,7067789.5,7067789.5,7067789.5,7067789.5,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7279823.1850000005,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7498217.8805499999,7723164.4169664998,{"$f":"+(IF($A43=\"\",\"\",IF($D43>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E43<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D43+IF($D43<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C43))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":7723164.4169664998},7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7723164.4169664998,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,7954859.3494754955,8193505.1299597602,0,0,0,0,0,0,0,0,{"$f":"+(IF($A43=\"\",\"\",IF($D43>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E43<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D43+IF($D43<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C43))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A43=\"\",\"\",IF($D43>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E43<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D43+IF($D43<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C43))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Obra civil - Caseta Para Equipos",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A44,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico)","v":6329992.5},null,null,56,{"$f":"+IF($A44=\"\",\"\",IF($D44=F$15,$B44+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C44,0),0))","v":6329992.5},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A44=\"\",\"\",IF($D44=BR$15,$B44+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C44,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Obra civil - Encerramiento",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A45,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico)","v":23430725},null,null,56,{"$f":"+IF($A45=\"\",\"\",IF($D45=F$15,$B45+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C45,0),0))","v":23430725},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Obra civil - Trasiegos",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A46,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico)","v":12000000},null,null,56,12000000,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A47,Tipo,TipoEspecifico,Relacion,'Parametros tecnológicos'!$F$7,ClaseTorreRango,ClaseTorre)/12","v":592410},null,56,0,{"$f":"+(IF($A47=\"\",\"\",IF(G$15>12,IF($D47>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C47))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(H$15>12,IF($D47>MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(H$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=G$14,$C47))))*HLOOKUP(YEAR(H$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(I$15>12,IF($D47>MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(I$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=H$14,$C47))))*HLOOKUP(YEAR(I$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(J$15>12,IF($D47>MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(J$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=I$14,$C47))))*HLOOKUP(YEAR(J$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(K$15>12,IF($D47>MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(K$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=J$14,$C47))))*HLOOKUP(YEAR(K$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(L$15>12,IF($D47>MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(L$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=K$14,$C47))))*HLOOKUP(YEAR(L$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(M$15>12,IF($D47>MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(M$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=L$14,$C47))))*HLOOKUP(YEAR(M$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(N$15>12,IF($D47>MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(N$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=M$14,$C47))))*HLOOKUP(YEAR(N$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(O$15>12,IF($D47>MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(O$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=N$14,$C47))))*HLOOKUP(YEAR(O$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(P$15>12,IF($D47>MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(P$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=O$14,$C47))))*HLOOKUP(YEAR(P$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(Q$15>12,IF($D47>MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(Q$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=P$14,$C47))))*HLOOKUP(YEAR(Q$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(R$15>12,IF($D47>MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(R$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Q$14,$C47))))*HLOOKUP(YEAR(R$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(S$15>12,IF($D47>MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(S$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=R$14,$C47))))*HLOOKUP(YEAR(S$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(T$15>12,IF($D47>MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(T$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=S$14,$C47))))*HLOOKUP(YEAR(T$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(U$15>12,IF($D47>MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(U$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=T$14,$C47))))*HLOOKUP(YEAR(U$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(V$15>12,IF($D47>MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(V$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=U$14,$C47))))*HLOOKUP(YEAR(V$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(W$15>12,IF($D47>MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(W$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=V$14,$C47))))*HLOOKUP(YEAR(W$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(X$15>12,IF($D47>MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(X$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=W$14,$C47))))*HLOOKUP(YEAR(X$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(Y$15>12,IF($D47>MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(Y$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=X$14,$C47))))*HLOOKUP(YEAR(Y$16),$E$3:$O$5,3,0),0)))","v":610182.30000000005},{"$f":"+(IF($A47=\"\",\"\",IF(Z$15>12,IF($D47>MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(Z$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Y$14,$C47))))*HLOOKUP(YEAR(Z$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AA$15>12,IF($D47>MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Z$14,$C47))))*HLOOKUP(YEAR(AA$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AB$15>12,IF($D47>MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AA$14,$C47))))*HLOOKUP(YEAR(AB$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AC$15>12,IF($D47>MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AB$14,$C47))))*HLOOKUP(YEAR(AC$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AD$15>12,IF($D47>MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AC$14,$C47))))*HLOOKUP(YEAR(AD$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AE$15>12,IF($D47>MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AD$14,$C47))))*HLOOKUP(YEAR(AE$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AF$15>12,IF($D47>MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AE$14,$C47))))*HLOOKUP(YEAR(AF$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AG$15>12,IF($D47>MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AF$14,$C47))))*HLOOKUP(YEAR(AG$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AH$15>12,IF($D47>MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AG$14,$C47))))*HLOOKUP(YEAR(AH$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AI$15>12,IF($D47>MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AH$14,$C47))))*HLOOKUP(YEAR(AI$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AJ$15>12,IF($D47>MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AI$14,$C47))))*HLOOKUP(YEAR(AJ$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AK$15>12,IF($D47>MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AJ$14,$C47))))*HLOOKUP(YEAR(AK$16),$E$3:$O$5,3,0),0)))","v":628487.76899999997},{"$f":"+(IF($A47=\"\",\"\",IF(AL$15>12,IF($D47>MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AK$14,$C47))))*HLOOKUP(YEAR(AL$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AM$15>12,IF($D47>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C47))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AN$15>12,IF($D47>MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AM$14,$C47))))*HLOOKUP(YEAR(AN$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AO$15>12,IF($D47>MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AN$14,$C47))))*HLOOKUP(YEAR(AO$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AP$15>12,IF($D47>MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AO$14,$C47))))*HLOOKUP(YEAR(AP$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AQ$15>12,IF($D47>MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AP$14,$C47))))*HLOOKUP(YEAR(AQ$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AR$15>12,IF($D47>MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AQ$14,$C47))))*HLOOKUP(YEAR(AR$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AS$15>12,IF($D47>MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AR$14,$C47))))*HLOOKUP(YEAR(AS$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AT$15>12,IF($D47>MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AS$14,$C47))))*HLOOKUP(YEAR(AT$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AU$15>12,IF($D47>MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AT$14,$C47))))*HLOOKUP(YEAR(AU$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AV$15>12,IF($D47>MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AU$14,$C47))))*HLOOKUP(YEAR(AV$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AW$15>12,IF($D47>MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AV$14,$C47))))*HLOOKUP(YEAR(AW$16),$E$3:$O$5,3,0),0)))","v":647342.40206999995},{"$f":"+(IF($A47=\"\",\"\",IF(AX$15>12,IF($D47>MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AW$14,$C47))))*HLOOKUP(YEAR(AX$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(AY$15>12,IF($D47>MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AX$14,$C47))))*HLOOKUP(YEAR(AY$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(AZ$15>12,IF($D47>MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(AZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AY$14,$C47))))*HLOOKUP(YEAR(AZ$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BA$15>12,IF($D47>MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AZ$14,$C47))))*HLOOKUP(YEAR(BA$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BB$15>12,IF($D47>MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BA$14,$C47))))*HLOOKUP(YEAR(BB$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BC$15>12,IF($D47>MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BB$14,$C47))))*HLOOKUP(YEAR(BC$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BD$15>12,IF($D47>MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BC$14,$C47))))*HLOOKUP(YEAR(BD$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BE$15>12,IF($D47>MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BD$14,$C47))))*HLOOKUP(YEAR(BE$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BF$15>12,IF($D47>MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BE$14,$C47))))*HLOOKUP(YEAR(BF$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BG$15>12,IF($D47>MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BF$14,$C47))))*HLOOKUP(YEAR(BG$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BH$15>12,IF($D47>MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BG$14,$C47))))*HLOOKUP(YEAR(BH$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BI$15>12,IF($D47>MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BH$14,$C47))))*HLOOKUP(YEAR(BI$16),$E$3:$O$5,3,0),0)))","v":666762.67413210007},{"$f":"+(IF($A47=\"\",\"\",IF(BJ$15>12,IF($D47>MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BI$14,$C47))))*HLOOKUP(YEAR(BJ$16),$E$3:$O$5,3,0),0)))","v":686765.55435606302},{"$f":"+(IF($A47=\"\",\"\",IF(BK$15>12,IF($D47>MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BJ$14,$C47))))*HLOOKUP(YEAR(BK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BL$15>12,IF($D47>MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BK$14,$C47))))*HLOOKUP(YEAR(BL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BM$15>12,IF($D47>MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BL$14,$C47))))*HLOOKUP(YEAR(BM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BN$15>12,IF($D47>MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BM$14,$C47))))*HLOOKUP(YEAR(BN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BO$15>12,IF($D47>MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BN$14,$C47))))*HLOOKUP(YEAR(BO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BP$15>12,IF($D47>MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BO$14,$C47))))*HLOOKUP(YEAR(BP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BQ$15>12,IF($D47>MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BP$14,$C47))))*HLOOKUP(YEAR(BQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BR$15>12,IF($D47>MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BQ$14,$C47))))*HLOOKUP(YEAR(BR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BS$15>12,IF($D47>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C47))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BT$15>12,IF($D47>MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BS$14,$C47))))*HLOOKUP(YEAR(BT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BU$15>12,IF($D47>MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BT$14,$C47))))*HLOOKUP(YEAR(BU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BV$15>12,IF($D47>MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BU$14,$C47))))*HLOOKUP(YEAR(BV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BW$15>12,IF($D47>MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BV$14,$C47))))*HLOOKUP(YEAR(BW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BX$15>12,IF($D47>MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BW$14,$C47))))*HLOOKUP(YEAR(BX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BY$15>12,IF($D47>MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BX$14,$C47))))*HLOOKUP(YEAR(BY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(BZ$15>12,IF($D47>MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(BZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BY$14,$C47))))*HLOOKUP(YEAR(BZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CA$15>12,IF($D47>MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BZ$14,$C47))))*HLOOKUP(YEAR(CA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CB$15>12,IF($D47>MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CA$14,$C47))))*HLOOKUP(YEAR(CB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CC$15>12,IF($D47>MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CB$14,$C47))))*HLOOKUP(YEAR(CC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CD$15>12,IF($D47>MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CC$14,$C47))))*HLOOKUP(YEAR(CD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CE$15>12,IF($D47>MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CD$14,$C47))))*HLOOKUP(YEAR(CE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CF$15>12,IF($D47>MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CE$14,$C47))))*HLOOKUP(YEAR(CF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CG$15>12,IF($D47>MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CF$14,$C47))))*HLOOKUP(YEAR(CG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CH$15>12,IF($D47>MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CG$14,$C47))))*HLOOKUP(YEAR(CH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CI$15>12,IF($D47>MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CH$14,$C47))))*HLOOKUP(YEAR(CI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CJ$15>12,IF($D47>MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CI$14,$C47))))*HLOOKUP(YEAR(CJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CK$15>12,IF($D47>MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CJ$14,$C47))))*HLOOKUP(YEAR(CK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CL$15>12,IF($D47>MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CK$14,$C47))))*HLOOKUP(YEAR(CL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CM$15>12,IF($D47>MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CL$14,$C47))))*HLOOKUP(YEAR(CM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CN$15>12,IF($D47>MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CM$14,$C47))))*HLOOKUP(YEAR(CN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CO$15>12,IF($D47>MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CN$14,$C47))))*HLOOKUP(YEAR(CO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CP$15>12,IF($D47>MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CO$14,$C47))))*HLOOKUP(YEAR(CP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CQ$15>12,IF($D47>MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CP$14,$C47))))*HLOOKUP(YEAR(CQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CR$15>12,IF($D47>MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CQ$14,$C47))))*HLOOKUP(YEAR(CR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CS$15>12,IF($D47>MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CR$14,$C47))))*HLOOKUP(YEAR(CS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CT$15>12,IF($D47>MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CS$14,$C47))))*HLOOKUP(YEAR(CT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CU$15>12,IF($D47>MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CT$14,$C47))))*HLOOKUP(YEAR(CU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CV$15>12,IF($D47>MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CU$14,$C47))))*HLOOKUP(YEAR(CV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CW$15>12,IF($D47>MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CV$14,$C47))))*HLOOKUP(YEAR(CW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CX$15>12,IF($D47>MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CW$14,$C47))))*HLOOKUP(YEAR(CX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CY$15>12,IF($D47>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C47))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(CZ$15>12,IF($D47>MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(CZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CY$14,$C47))))*HLOOKUP(YEAR(CZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DA$15>12,IF($D47>MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CZ$14,$C47))))*HLOOKUP(YEAR(DA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DB$15>12,IF($D47>MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DA$14,$C47))))*HLOOKUP(YEAR(DB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DC$15>12,IF($D47>MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DB$14,$C47))))*HLOOKUP(YEAR(DC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DD$15>12,IF($D47>MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DC$14,$C47))))*HLOOKUP(YEAR(DD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DE$15>12,IF($D47>MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DD$14,$C47))))*HLOOKUP(YEAR(DE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DF$15>12,IF($D47>MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DE$14,$C47))))*HLOOKUP(YEAR(DF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DG$15>12,IF($D47>MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DF$14,$C47))))*HLOOKUP(YEAR(DG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DH$15>12,IF($D47>MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DG$14,$C47))))*HLOOKUP(YEAR(DH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DI$15>12,IF($D47>MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DH$14,$C47))))*HLOOKUP(YEAR(DI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DJ$15>12,IF($D47>MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DI$14,$C47))))*HLOOKUP(YEAR(DJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DK$15>12,IF($D47>MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DJ$14,$C47))))*HLOOKUP(YEAR(DK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DL$15>12,IF($D47>MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DK$14,$C47))))*HLOOKUP(YEAR(DL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DM$15>12,IF($D47>MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DL$14,$C47))))*HLOOKUP(YEAR(DM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DN$15>12,IF($D47>MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DM$14,$C47))))*HLOOKUP(YEAR(DN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DO$15>12,IF($D47>MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DN$14,$C47))))*HLOOKUP(YEAR(DO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DP$15>12,IF($D47>MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DO$14,$C47))))*HLOOKUP(YEAR(DP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DQ$15>12,IF($D47>MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DP$14,$C47))))*HLOOKUP(YEAR(DQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DR$15>12,IF($D47>MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DQ$14,$C47))))*HLOOKUP(YEAR(DR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DS$15>12,IF($D47>MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DR$14,$C47))))*HLOOKUP(YEAR(DS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DT$15>12,IF($D47>MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DS$14,$C47))))*HLOOKUP(YEAR(DT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DU$15>12,IF($D47>MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DT$14,$C47))))*HLOOKUP(YEAR(DU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A47=\"\",\"\",IF(DV$15>12,IF($D47>MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion))+1,0,IF($E47<=(MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion)))-$D47+IF($D47<>\"\",1,0),0,IF(DV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DU$14,$C47))))*HLOOKUP(YEAR(DV$16),$E$3:$O$5,3,0),0)))","v":0}]
["Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A48,Tipo,TipoEspecifico,Relacion,'Parametros tecnológicos'!$F$7,ClaseTorreRango,ClaseTorre)/12","v":0},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto encerramiento",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A49,Tipo,TipoEspecifico,Relacion,'Parametros tecnológicos'!$F$7)/12","v":226014.21645225445},null,56,{"$f":"+IF($A49=\"\",\"\",$B49+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C49,0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,232794.6429458221,232794.6429458221,232794.6429458221,232794.6429458221,232794.6429458221,232794.6429458221,232794.6429458221,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,239778.48223419674,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,246971.83670122264,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,254380.99180225935,262012.42155632711,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Servicios Profesionales: Terreno, Ambiente, Aeronautica",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A50,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico)","v":17740633.5},null,null,56,{"$f":"+IF($A50=\"\",\"\",IF($D50=F$15,$B50+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C50,0),0))","v":17740633.5},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A50=\"\",\"\",IF($D50=BR$15,$B50+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C50,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Torre (Incluye: Tierra, Pararrayo) - Convencional (*)",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A51,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico,ClaseTorreRango,ClaseTorre)","v":82415267.5},null,null,56,{"$f":"+IF($A51=\"\",\"\",IF($D51=F$15,$B51+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C51,0),0))","v":82415267.5},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)",{"$f":"+SUMIFS(ValoresMercado,Conceptos,A52,Relacion,'Parametros tecnológicos'!$F$7,Tipo,TipoEspecifico,ClaseTorreRango,ClaseTorre)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["OPEX GENERAL",null,null,null,56,{"$f":"+IF($A53=\"\",\"\",$B53+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C53,0))","v":0},{"$f":"+(IF($A53=\"\",\"\",IF($D53>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E53<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D53,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C53))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A53=\"\",\"\",IF($D53>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E53<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D53,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C53))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A53=\"\",\"\",IF($D53>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E53<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D53,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C53))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A53=\"\",\"\",IF($D53>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E53<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D53,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C53))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Licencias MW MinTIC",null,{"$f":"+IF('Parametros tecnológicos'!C22=\"S\",SUMIFS(ValoresMercado,Conceptos,A54),0)","v":1571182.7679744002},null,56,0,{"$f":"+(IF($A54=\"\",\"\",IF($D54>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E54<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D54+IF($D54<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C54))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},1571182.7679744002,1571182.7679744002,1571182.7679744002,1571182.7679744002,1571182.7679744002,1571182.7679744002,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1618318.2510136322,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1666867.7985440411,1716873.8325003623,{"$f":"+(IF($A54=\"\",\"\",IF($D54>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E54<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D54+IF($D54<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C54))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":1716873.8325003623},1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1716873.8325003623,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1768380.0474753734,1821431.4488996346,0,0,0,0,0,0,0,0,{"$f":"+(IF($A54=\"\",\"\",IF($D54>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E54<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D54+IF($D54<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C54))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A54=\"\",\"\",IF($D54>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E54<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D54+IF($D54<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C54))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Energia Electrica - menos de 3 meses",null,{"$f":"+IF('Parametros tecnológicos'!C34=\"S\",0,SUMIFS(ValoresMercado,Conceptos,A55)/3)","v":2905000},null,3,0,{"$f":"+(IF($A55=\"\",\"\",IF($D55>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E55<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D55+IF($D55<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C55))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},2905000,2905000,2905000,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A55=\"\",\"\",IF($D55>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E55<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D55+IF($D55<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C55))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A55=\"\",\"\",IF($D55>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E55<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D55+IF($D55<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C55))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A55=\"\",\"\",IF($D55>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E55<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D55+IF($D55<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C55))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Seguros",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A56)","v":5052.9840000000004},null,56,0,{"$f":"+(IF($A56=\"\",\"\",IF($D56>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E56<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D56+IF($D56<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C56))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},5052.9840000000004,5052.9840000000004,5052.9840000000004,5052.9840000000004,5052.9840000000004,5052.9840000000004,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5204.5735200000008,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5360.7107255999999,5521.5320473680003,{"$f":"+(IF($A56=\"\",\"\",IF($D56>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E56<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D56+IF($D56<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C56))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":5521.5320473680003},5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5521.5320473680003,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5687.1780087890411,5857.7933490527121,0,0,0,0,0,0,0,0,{"$f":"+(IF($A56=\"\",\"\",IF($D56>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E56<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D56+IF($D56<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C56))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A56=\"\",\"\",IF($D56>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E56<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D56+IF($D56<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C56))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Monitoreo y Gestión",null,{"$f":"+SUMIFS(ValoresMercado,Conceptos,A57)","v":190000},null,56,0,{"$f":"+(IF($A57=\"\",\"\",IF($D57>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E57<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D57+IF($D57<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C57))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},190000,190000,190000,190000,190000,190000,195700,195700,195700,195700,195700,195700,195700,195700,195700,195700,195700,195700,201571,201571,201571,201571,201571,201571,201571,201571,201571,201571,201571,201571,207618.13,{"$f":"+(IF($A57=\"\",\"\",IF($D57>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E57<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D57+IF($D57<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C57))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":207618.13},207618.13,207618.13,207618.13,207618.13,207618.13,207618.13,207618.13,207618.13,207618.13,207618.13,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,213846.67390000002,220262.07411700001,0,0,0,0,0,0,0,0,{"$f":"+(IF($A57=\"\",\"\",IF($D57>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E57<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D57+IF($D57<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C57))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A57=\"\",\"\",IF($D57>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E57<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D57+IF($D57<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C57))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["RED ENERGÍA MT",null,null,null,56,0,{"$f":"+(IF($A58=\"\",\"\",IF($D58>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E58<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D58,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C58))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A58=\"\",\"\",IF($D58>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E58<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D58,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C58))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A58=\"\",\"\",IF($D58>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E58<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D58,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C58))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A58=\"\",\"\",IF($D58>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E58<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D58,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C58))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"\"Terreno \"&Tipo_Terreno&\" - \"&\"Trasiegos\"","v":"Terreno Plano - Trasiegos"},{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A59,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,Terreno_Energia,Tipo_Terreno,KW_Energia,KW_EnergiaValor))","v":1079896.6666666656},null,null,56,{"$f":"+IF($A59=\"\",\"\",IF($D59=F$15,$B59+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C59,0),0))","v":1079896.6666666656},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A59=\"\",\"\",IF($D59=BR$15,$B59+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C59,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"\"Terreno \"&Tipo_Terreno&\" - \"&\"Cableados Mt\"","v":"Terreno Plano - Cableados Mt"},{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A60,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,Terreno_Energia,Tipo_Terreno,KW_Energia,KW_EnergiaValor))","v":9319531.0633333344},null,null,56,{"$f":"+IF($A60=\"\",\"\",IF($D60=F$15,$B60+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C60,0),0))","v":9319531.0633333344},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Diseños, Planos\"","v":"Terreno Plano - Diseños, Planos"},{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A61,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,Terreno_Energia,Tipo_Terreno,KW_Energia,KW_EnergiaValor))","v":2218858.4419999998},null,null,56,2218858.4419999998,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Pararrayos, Tierra",null,{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A62,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,KW_Energia,KW_EnergiaValor)/12)","v":25130.875},null,56,0,{"$f":"+(IF($A62=\"\",\"\",IF(G$15>12,IF($D62>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C62))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(H$15>12,IF($D62>MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(H$16)-MONTH(InicioFuncion)+12*(YEAR(H$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(H$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=G$14,$C62))))*HLOOKUP(YEAR(H$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(I$15>12,IF($D62>MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(I$16)-MONTH(InicioFuncion)+12*(YEAR(I$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(I$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=H$14,$C62))))*HLOOKUP(YEAR(I$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(J$15>12,IF($D62>MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(J$16)-MONTH(InicioFuncion)+12*(YEAR(J$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(J$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=I$14,$C62))))*HLOOKUP(YEAR(J$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(K$15>12,IF($D62>MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(K$16)-MONTH(InicioFuncion)+12*(YEAR(K$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(K$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=J$14,$C62))))*HLOOKUP(YEAR(K$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(L$15>12,IF($D62>MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(L$16)-MONTH(InicioFuncion)+12*(YEAR(L$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(L$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=K$14,$C62))))*HLOOKUP(YEAR(L$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(M$15>12,IF($D62>MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(M$16)-MONTH(InicioFuncion)+12*(YEAR(M$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(M$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=L$14,$C62))))*HLOOKUP(YEAR(M$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(N$15>12,IF($D62>MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(N$16)-MONTH(InicioFuncion)+12*(YEAR(N$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(N$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=M$14,$C62))))*HLOOKUP(YEAR(N$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(O$15>12,IF($D62>MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(O$16)-MONTH(InicioFuncion)+12*(YEAR(O$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(O$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=N$14,$C62))))*HLOOKUP(YEAR(O$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(P$15>12,IF($D62>MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(P$16)-MONTH(InicioFuncion)+12*(YEAR(P$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(P$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=O$14,$C62))))*HLOOKUP(YEAR(P$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(Q$15>12,IF($D62>MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(Q$16)-MONTH(InicioFuncion)+12*(YEAR(Q$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(Q$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=P$14,$C62))))*HLOOKUP(YEAR(Q$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(R$15>12,IF($D62>MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(R$16)-MONTH(InicioFuncion)+12*(YEAR(R$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(R$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Q$14,$C62))))*HLOOKUP(YEAR(R$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(S$15>12,IF($D62>MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(S$16)-MONTH(InicioFuncion)+12*(YEAR(S$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(S$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=R$14,$C62))))*HLOOKUP(YEAR(S$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(T$15>12,IF($D62>MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(T$16)-MONTH(InicioFuncion)+12*(YEAR(T$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(T$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=S$14,$C62))))*HLOOKUP(YEAR(T$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(U$15>12,IF($D62>MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(U$16)-MONTH(InicioFuncion)+12*(YEAR(U$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(U$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=T$14,$C62))))*HLOOKUP(YEAR(U$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(V$15>12,IF($D62>MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(V$16)-MONTH(InicioFuncion)+12*(YEAR(V$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(V$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=U$14,$C62))))*HLOOKUP(YEAR(V$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(W$15>12,IF($D62>MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(W$16)-MONTH(InicioFuncion)+12*(YEAR(W$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(W$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=V$14,$C62))))*HLOOKUP(YEAR(W$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(X$15>12,IF($D62>MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(X$16)-MONTH(InicioFuncion)+12*(YEAR(X$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(X$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=W$14,$C62))))*HLOOKUP(YEAR(X$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(Y$15>12,IF($D62>MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(Y$16)-MONTH(InicioFuncion)+12*(YEAR(Y$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(Y$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=X$14,$C62))))*HLOOKUP(YEAR(Y$16),$E$3:$O$5,3,0),0)))","v":25884.80125},{"$f":"+(IF($A62=\"\",\"\",IF(Z$15>12,IF($D62>MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(Z$16)-MONTH(InicioFuncion)+12*(YEAR(Z$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(Z$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Y$14,$C62))))*HLOOKUP(YEAR(Z$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AA$15>12,IF($D62>MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AA$16)-MONTH(InicioFuncion)+12*(YEAR(AA$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=Z$14,$C62))))*HLOOKUP(YEAR(AA$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AB$15>12,IF($D62>MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AB$16)-MONTH(InicioFuncion)+12*(YEAR(AB$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AA$14,$C62))))*HLOOKUP(YEAR(AB$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AC$15>12,IF($D62>MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AC$16)-MONTH(InicioFuncion)+12*(YEAR(AC$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AB$14,$C62))))*HLOOKUP(YEAR(AC$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AD$15>12,IF($D62>MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AD$16)-MONTH(InicioFuncion)+12*(YEAR(AD$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AC$14,$C62))))*HLOOKUP(YEAR(AD$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AE$15>12,IF($D62>MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AE$16)-MONTH(InicioFuncion)+12*(YEAR(AE$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AD$14,$C62))))*HLOOKUP(YEAR(AE$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AF$15>12,IF($D62>MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AF$16)-MONTH(InicioFuncion)+12*(YEAR(AF$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AE$14,$C62))))*HLOOKUP(YEAR(AF$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AG$15>12,IF($D62>MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AG$16)-MONTH(InicioFuncion)+12*(YEAR(AG$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AF$14,$C62))))*HLOOKUP(YEAR(AG$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AH$15>12,IF($D62>MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AH$16)-MONTH(InicioFuncion)+12*(YEAR(AH$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AG$14,$C62))))*HLOOKUP(YEAR(AH$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AI$15>12,IF($D62>MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AI$16)-MONTH(InicioFuncion)+12*(YEAR(AI$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AH$14,$C62))))*HLOOKUP(YEAR(AI$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AJ$15>12,IF($D62>MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AJ$16)-MONTH(InicioFuncion)+12*(YEAR(AJ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AI$14,$C62))))*HLOOKUP(YEAR(AJ$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AK$15>12,IF($D62>MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AK$16)-MONTH(InicioFuncion)+12*(YEAR(AK$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AJ$14,$C62))))*HLOOKUP(YEAR(AK$16),$E$3:$O$5,3,0),0)))","v":26661.3452875},{"$f":"+(IF($A62=\"\",\"\",IF(AL$15>12,IF($D62>MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AL$16)-MONTH(InicioFuncion)+12*(YEAR(AL$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AK$14,$C62))))*HLOOKUP(YEAR(AL$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AM$15>12,IF($D62>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C62))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AN$15>12,IF($D62>MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AN$16)-MONTH(InicioFuncion)+12*(YEAR(AN$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AM$14,$C62))))*HLOOKUP(YEAR(AN$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AO$15>12,IF($D62>MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AO$16)-MONTH(InicioFuncion)+12*(YEAR(AO$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AN$14,$C62))))*HLOOKUP(YEAR(AO$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AP$15>12,IF($D62>MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AP$16)-MONTH(InicioFuncion)+12*(YEAR(AP$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AO$14,$C62))))*HLOOKUP(YEAR(AP$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AQ$15>12,IF($D62>MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AQ$16)-MONTH(InicioFuncion)+12*(YEAR(AQ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AP$14,$C62))))*HLOOKUP(YEAR(AQ$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AR$15>12,IF($D62>MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AR$16)-MONTH(InicioFuncion)+12*(YEAR(AR$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AQ$14,$C62))))*HLOOKUP(YEAR(AR$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AS$15>12,IF($D62>MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AS$16)-MONTH(InicioFuncion)+12*(YEAR(AS$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AR$14,$C62))))*HLOOKUP(YEAR(AS$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AT$15>12,IF($D62>MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AT$16)-MONTH(InicioFuncion)+12*(YEAR(AT$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AS$14,$C62))))*HLOOKUP(YEAR(AT$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AU$15>12,IF($D62>MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AU$16)-MONTH(InicioFuncion)+12*(YEAR(AU$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AT$14,$C62))))*HLOOKUP(YEAR(AU$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AV$15>12,IF($D62>MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AV$16)-MONTH(InicioFuncion)+12*(YEAR(AV$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AU$14,$C62))))*HLOOKUP(YEAR(AV$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AW$15>12,IF($D62>MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AW$16)-MONTH(InicioFuncion)+12*(YEAR(AW$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AV$14,$C62))))*HLOOKUP(YEAR(AW$16),$E$3:$O$5,3,0),0)))","v":27461.185646124999},{"$f":"+(IF($A62=\"\",\"\",IF(AX$15>12,IF($D62>MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AX$16)-MONTH(InicioFuncion)+12*(YEAR(AX$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AW$14,$C62))))*HLOOKUP(YEAR(AX$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(AY$15>12,IF($D62>MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AY$16)-MONTH(InicioFuncion)+12*(YEAR(AY$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AX$14,$C62))))*HLOOKUP(YEAR(AY$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(AZ$15>12,IF($D62>MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(AZ$16)-MONTH(InicioFuncion)+12*(YEAR(AZ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(AZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AY$14,$C62))))*HLOOKUP(YEAR(AZ$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BA$15>12,IF($D62>MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BA$16)-MONTH(InicioFuncion)+12*(YEAR(BA$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AZ$14,$C62))))*HLOOKUP(YEAR(BA$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BB$15>12,IF($D62>MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BB$16)-MONTH(InicioFuncion)+12*(YEAR(BB$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BA$14,$C62))))*HLOOKUP(YEAR(BB$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BC$15>12,IF($D62>MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BC$16)-MONTH(InicioFuncion)+12*(YEAR(BC$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BB$14,$C62))))*HLOOKUP(YEAR(BC$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BD$15>12,IF($D62>MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BD$16)-MONTH(InicioFuncion)+12*(YEAR(BD$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BC$14,$C62))))*HLOOKUP(YEAR(BD$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BE$15>12,IF($D62>MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BE$16)-MONTH(InicioFuncion)+12*(YEAR(BE$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BD$14,$C62))))*HLOOKUP(YEAR(BE$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BF$15>12,IF($D62>MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BF$16)-MONTH(InicioFuncion)+12*(YEAR(BF$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BE$14,$C62))))*HLOOKUP(YEAR(BF$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BG$15>12,IF($D62>MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BG$16)-MONTH(InicioFuncion)+12*(YEAR(BG$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BF$14,$C62))))*HLOOKUP(YEAR(BG$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BH$15>12,IF($D62>MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BH$16)-MONTH(InicioFuncion)+12*(YEAR(BH$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BG$14,$C62))))*HLOOKUP(YEAR(BH$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BI$15>12,IF($D62>MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BI$16)-MONTH(InicioFuncion)+12*(YEAR(BI$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BH$14,$C62))))*HLOOKUP(YEAR(BI$16),$E$3:$O$5,3,0),0)))","v":28285.021215508754},{"$f":"+(IF($A62=\"\",\"\",IF(BJ$15>12,IF($D62>MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BJ$16)-MONTH(InicioFuncion)+12*(YEAR(BJ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BI$14,$C62))))*HLOOKUP(YEAR(BJ$16),$E$3:$O$5,3,0),0)))","v":29133.571851974015},{"$f":"+(IF($A62=\"\",\"\",IF(BK$15>12,IF($D62>MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BK$16)-MONTH(InicioFuncion)+12*(YEAR(BK$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BJ$14,$C62))))*HLOOKUP(YEAR(BK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BL$15>12,IF($D62>MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BL$16)-MONTH(InicioFuncion)+12*(YEAR(BL$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BK$14,$C62))))*HLOOKUP(YEAR(BL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BM$15>12,IF($D62>MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BM$16)-MONTH(InicioFuncion)+12*(YEAR(BM$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BL$14,$C62))))*HLOOKUP(YEAR(BM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BN$15>12,IF($D62>MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BN$16)-MONTH(InicioFuncion)+12*(YEAR(BN$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BM$14,$C62))))*HLOOKUP(YEAR(BN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BO$15>12,IF($D62>MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BO$16)-MONTH(InicioFuncion)+12*(YEAR(BO$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BN$14,$C62))))*HLOOKUP(YEAR(BO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BP$15>12,IF($D62>MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BP$16)-MONTH(InicioFuncion)+12*(YEAR(BP$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BO$14,$C62))))*HLOOKUP(YEAR(BP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BQ$15>12,IF($D62>MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BQ$16)-MONTH(InicioFuncion)+12*(YEAR(BQ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BP$14,$C62))))*HLOOKUP(YEAR(BQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BR$15>12,IF($D62>MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BR$16)-MONTH(InicioFuncion)+12*(YEAR(BR$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BQ$14,$C62))))*HLOOKUP(YEAR(BR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BS$15>12,IF($D62>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C62))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BT$15>12,IF($D62>MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BT$16)-MONTH(InicioFuncion)+12*(YEAR(BT$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BS$14,$C62))))*HLOOKUP(YEAR(BT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BU$15>12,IF($D62>MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BU$16)-MONTH(InicioFuncion)+12*(YEAR(BU$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BT$14,$C62))))*HLOOKUP(YEAR(BU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BV$15>12,IF($D62>MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BV$16)-MONTH(InicioFuncion)+12*(YEAR(BV$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BU$14,$C62))))*HLOOKUP(YEAR(BV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BW$15>12,IF($D62>MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BW$16)-MONTH(InicioFuncion)+12*(YEAR(BW$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BV$14,$C62))))*HLOOKUP(YEAR(BW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BX$15>12,IF($D62>MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BX$16)-MONTH(InicioFuncion)+12*(YEAR(BX$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BW$14,$C62))))*HLOOKUP(YEAR(BX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BY$15>12,IF($D62>MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BY$16)-MONTH(InicioFuncion)+12*(YEAR(BY$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BX$14,$C62))))*HLOOKUP(YEAR(BY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(BZ$15>12,IF($D62>MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(BZ$16)-MONTH(InicioFuncion)+12*(YEAR(BZ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(BZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BY$14,$C62))))*HLOOKUP(YEAR(BZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CA$15>12,IF($D62>MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CA$16)-MONTH(InicioFuncion)+12*(YEAR(CA$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BZ$14,$C62))))*HLOOKUP(YEAR(CA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CB$15>12,IF($D62>MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CB$16)-MONTH(InicioFuncion)+12*(YEAR(CB$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CA$14,$C62))))*HLOOKUP(YEAR(CB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CC$15>12,IF($D62>MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CC$16)-MONTH(InicioFuncion)+12*(YEAR(CC$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CB$14,$C62))))*HLOOKUP(YEAR(CC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CD$15>12,IF($D62>MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CD$16)-MONTH(InicioFuncion)+12*(YEAR(CD$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CC$14,$C62))))*HLOOKUP(YEAR(CD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CE$15>12,IF($D62>MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CE$16)-MONTH(InicioFuncion)+12*(YEAR(CE$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CD$14,$C62))))*HLOOKUP(YEAR(CE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CF$15>12,IF($D62>MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CF$16)-MONTH(InicioFuncion)+12*(YEAR(CF$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CE$14,$C62))))*HLOOKUP(YEAR(CF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CG$15>12,IF($D62>MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CG$16)-MONTH(InicioFuncion)+12*(YEAR(CG$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CF$14,$C62))))*HLOOKUP(YEAR(CG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CH$15>12,IF($D62>MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CH$16)-MONTH(InicioFuncion)+12*(YEAR(CH$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CG$14,$C62))))*HLOOKUP(YEAR(CH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CI$15>12,IF($D62>MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CI$16)-MONTH(InicioFuncion)+12*(YEAR(CI$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CH$14,$C62))))*HLOOKUP(YEAR(CI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CJ$15>12,IF($D62>MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CJ$16)-MONTH(InicioFuncion)+12*(YEAR(CJ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CI$14,$C62))))*HLOOKUP(YEAR(CJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CK$15>12,IF($D62>MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CK$16)-MONTH(InicioFuncion)+12*(YEAR(CK$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CJ$14,$C62))))*HLOOKUP(YEAR(CK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CL$15>12,IF($D62>MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CL$16)-MONTH(InicioFuncion)+12*(YEAR(CL$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CK$14,$C62))))*HLOOKUP(YEAR(CL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CM$15>12,IF($D62>MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CM$16)-MONTH(InicioFuncion)+12*(YEAR(CM$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CL$14,$C62))))*HLOOKUP(YEAR(CM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CN$15>12,IF($D62>MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CN$16)-MONTH(InicioFuncion)+12*(YEAR(CN$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CM$14,$C62))))*HLOOKUP(YEAR(CN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CO$15>12,IF($D62>MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CO$16)-MONTH(InicioFuncion)+12*(YEAR(CO$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CN$14,$C62))))*HLOOKUP(YEAR(CO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CP$15>12,IF($D62>MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CP$16)-MONTH(InicioFuncion)+12*(YEAR(CP$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CO$14,$C62))))*HLOOKUP(YEAR(CP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CQ$15>12,IF($D62>MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CQ$16)-MONTH(InicioFuncion)+12*(YEAR(CQ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CP$14,$C62))))*HLOOKUP(YEAR(CQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CR$15>12,IF($D62>MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CR$16)-MONTH(InicioFuncion)+12*(YEAR(CR$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CQ$14,$C62))))*HLOOKUP(YEAR(CR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CS$15>12,IF($D62>MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CS$16)-MONTH(InicioFuncion)+12*(YEAR(CS$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CR$14,$C62))))*HLOOKUP(YEAR(CS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CT$15>12,IF($D62>MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CT$16)-MONTH(InicioFuncion)+12*(YEAR(CT$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CS$14,$C62))))*HLOOKUP(YEAR(CT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CU$15>12,IF($D62>MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CU$16)-MONTH(InicioFuncion)+12*(YEAR(CU$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CT$14,$C62))))*HLOOKUP(YEAR(CU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CV$15>12,IF($D62>MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CV$16)-MONTH(InicioFuncion)+12*(YEAR(CV$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CU$14,$C62))))*HLOOKUP(YEAR(CV$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CW$15>12,IF($D62>MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CW$16)-MONTH(InicioFuncion)+12*(YEAR(CW$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CW$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CV$14,$C62))))*HLOOKUP(YEAR(CW$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CX$15>12,IF($D62>MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CX$16)-MONTH(InicioFuncion)+12*(YEAR(CX$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CX$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CW$14,$C62))))*HLOOKUP(YEAR(CX$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CY$15>12,IF($D62>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C62))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(CZ$15>12,IF($D62>MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(CZ$16)-MONTH(InicioFuncion)+12*(YEAR(CZ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(CZ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CY$14,$C62))))*HLOOKUP(YEAR(CZ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DA$15>12,IF($D62>MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DA$16)-MONTH(InicioFuncion)+12*(YEAR(DA$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DA$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CZ$14,$C62))))*HLOOKUP(YEAR(DA$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DB$15>12,IF($D62>MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DB$16)-MONTH(InicioFuncion)+12*(YEAR(DB$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DB$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DA$14,$C62))))*HLOOKUP(YEAR(DB$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DC$15>12,IF($D62>MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DC$16)-MONTH(InicioFuncion)+12*(YEAR(DC$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DC$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DB$14,$C62))))*HLOOKUP(YEAR(DC$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DD$15>12,IF($D62>MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DD$16)-MONTH(InicioFuncion)+12*(YEAR(DD$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DD$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DC$14,$C62))))*HLOOKUP(YEAR(DD$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DE$15>12,IF($D62>MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DE$16)-MONTH(InicioFuncion)+12*(YEAR(DE$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DE$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DD$14,$C62))))*HLOOKUP(YEAR(DE$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DF$15>12,IF($D62>MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DF$16)-MONTH(InicioFuncion)+12*(YEAR(DF$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DF$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DE$14,$C62))))*HLOOKUP(YEAR(DF$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DG$15>12,IF($D62>MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DG$16)-MONTH(InicioFuncion)+12*(YEAR(DG$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DG$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DF$14,$C62))))*HLOOKUP(YEAR(DG$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DH$15>12,IF($D62>MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DH$16)-MONTH(InicioFuncion)+12*(YEAR(DH$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DH$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DG$14,$C62))))*HLOOKUP(YEAR(DH$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DI$15>12,IF($D62>MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DI$16)-MONTH(InicioFuncion)+12*(YEAR(DI$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DI$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DH$14,$C62))))*HLOOKUP(YEAR(DI$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DJ$15>12,IF($D62>MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DJ$16)-MONTH(InicioFuncion)+12*(YEAR(DJ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DJ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DI$14,$C62))))*HLOOKUP(YEAR(DJ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DK$15>12,IF($D62>MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DK$16)-MONTH(InicioFuncion)+12*(YEAR(DK$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DK$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DJ$14,$C62))))*HLOOKUP(YEAR(DK$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DL$15>12,IF($D62>MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DL$16)-MONTH(InicioFuncion)+12*(YEAR(DL$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DL$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DK$14,$C62))))*HLOOKUP(YEAR(DL$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DM$15>12,IF($D62>MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DM$16)-MONTH(InicioFuncion)+12*(YEAR(DM$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DL$14,$C62))))*HLOOKUP(YEAR(DM$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DN$15>12,IF($D62>MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DN$16)-MONTH(InicioFuncion)+12*(YEAR(DN$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DN$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DM$14,$C62))))*HLOOKUP(YEAR(DN$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DO$15>12,IF($D62>MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DO$16)-MONTH(InicioFuncion)+12*(YEAR(DO$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DO$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DN$14,$C62))))*HLOOKUP(YEAR(DO$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DP$15>12,IF($D62>MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DP$16)-MONTH(InicioFuncion)+12*(YEAR(DP$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DP$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DO$14,$C62))))*HLOOKUP(YEAR(DP$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DQ$15>12,IF($D62>MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DQ$16)-MONTH(InicioFuncion)+12*(YEAR(DQ$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DQ$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DP$14,$C62))))*HLOOKUP(YEAR(DQ$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DR$15>12,IF($D62>MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DR$16)-MONTH(InicioFuncion)+12*(YEAR(DR$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DR$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DQ$14,$C62))))*HLOOKUP(YEAR(DR$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DS$15>12,IF($D62>MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DS$16)-MONTH(InicioFuncion)+12*(YEAR(DS$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DR$14,$C62))))*HLOOKUP(YEAR(DS$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DT$15>12,IF($D62>MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DT$16)-MONTH(InicioFuncion)+12*(YEAR(DT$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DT$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DS$14,$C62))))*HLOOKUP(YEAR(DT$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DU$15>12,IF($D62>MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DU$16)-MONTH(InicioFuncion)+12*(YEAR(DU$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DU$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DT$14,$C62))))*HLOOKUP(YEAR(DU$16),$E$3:$O$5,3,0),0)))","v":0},{"$f":"+(IF($A62=\"\",\"\",IF(DV$15>12,IF($D62>MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion))+1,0,IF($E62<=(MONTH(DV$16)-MONTH(InicioFuncion)+12*(YEAR(DV$16)-YEAR(InicioFuncion)))-$D62+IF($D62<>\"\",1,0),0,IF(DV$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=DU$14,$C62))))*HLOOKUP(YEAR(DV$16),$E$3:$O$5,3,0),0)))","v":0}]
["Mto Podas",null,{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A63,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,KW_Energia,KW_EnergiaValor)/12)","v":282224.565},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,290691.30194999999,290691.30194999999,290691.30194999999,290691.30194999999,290691.30194999999,290691.30194999999,290691.30194999999,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,299412.04100849997,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,308394.40223875502,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,317646.23430591769,327175.6213350952,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Red De Mt (Postes, Lar)",null,{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A64,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,KW_Energia,KW_EnergiaValor)/12)","v":41666.666666666664},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,42916.666666666664,42916.666666666664,42916.666666666664,42916.666666666664,42916.666666666664,42916.666666666664,42916.666666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,44204.166666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,45530.291666666664,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,46896.200416666667,48303.086429166666,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Mto Transformador",null,{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A65,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,KW_Energia,KW_EnergiaValor)/12)","v":327575.12666666665},null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,337402.38046666665,337402.38046666665,337402.38046666665,337402.38046666665,337402.38046666665,337402.38046666665,337402.38046666665,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,347524.45188066666,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,357950.18543708662,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,368688.69100019929,379749.35173020524,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Tramite conexión  y permisos\"","v":"Terreno Plano - Tramite conexión  y permisos"},{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A66,Relacion,DistanciaEnergiaSTD,Tipo,TipoEspecifico,Terreno_Energia,Tipo_Terreno,KW_Energia,KW_EnergiaValor))","v":778384.16280000005},null,null,56,{"$f":"+IF($A66=\"\",\"\",IF($D66=F$15,$B66+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C66,0),0))","v":778384.16280000005},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A66=\"\",\"\",IF($D66=BR$15,$B66+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C66,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Asesoria y Certificacion RETIE\"","v":"Terreno Plano - Asesoria y Certificacion RETIE"},3086218.5474999999,null,null,56,{"$f":"+IF($A67=\"\",\"\",IF($D67=F$15,$B67+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C67,0),0))","v":3086218.5474999999},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Transformador Kw\"","v":"Terreno Plano - Transformador Kw"},6691474.0949999997,null,null,56,6691474.0949999997,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Derechos de conexión\"","v":"Terreno Plano - Derechos de conexión"},460286.44419999997,null,null,56,460286.44419999997,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Maniobras en conexión\"","v":"Terreno Plano - Maniobras en conexión"},1653418.3960279999,null,null,56,1653418.3960279999,0,0,{"$f":"+IF($A70=\"\",\"\",IF($D70=I$15,$B70+IF(MONTH($B$8)-MONTH($B$7)+$E$14=H$14,$C70,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A70=\"\",\"\",IF($D70=CT$15,$B70+IF(MONTH($B$8)-MONTH($B$7)+$E$14=CS$14,$C70,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Parrarayos, Malla\"","v":"Terreno Plano - Parrarayos, Malla"},5165519.7299999995,null,null,56,5165519.7299999995,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Paso Cruceta Lar\"","v":"Terreno Plano - Paso Cruceta Lar"},5626782.5633333335,null,null,56,{"$f":"+IF($A72=\"\",\"\",IF($D72=F$15,$B72+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C72,0),0))","v":5626782.5633333335},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Servidumbres\"","v":"Terreno Plano - Servidumbres"},494190,null,null,56,494190,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"+\"Terreno \"&Tipo_Terreno&\" - \"&\"Soportes (Postes)\"","v":"Terreno Plano - Soportes (Postes)"},7360575.8313333327,null,null,56,7360575.8313333327,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A74=\"\",\"\",IF($D74=BP$15,$B74+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BO$14,$C74,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Valor Consumo De Energia Kwh",null,{"$f":"+IF(Tipologia_Campo=\"FTTH\",0,SUMIFS(ValoresMercado,Conceptos,A75,Relacion,DistanciaRedEnergia,Tipo,TipoEspecifico,KW_Energia,KW_EnergiaValor))","v":2160000},null,56,0,{"$f":"+(IF($A75=\"\",\"\",IF($D75>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E75<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D75+IF($D75<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C75))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},2160000,2160000,2160000,2160000,2160000,2160000,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2224800,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2291544,2360290.3199999998,{"$f":"+(IF($A75=\"\",\"\",IF($D75>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E75<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D75+IF($D75<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C75))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":2360290.3199999998},2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2360290.3199999998,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2431099.0296000005,2504032.000488,0,0,0,0,0,0,0,0,{"$f":"+(IF($A75=\"\",\"\",IF($D75>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E75<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D75+IF($D75<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C75))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A75=\"\",\"\",IF($D75>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E75<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D75+IF($D75<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C75))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["TOTAL CAPEX MEDIA TENSIÓN",{"$f":"+SUM(B59:B74)","v":43935135.94219467}]
["FTTH",null,null,null,{"$f":"+MesesReconocimiento","v":56},{"$f":"+IF($A77=\"\",\"\",IF($D77=F$15,$B77+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C77,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A77=\"\",\"\",IF($D77=BR$15,$B77+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C77,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Splitter óptico",{"$f":"+IF(Tipologia_Campo=\"FTTH\",Detalle!P968,0)","v":0},null,null,56,{"$f":"+IF($A78=\"\",\"\",IF($D78=F$15,$B78+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C78,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["OLT",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P969,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Firewall & Caché Server",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P970,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Poste Servidumbre / 5 Años",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P971,0)","v":0},null,null,56,0,0,0,{"$f":"+IF($A81=\"\",\"\",IF($D81=I$15,$B81+IF(MONTH($B$8)-MONTH($B$7)+$E$14=H$14,$C81,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A81=\"\",\"\",IF($D81=CT$15,$B81+IF(MONTH($B$8)-MONTH($B$7)+$E$14=CS$14,$C81,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Cable óptico (48 hilos) Troncal/Km (Instalado)",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P972,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Cable óptico Acometida /Mt",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P973,0)","v":0},null,null,56,{"$f":"+IF($A83=\"\",\"\",IF($D83=F$15,$B83+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C83,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Pigtail",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P974,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["ONT",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P975,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A85=\"\",\"\",IF($D85=BP$15,$B85+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BO$14,$C85,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Materiales instalación FTTH",{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!P979,0)","v":0},null,null,56,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A86=\"\",\"\",IF($D86=V$15,$B86+IF(MONTH($B$8)-MONTH($B$7)+$E$14=U$14,$C86,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A86=\"\",\"\",IF($D86=BU$15,$B86+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BT$14,$C86,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Costo Transporte (Mbps)",null,{"$f":"++IF(Tipologia_Campo=\"FTTH\",Detalle!$P$978,0)","v":0},null,56,{"$f":"+IF($A87=\"\",\"\",$B87+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C87,0))","v":0},{"$f":"+(IF($A87=\"\",\"\",IF($D87>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E87<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D87+IF($D87<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C87))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A87=\"\",\"\",IF($D87>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E87<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D87+IF($D87<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C87))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A87=\"\",\"\",IF($D87>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E87<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D87+IF($D87<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C87))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A87=\"\",\"\",IF($D87>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E87<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D87+IF($D87<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C87))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Satelital",null,null,null,56,{"$f":"+IF($A88=\"\",\"\",$B88+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C88,0))","v":0},{"$f":"+(IF($A88=\"\",\"\",IF($D88>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E88<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D88,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C88))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A88=\"\",\"\",IF($D88>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E88<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D88,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C88))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A88=\"\",\"\",IF($D88>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E88<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D88,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C88))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A88=\"\",\"\",IF($D88>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E88<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D88,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C88))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Plan satelital",null,{"$f":"+IF(Tipologia_Campo=\"LTE No Lic BH Satelital\",Detalle!H963,0)","v":0},null,56,0,{"$f":"+(IF($A89=\"\",\"\",IF($D89>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E89<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D89+IF($D89<>\"\",1,0),0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C89))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A89=\"\",\"\",IF($D89>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E89<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D89+IF($D89<>\"\",1,0),0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C89))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A89=\"\",\"\",IF($D89>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E89<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D89+IF($D89<>\"\",1,0),0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C89))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+(IF($A89=\"\",\"\",IF($D89>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E89<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D89+IF($D89<>\"\",1,0),0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C89))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["Cargo de activacion",{"$f":"+IF(Tipologia_Campo=\"LTE No Lic BH Satelital\",Detalle!H964,0)","v":0},null,null,56,{"$f":"+IF($A90=\"\",\"\",IF($D90=F$15,$B90+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C90,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"+IF($A90=\"\",\"\",IF($D90=BR$15,$B90+IF(MONTH($B$8)-MONTH($B$7)+$E$14=BQ$14,$C90,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["VSAT (con instalacion)",{"$f":"+IF(Tipologia_Campo=\"LTE No Lic BH Satelital\",Detalle!P965,0)","v":0},null,null,56,{"$f":"+IF($A91=\"\",\"\",IF($D91=F$15,$B91+IF(MONTH($B$8)-MONTH($B$7)+$E$14=E$14,$C91,0),0))","v":0},0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,null,null,{"$f":"+(IF($A92=\"\",\"\",IF($D92>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E92<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D92+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C92))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A92=\"\",\"\",IF($D92>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E92<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D92+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C92))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A92=\"\",\"\",IF($D92>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E92<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D92+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C92))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A92=\"\",\"\",IF($D92>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E92<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D92+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C92))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A93=\"\",\"\",IF($D93>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E93<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D93+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C93))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A93=\"\",\"\",IF($D93>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E93<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D93+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C93))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A93=\"\",\"\",IF($D93>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E93<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D93+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C93))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A93=\"\",\"\",IF($D93>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E93<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D93+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C93))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A94=\"\",\"\",IF($D94>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E94<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D94+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C94))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A94=\"\",\"\",IF($D94>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E94<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D94+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C94))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A94=\"\",\"\",IF($D94>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E94<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D94+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C94))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A94=\"\",\"\",IF($D94>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E94<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D94+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C94))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A95=\"\",\"\",IF($D95>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E95<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D95+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C95))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A95=\"\",\"\",IF($D95>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E95<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D95+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C95))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A95=\"\",\"\",IF($D95>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E95<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D95+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C95))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A95=\"\",\"\",IF($D95>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E95<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D95+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C95))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A96=\"\",\"\",IF($D96>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E96<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D96+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C96))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A96=\"\",\"\",IF($D96>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E96<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D96+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C96))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A96=\"\",\"\",IF($D96>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E96<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D96+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C96))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A96=\"\",\"\",IF($D96>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E96<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D96+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C96))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A97=\"\",\"\",IF($D97>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E97<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D97+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C97))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A97=\"\",\"\",IF($D97>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E97<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D97+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C97))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A97=\"\",\"\",IF($D97>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E97<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D97+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C97))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A97=\"\",\"\",IF($D97>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E97<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D97+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C97))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A98=\"\",\"\",IF($D98>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E98<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D98+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C98))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A98=\"\",\"\",IF($D98>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E98<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D98+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C98))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A98=\"\",\"\",IF($D98>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E98<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D98+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C98))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A98=\"\",\"\",IF($D98>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E98<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D98+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C98))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A99=\"\",\"\",IF($D99>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E99<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D99+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C99))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A99=\"\",\"\",IF($D99>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E99<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D99+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C99))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A99=\"\",\"\",IF($D99>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E99<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D99+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C99))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A99=\"\",\"\",IF($D99>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E99<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D99+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C99))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A100=\"\",\"\",IF($D100>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E100<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D100+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C100))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A100=\"\",\"\",IF($D100>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E100<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D100+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C100))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A100=\"\",\"\",IF($D100>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E100<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D100+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C100))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A100=\"\",\"\",IF($D100>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E100<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D100+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C100))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]
[null,null,null,null,null,null,{"$f":"+(IF($A101=\"\",\"\",IF($D101>MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion))+1,0,IF($E101<=(MONTH(G$16)-MONTH(InicioFuncion)+12*(YEAR(G$16)-YEAR(InicioFuncion)))-$D101+1,0,IF(G$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=F$14,$C101))))*HLOOKUP(YEAR(G$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A101=\"\",\"\",IF($D101>MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion))+1,0,IF($E101<=(MONTH(AM$16)-MONTH(InicioFuncion)+12*(YEAR(AM$16)-YEAR(InicioFuncion)))-$D101+1,0,IF(AM$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=AL$14,$C101))))*HLOOKUP(YEAR(AM$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A101=\"\",\"\",IF($D101>MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion))+1,0,IF($E101<=(MONTH(BS$16)-MONTH(InicioFuncion)+12*(YEAR(BS$16)-YEAR(InicioFuncion)))-$D101+1,0,IF(BS$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=BR$14,$C101))))*HLOOKUP(YEAR(BS$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","","","","","","","","","","",{"$f":"+(IF($A101=\"\",\"\",IF($D101>MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion))+1,0,IF($E101<=(MONTH(CY$16)-MONTH(InicioFuncion)+12*(YEAR(CY$16)-YEAR(InicioFuncion)))-$D101+1,0,IF(CY$15>$B$9,0,IF((YEAR($B$8)-YEAR($B$7))*12+(MONTH($B$8)-MONTH($B$7))+$E$14<=CX$14,$C101))))*HLOOKUP(YEAR(CY$16),$E$3:$O$5,3,0)))","v":""},"","","","","","","","","","","","","","","","","","","","","","",""]

{"sheet":"Detalle","index":3,"n_rows":979,"n_cols":20,"rows_kept":979,"cut":false,"hidden":false,"merged":[]}
["Tipología","Grupo","Descripcion","Detalle","Tipos","Clase","Unidad","Valor","TRM","Relación","Terreno - Energia","Kw-Energia","Clase Torre","Sector Enodeb","FTTH","Total","Item utilizado"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",17740633.5,1,{"$f":"+IF(ISNUMBER(FIND(\"12 - 18\",D2)),\"12-18\",IF(ISNUMBER(FIND(\"19 - 35\",D2)),\"19-35\",IF(ISNUMBER(FIND(\"36 - 45\",D2)),\"36-45\",IF(ISNUMBER(FIND(\"46 - 60\",D2)),\"46-60\",IF(ISNUMBER(FIND(\"90\",D2)),\"90\",\"\")))))","v":"12-18"},null,null,null,null,"S",{"$f":"+I2*H2","v":17740633.5},"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",1,"CAPEX","Unitario",17740633.5,1,"19-35",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",1,"CAPEX","Unitario",17740633.5,1,"36-45",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",1,"CAPEX","Unitario",17740633.5,1,"46-60",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 90",1,"CAPEX","Unitario",17740633.5,1,"90",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",17740633.5,1,"12-18",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",2,"CAPEX","Unitario",17740633.5,1,"19-35",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",2,"CAPEX","Unitario",17740633.5,1,"36-45",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",2,"CAPEX","Unitario",17740633.5,1,"46-60",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 90",2,"CAPEX","Unitario",17740633.5,1,"90",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",17740633.5,1,"12-18",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",3,"CAPEX","Unitario",17740633.5,1,"19-35",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",3,"CAPEX","Unitario",17740633.5,1,"36-45",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",3,"CAPEX","Unitario",17740633.5,1,"46-60",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Servicios Profesionales: Terreno, Ambiente, Aeronautica","Altura (mts) / (Monopolo, Portatil, Convencional) 90",3,"CAPEX","Unitario",17740633.5,1,"90",null,null,null,null,"S",17740633.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",36660939,1,"12-18",null,null,"Monopolo",null,"S",36660939,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",36660939,1,"12-18",null,null,"Monopolo",null,"S",36660939,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",36660939,1,"12-18",null,null,"Monopolo",null,"S",36660939,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",67861699.359999999,1,"12-18",null,null,"Convencional",null,"S",67861699.359999999,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",1,"CAPEX","Unitario",82415267.5,1,"19-35",null,null,"Convencional",null,"S",82415267.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",1,"CAPEX","Unitario",84340950,1,"36-45",null,null,"Convencional",null,"S",84340950,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",1,"CAPEX","Unitario",109632220.5,1,"46-60",null,null,"Convencional",null,"S",109632220.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 90",1,"CAPEX","Unitario",167735585,1,"90",null,null,"Convencional",null,"S",167735585,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",67861699.359999999,1,"12-18",null,null,"Convencional",null,"S",67861699.359999999,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",2,"CAPEX","Unitario",82415267.5,1,"19-35",null,null,"Convencional",null,"S",82415267.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",2,"CAPEX","Unitario",84340950,1,"36-45",null,null,"Convencional",null,"S",84340950,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",2,"CAPEX","Unitario",109632220.5,1,"46-60",null,null,"Convencional",null,"S",109632220.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 90",2,"CAPEX","Unitario",167735585,1,"90",null,null,"Convencional",null,"S",167735585,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",67861699.359999999,1,"12-18",null,null,"Convencional",null,"S",67861699.359999999,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",3,"CAPEX","Unitario",82415267.5,1,"19-35",null,null,"Convencional",null,"S",82415267.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",3,"CAPEX","Unitario",84340950,1,"36-45",null,null,"Convencional",null,"S",84340950,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",3,"CAPEX","Unitario",109632220.5,1,"46-60",null,null,"Convencional",null,"S",109632220.5,"N"]
["TMC 4G","Obra Civil","Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / (Monopolo, Portatil, Convencional) 90",3,"CAPEX","Unitario",167735585,1,"90",null,null,"Convencional",null,"S",167735585,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",6329992.5,1,{"$f":"+IF(ISNUMBER(FIND(\"12 - 18\",D35)),\"12-18\",IF(ISNUMBER(FIND(\"19 - 35\",D35)),\"19-35\",IF(ISNUMBER(FIND(\"36 - 45\",D35)),\"36-45\",IF(ISNUMBER(FIND(\"46 - 60\",D35)),\"46-60\",IF(ISNUMBER(FIND(\"90\",D35)),\"90\",\"\")))))","v":"12-18"},{"$f":"60000000*0.4","v":24000000},null,null,null,"S",{"$f":"+I35*H35","v":6329992.5},"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",1,"CAPEX","Unitario",6329992.5,1,"19-35",{"$f":"60000000*0.4","v":24000000},null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",1,"CAPEX","Unitario",6329992.5,1,"36-45",{"$f":"60000000*0.2","v":12000000},null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",1,"CAPEX","Unitario",6329992.5,1,"46-60",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",1,"CAPEX","Unitario",6329992.5,1,"90",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",6329992.5,1,"12-18",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",2,"CAPEX","Unitario",6329992.5,1,"19-35",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",2,"CAPEX","Unitario",6329992.5,1,"36-45",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",2,"CAPEX","Unitario",6329992.5,1,"46-60",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",2,"CAPEX","Unitario",6329992.5,1,"90",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",6329992.5,1,"12-18",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",3,"CAPEX","Unitario",6329992.5,1,"19-35",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",3,"CAPEX","Unitario",6329992.5,1,"36-45",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",3,"CAPEX","Unitario",6329992.5,1,"46-60",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Caseta Para Equipos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",3,"CAPEX","Unitario",6329992.5,1,"90",null,null,null,null,"S",6329992.5,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",15580725,1,"12-18",null,null,null,null,"S",15580725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",1,"CAPEX","Unitario",23430725,1,"19-35",null,null,null,null,"S",23430725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",1,"CAPEX","Unitario",31030725,1,"36-45",null,null,null,null,"S",31030725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",1,"CAPEX","Unitario",36830725,1,"46-60",null,null,null,null,"S",36830725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 90",1,"CAPEX","Unitario",48730725,1,"90",null,null,null,null,"S",48730725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",15580725,1,"12-18",null,null,null,null,"S",15580725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",2,"CAPEX","Unitario",23430725,1,"19-35",null,null,null,null,"S",23430725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",2,"CAPEX","Unitario",31030725,1,"36-45",null,null,null,null,"S",31030725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",2,"CAPEX","Unitario",36830725,1,"46-60",null,null,null,null,"S",36830725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 90",2,"CAPEX","Unitario",48730725,1,"90",null,null,null,null,"S",48730725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",15580725,1,"12-18",null,null,null,null,"S",15580725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",3,"CAPEX","Unitario",23430725,1,"19-35",null,null,null,null,"S",23430725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",3,"CAPEX","Unitario",31030725,1,"36-45",null,null,null,null,"S",31030725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",3,"CAPEX","Unitario",36830725,1,"46-60",null,null,null,null,"S",36830725,"N"]
["TMC 4G","Obra Civil","Obra civil - Encerramiento","Altura (mts) / (Monopolo, Portatil, Convencional) 90",3,"CAPEX","Unitario",48730725,1,"90",null,null,null,null,"S",48730725,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",1,"CAPEX","Unitario",12000000,1,"12-18",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",1,"CAPEX","Unitario",12000000,1,"19-35",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",1,"CAPEX","Unitario",12000000,1,"36-45",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",1,"CAPEX","Unitario",12000000,1,"46-60",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",1,"CAPEX","Unitario",12000000,1,"90",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",2,"CAPEX","Unitario",12000000,1,"12-18",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",2,"CAPEX","Unitario",12000000,1,"19-35",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",2,"CAPEX","Unitario",12000000,1,"36-45",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",2,"CAPEX","Unitario",12000000,1,"46-60",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",2,"CAPEX","Unitario",12000000,1,"90",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 12 - 18",3,"CAPEX","Unitario",12000000,1,"12-18",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 19 - 35",3,"CAPEX","Unitario",12000000,1,"19-35",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 36 - 45",3,"CAPEX","Unitario",12000000,1,"36-45",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 46 - 60",3,"CAPEX","Unitario",12000000,1,"46-60",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Obra civil - Trasiegos","Altura (mts) / (Monopolo, Portatil, Convencional) 90",3,"CAPEX","Unitario",12000000,1,"90",null,null,null,null,"S",12000000,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",4401180,1,"12-18",null,null,"Monopolo",null,"S",4401180,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",6303360,1,"19-35",null,null,"Monopolo",null,"S",6303360,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",12449147.083199998,1,"36-45",null,null,"Monopolo",null,"S",12449147.083199998,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",8001700,1,"46-60",null,null,"Monopolo",null,"S",8001700,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",8469160,1,"90",null,null,"Monopolo",null,"S",8469160,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",4401180,1,"12-18",null,null,"Monopolo",null,"S",4401180,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",11969810.908879999,1,"19-35",null,null,"Monopolo",null,"S",11969810.908879999,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",7709660,1,"36-45",null,null,"Monopolo",null,"S",7709660,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",8001700,1,{"$f":"+IF(ISNUMBER(FIND(\"12 - 18\",D88)),\"12-18\",IF(ISNUMBER(FIND(\"19 - 35\",D88)),\"19-35\",IF(ISNUMBER(FIND(\"36 - 45\",D88)),\"36-45\",IF(ISNUMBER(FIND(\"46 - 60\",D88)),\"46-60\",IF(ISNUMBER(FIND(\"90\",D88)),\"90\",\"\")))))","v":"46-60"},null,null,"Monopolo",null,"S",{"$f":"+I88*H88","v":8001700},"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",8469160,1,"90",null,null,"Monopolo",null,"S",8469160,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Sin Acceso Vial",3,"OPEX","Annual",4401180,1,"12-18",null,null,"Monopolo",null,"S",4401180,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Sin Acceso Vial",3,"OPEX","Annual",11969810.908879999,1,"19-35",null,null,"Monopolo",null,"S",11969810.908879999,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Sin Acceso Vial",3,"OPEX","Annual",7709660,1,"36-45",null,null,"Monopolo",null,"S",7709660,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Sin Acceso Vial",3,"OPEX","Annual",8001700,1,"46-60",null,null,"Monopolo",null,"S",8001700,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Monopolo (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Sin Acceso Vial",3,"OPEX","Annual",8469160,1,"90",null,null,"Monopolo",null,"S",8469160,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",6338619.4199999999,1,"12-18",null,null,"Convencional",null,"S",6338619.4199999999,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",7108920,1,"19-35",null,null,"Convencional",null,"S",7108920,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",7709660,1,"36-45",null,null,"Convencional",null,"S",7709660,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",15390347.083199998,1,"46-60",null,null,"Convencional",null,"S",15390347.083199998,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",21472647.0832,1,"90",null,null,"Convencional",null,"S",21472647.0832,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",6338619.4199999999,1,"12-18",null,null,"Convencional",null,"S",6338619.4199999999,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",7108920,1,"19-35",null,null,"Convencional",null,"S",7108920,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",7709660,1,"36-45",null,null,"Convencional",null,"S",7709660,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",15390347.083199998,1,"46-60",null,null,"Convencional",null,"S",15390347.083199998,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",21472647.0832,1,"90",null,null,"Convencional",null,"S",21472647.0832,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Sin Acceso Vial",3,"OPEX","Annual",6338619.4199999999,1,"12-18",null,null,"Convencional",null,"S",6338619.4199999999,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Sin Acceso Vial",3,"OPEX","Annual",7108920,1,"19-35",null,null,"Convencional",null,"S",7108920,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Sin Acceso Vial",3,"OPEX","Annual",7709660,1,"36-45",null,null,"Convencional",null,"S",7709660,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Sin Acceso Vial",3,"OPEX","Annual",15390347.083199998,1,"46-60",null,null,"Convencional",null,"S",15390347.083199998,"N"]
["TMC 4G","Obra Civil","Mto Torre (Incluye: Tierra, Pararrayo) - Convencional (*)","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Sin Acceso Vial",3,"OPEX","Annual",21472647.0832,1,"90",null,null,"Convencional",null,"S",21472647.0832,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2843796.1332,1,"12-18",null,null,null,null,"S",2843796.1332,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2843796.1332,1,"19-35",null,null,null,null,"S",2843796.1332,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2843796.1332,1,"36-45",null,null,null,null,"S",2843796.1332,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2843796.1332,1,"46-60",null,null,null,null,"S",2843796.1332,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2843796.1332,1,"90",null,null,null,null,"S",2843796.1332,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3081959.9588799998,1,"12-18",null,null,null,null,"S",3081959.9588799998,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3081959.9588799998,1,"19-35",null,null,null,null,"S",3081959.9588799998,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3081959.9588799998,1,"36-45",null,null,null,null,"S",3081959.9588799998,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3081959.9588799998,1,"46-60",null,null,null,null,"S",3081959.9588799998,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3081959.9588799998,1,"90",null,null,null,null,"S",3081959.9588799998,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Sin Acceso Vial",3,"OPEX","Annual",3197619.5,1,"12-18",null,null,null,null,"S",3197619.5,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Sin Acceso Vial",3,"OPEX","Annual",3197619.5,1,"19-35",null,null,null,null,"S",3197619.5,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Sin Acceso Vial",3,"OPEX","Annual",3197619.5,1,"36-45",null,null,null,null,"S",3197619.5,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Sin Acceso Vial",3,"OPEX","Annual",3197619.5,1,"46-60",null,null,null,null,"S",3197619.5,"N"]
["TMC 4G","Obra Civil","Caseta / Rack Equipos","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Sin Acceso Vial",3,"OPEX","Annual",3197619.5,1,"90",null,null,null,null,"S",3197619.5,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2712170.5974270534,1,"12-18",null,null,null,null,"S",2712170.5974270534,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",2712170.5974270534,1,"19-35",null,null,null,null,"S",2712170.5974270534,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",3170463.0884838169,1,"36-45",null,null,null,null,"S",3170463.0884838169,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",4316194.3161257254,1,"46-60",null,null,null,null,"S",4316194.3161257254,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Annual",5461925.5437676338,1,"90",null,null,null,null,"S",5461925.5437676338,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",2950334.4231070532,1,"12-18",null,null,null,null,"S",2950334.4231070532,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",2950334.4231070532,1,"19-35",null,null,null,null,"S",2950334.4231070532,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",3408626.9141638167,1,"36-45",null,null,null,null,"S",3408626.9141638167,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",4554358.1418057252,1,"46-60",null,null,null,null,"S",4554358.1418057252,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Annual",5700089.3694476336,1,"90",null,null,null,null,"S",5700089.3694476336,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Sin Acceso Vial",3,"OPEX","Annual",3065993.9642270533,1,"12-18",null,null,null,null,"S",3065993.9642270533,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Sin Acceso Vial",3,"OPEX","Annual",3065993.9642270533,1,"19-35",null,null,null,null,"S",3065993.9642270533,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Sin Acceso Vial",3,"OPEX","Annual",3524286.4552838169,1,{"$f":"+IF(ISNUMBER(FIND(\"12 - 18\",D137)),\"12-18\",IF(ISNUMBER(FIND(\"19 - 35\",D137)),\"19-35\",IF(ISNUMBER(FIND(\"36 - 45\",D137)),\"36-45\",IF(ISNUMBER(FIND(\"46 - 60\",D137)),\"46-60\",IF(ISNUMBER(FIND(\"90\",D137)),\"90\",\"\")))))","v":"36-45"},null,null,null,null,"S",{"$f":"+I137*H137","v":3524286.4552838169},"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Sin Acceso Vial",3,"OPEX","Annual",4670017.6829257254,1,"46-60",null,null,null,null,"S",4670017.6829257254,"N"]
["TMC 4G","Obra Civil","Mto encerramiento","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Sin Acceso Vial",3,"OPEX","Annual",5815748.9105676338,1,"90",null,null,null,null,"S",5815748.9105676338,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Mensual",7067789.5,1,"12-18",null,null,null,null,"S",7067789.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Mensual",7067789.5,1,"19-35",null,null,null,null,"S",7067789.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Mensual",7067789.5,1,"36-45",null,null,null,null,"S",7067789.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Mensual",7067789.5,1,"46-60",null,null,null,null,"S",7067789.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Facil (Acceso Vial Y Cercania A Operador Electrico)",1,"OPEX","Mensual",7067789.5,1,"90",null,null,null,null,"S",7067789.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Mensual",7805300,1,"12-18",null,null,null,null,"S",7805300,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Mensual",7805300,1,"19-35",null,null,null,null,"S",7805300,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Mensual",7805300,1,"36-45",null,null,null,null,"S",7805300,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Mensual",7805300,1,"46-60",null,null,null,null,"S",7805300,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Dificil (Acceso Vial Y Cercania A Operador Electrico)",2,"OPEX","Mensual",7805300,1,"90",null,null,null,null,"S",7805300,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 12 - 18 Sin Acceso Vial",3,"OPEX","Mensual",9582636.5,1,"12-18",null,null,null,null,"S",9582636.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 19 - 35 Sin Acceso Vial",3,"OPEX","Mensual",9582636.5,1,"19-35",null,null,null,null,"S",9582636.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 36 - 45 Sin Acceso Vial",3,"OPEX","Mensual",9582636.5,1,"36-45",null,null,null,null,"S",9582636.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 46 - 60 Sin Acceso Vial",3,"OPEX","Mensual",9582636.5,1,"46-60",null,null,null,null,"S",9582636.5,"N"]
["TMC 4G","Obra Civil","Arriendo","Altura (mts) / Tipo (Monopolo, Portatil, Convencional) 90 Sin Acceso Vial",3,"OPEX","Mensual",9582636.5,1,"90",null,null,null,null,"S",9582636.5,"N"]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",7970590.2786666667,1,500,"Ondulado",25,null,null,null,{"$f":"+I155*H155","v":7970590.2786666667},"N",null,{"$f":"+$T$155*H155*12/5","v":14653133.168300802},0.76600000000000001]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",17253486.835999999,1,1000,"Ondulado",25,null,null,null,17253486.835999999,"N",null,31718810.199302398]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",27004015.447999999,1,1500,"Ondulado",25,null,null,null,27004015.447999999,"N",null,49644181.999603197]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",40124226.079999998,1,2500,"Ondulado",25,null,null,null,40124226.079999998,"N",null,73764377.225472003]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",7970590.2786666667,1,500,"Ondulado",15,null,null,null,7970590.2786666667,"N",null,14653133.168300802]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",17253486.835999999,1,1000,"Ondulado",15,null,null,null,17253486.835999999,"N",null,31718810.199302398]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",27004015.447999999,1,1500,"Ondulado",15,null,null,null,27004015.447999999,"N",null,49644181.999603197]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",40124226.079999998,1,2500,"Ondulado",15,null,null,null,40124226.079999998,"N",null,73764377.225472003]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",9192714.8159999996,1,500,"Ondulado",25,null,null,null,9192714.8159999996,"N",null,16899886.917734399]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",19252335.373333331,1,1000,"Ondulado",25,null,null,null,19252335.373333331,"N",null,35393493.350336]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",29532935.985333335,1,1500,"Ondulado",25,null,null,null,29532935.985333335,"N",null,54293349.515436806]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",42653146.61733333,1,2500,"Ondulado",25,null,null,null,42653146.61733333,"N",null,78413544.74130559]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",9192714.8159999996,1,500,"Ondulado",15,null,null,null,9192714.8159999996,"N",null,16899886.917734399]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",19252335.373333331,1,1000,"Ondulado",15,null,null,null,19252335.373333331,"N",null,35393493.350336]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",29532935.985333335,1,1500,"Ondulado",15,null,null,null,29532935.985333335,"N",null,54293349.515436806]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",42653146.61733333,1,2500,"Ondulado",15,null,null,null,42653146.61733333,"N",null,78413544.74130559]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",9192714.8159999996,1,500,"Ondulado",25,null,null,null,{"$f":"+I171*H171","v":9192714.8159999996},"N",null,16899886.917734399]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",19252335.373333331,1,1000,"Ondulado",25,null,null,null,19252335.373333331,"N",null,35393493.350336]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",29532935.985333335,1,1500,"Ondulado",25,null,null,null,29532935.985333335,"N",null,54293349.515436806]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",42653146.61733333,1,2500,"Ondulado",25,null,null,null,42653146.61733333,"N",null,78413544.74130559]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",9192714.8159999996,1,500,"Ondulado",15,null,null,null,9192714.8159999996,"N",null,16899886.917734399]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",19252335.373333331,1,1000,"Ondulado",15,null,null,null,19252335.373333331,"N",null,35393493.350336]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",29532935.985333335,1,1500,"Ondulado",15,null,null,null,29532935.985333335,"N",null,54293349.515436806]
["TMC 4G","Red Energia","Terreno Ondulado - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",42653146.61733333,1,2500,"Ondulado",15,null,null,null,42653146.61733333,"N",null,78413544.74130559]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",9814367.0633333344,1,500,"Ondulado",25,null,null,null,9814367.0633333344,"N",null,18042732.409232002]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",18918907.063333333,1,1000,"Ondulado",25,null,null,null,18918907.063333333,"N",null,34780518.745232001]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",27201273.73,1,1500,"Ondulado",25,null,null,null,27201273.73,"N",null,50006821.625231996]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",40232193.729999997,1,2500,"Ondulado",25,null,null,null,40232193.729999997,"N",null,73962864.953232005]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",9408240.3966666665,1,500,"Ondulado",15,null,null,null,9408240.3966666665,"N",null,17296109.145231999]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",18106653.73,1,1000,"Ondulado",15,null,null,null,18106653.73,"N",null,33287272.217232]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",25982893.73,1,1500,"Ondulado",15,null,null,null,25982893.73,"N",null,47766951.833232]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",38201560.396666668,1,2500,"Ondulado",15,null,null,null,38201560.396666668,"N",null,70229748.633232012]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",10804039.063333334,1,500,"Ondulado",25,null,null,null,10804039.063333334,"N",null,{"$f":"+$T$155*H187*12/5","v":19862145.414032001}]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",20685303.063333333,1,1000,"Ondulado",25,null,null,null,20685303.063333333,"N",null,38027861.151631996]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",29497741.73,1,1500,"Ondulado",25,null,null,null,29497741.73,"N",null,54228648.396432005]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",42528661.729999997,1,2500,"Ondulado",25,null,null,null,42528661.729999997,"N",null,78184691.724431992]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",10397912.396666666,1,500,"Ondulado",15,null,null,null,10397912.396666666,"N",null,19115522.150032002]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",19873049.73,1,1000,"Ondulado",15,null,null,null,19873049.73,"N",null,36534614.623631999]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",28279361.73,1,1500,"Ondulado",15,null,null,null,28279361.73,"N",null,51988778.604432002]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",40498028.396666668,1,2500,"Ondulado",15,null,null,null,40498028.396666668,"N",null,74451575.404431999]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",10804039.063333334,1,500,"Ondulado",25,null,null,null,{"$f":"+I195*H195","v":10804039.063333334},"N",null,19862145.414032001]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",20685303.063333333,1,1000,"Ondulado",25,null,null,null,20685303.063333333,"N",null,38027861.151631996]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",29497741.73,1,1500,"Ondulado",25,null,null,null,29497741.73,"N",null,54228648.396432005]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",42528661.729999997,1,2500,"Ondulado",25,null,null,null,42528661.729999997,"N",null,78184691.724431992]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",10397912.396666666,1,500,"Ondulado",15,null,null,null,10397912.396666666,"N",null,19115522.150032002]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",19873049.73,1,1000,"Ondulado",15,null,null,null,19873049.73,"N",null,36534614.623631999]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",28279361.73,1,1500,"Ondulado",15,null,null,null,28279361.73,"N",null,51988778.604432002]
["TMC 4G","Red Energia","Terreno Ondulado - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",40498028.396666668,1,2500,"Ondulado",15,null,null,null,40498028.396666668,"N",null,74451575.404431999]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6121618.5633333335,1,500,"Ondulado",25,null,null,null,6121618.5633333335,"N",null,11253983.566832002]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",11887924.563333333,1,1000,"Ondulado",25,null,null,null,11887924.563333333,"N",null,21854760.517232001]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",16484244.979999999,1,1500,"Ondulado",25,null,null,null,16484244.979999999,"N",null,30304635.971231997]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",22136370.23,1,2500,"Ondulado",25,null,null,null,22136370.23,"N",null,40695503.030832]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6121618.5633333335,1,500,"Ondulado",15,null,null,null,6121618.5633333335,"N",null,11253983.566832002]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",11887924.563333333,1,1000,"Ondulado",15,null,null,null,11887924.563333333,"N",null,21854760.517232001]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",16484244.979999999,1,1500,"Ondulado",15,null,null,null,16484244.979999999,"N",null,30304635.971231997]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",22136370.23,1,2500,"Ondulado",15,null,null,null,22136370.23,"N",null,40695503.030832]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",7111290.5633333335,1,500,"Ondulado",25,null,null,null,7111290.5633333335,"N",null,13073396.571632002]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",13654320.563333333,1,1000,"Ondulado",25,null,null,null,13654320.563333333,"N",null,25102102.923632]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",18780712.98,1,1500,"Ondulado",25,null,null,null,18780712.98,"N",null,34526462.742431998]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",24432838.23,1,2500,"Ondulado",25,null,null,null,24432838.23,"N",null,44917329.802032009]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",7111290.5633333335,1,500,"Ondulado",15,null,null,null,{"$f":"+I215*H215","v":7111290.5633333335},"N",null,13073396.571632002]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",13654320.563333333,1,1000,"Ondulado",15,null,null,null,13654320.563333333,"N",null,25102102.923632]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",18780712.98,1,1500,"Ondulado",15,null,null,null,18780712.98,"N",null,34526462.742431998]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",24432838.23,1,2500,"Ondulado",15,null,null,null,24432838.23,"N",null,44917329.802032009]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",7111290.5633333335,1,500,"Ondulado",25,null,null,null,7111290.5633333335,"N",null,{"$f":"+$T$155*H219*12/5","v":13073396.571632002}]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",13654320.563333333,1,1000,"Ondulado",25,null,null,null,13654320.563333333,"N",null,25102102.923632]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",18780712.98,1,1500,"Ondulado",25,null,null,null,18780712.98,"N",null,34526462.742431998]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",24432838.23,1,2500,"Ondulado",25,null,null,null,24432838.23,"N",null,44917329.802032009]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",7111290.5633333335,1,500,"Ondulado",15,null,null,null,{"$f":"+I223*H223","v":7111290.5633333335},"N",null,13073396.571632002]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",13654320.563333333,1,1000,"Ondulado",15,null,null,null,13654320.563333333,"N",null,25102102.923632]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",18780712.98,1,1500,"Ondulado",15,null,null,null,18780712.98,"N",null,34526462.742431998]
["TMC 4G","Red Energia","Terreno Ondulado - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",24432838.23,1,2500,"Ondulado",15,null,null,null,24432838.23,"N",null,44917329.802032009]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6691474.0949999997,1,500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",6691474.0949999997,1,1000,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6691474.0949999997,1,1500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6691474.0949999997,1,2500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6257369.0949999997,1,500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",6257369.0949999997,1,1000,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6257369.0949999997,1,1500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6257369.0949999997,1,2500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6691474.0949999997,1,500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6691474.0949999997,1,1000,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",6691474.0949999997,1,1500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",6691474.0949999997,1,2500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6257369.0949999997,1,500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6257369.0949999997,1,1000,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",6257369.0949999997,1,1500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",6257369.0949999997,1,2500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6691474.0949999997,1,500,"Ondulado",25,null,null,null,{"$f":"+I243*H243","v":6691474.0949999997},"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6691474.0949999997,1,1000,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",6691474.0949999997,1,1500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",6691474.0949999997,1,2500,"Ondulado",25,null,null,null,6691474.0949999997,"N",null,12301605.976248]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6257369.0949999997,1,500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6257369.0949999997,1,1000,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",6257369.0949999997,1,1500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",6257369.0949999997,1,2500,"Ondulado",15,null,null,null,6257369.0949999997,"N",null,11503547.344248001]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5660355.7299999995,1,500,"Ondulado",25,null,null,null,5660355.7299999995,"N",null,{"$f":"+$T$155*H251*12/5","v":10405997.974032}]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",10019269.063333333,1,1000,"Ondulado",25,null,null,null,10019269.063333333,"N",null,18419424.246032]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",13556009.063333333,1,1500,"Ondulado",25,null,null,null,13556009.063333333,"N",null,24921367.062032003]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",17629009.063333333,1,2500,"Ondulado",25,null,null,null,17629009.063333333,"N",null,32409170.262032002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5660355.7299999995,1,500,"Ondulado",15,null,null,null,5660355.7299999995,"N",null,10405997.974032]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",10019269.063333333,1,1000,"Ondulado",15,null,null,null,10019269.063333333,"N",null,18419424.246032]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",13556009.063333333,1,1500,"Ondulado",15,null,null,null,13556009.063333333,"N",null,24921367.062032003]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",17629009.063333333,1,2500,"Ondulado",15,null,null,null,17629009.063333333,"N",null,32409170.262032002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6650027.7299999995,1,500,"Ondulado",25,null,null,null,6650027.7299999995,"N",null,12225410.978832001]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",11785665.063333333,1,1000,"Ondulado",25,null,null,null,11785665.063333333,"N",null,21666766.652432002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",15852477.063333333,1,1500,"Ondulado",25,null,null,null,15852477.063333333,"N",null,29143193.833231997]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",19925477.063333333,1,2500,"Ondulado",25,null,null,null,19925477.063333333,"N",null,36630997.033231996]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6650027.7299999995,1,500,"Ondulado",15,null,null,null,6650027.7299999995,"N",null,12225410.978832001]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",11785665.063333333,1,1000,"Ondulado",15,null,null,null,11785665.063333333,"N",null,21666766.652432002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",15852477.063333333,1,1500,"Ondulado",15,null,null,null,15852477.063333333,"N",null,29143193.833231997]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",19925477.063333333,1,2500,"Ondulado",15,null,null,null,19925477.063333333,"N",null,36630997.033231996]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6650027.7299999995,1,500,"Ondulado",25,null,null,null,{"$f":"+I267*H267","v":6650027.7299999995},"N",null,12225410.978832001]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",11785665.063333333,1,1000,"Ondulado",25,null,null,null,11785665.063333333,"N",null,21666766.652432002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",15852477.063333333,1,1500,"Ondulado",25,null,null,null,15852477.063333333,"N",null,29143193.833231997]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",19925477.063333333,1,2500,"Ondulado",25,null,null,null,19925477.063333333,"N",null,36630997.033231996]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6650027.7299999995,1,500,"Ondulado",15,null,null,null,6650027.7299999995,"N",null,12225410.978832001]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",11785665.063333333,1,1000,"Ondulado",15,null,null,null,11785665.063333333,"N",null,21666766.652432002]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",15852477.063333333,1,1500,"Ondulado",15,null,null,null,15852477.063333333,"N",null,29143193.833231997]
["TMC 4G","Red Energia","Terreno Ondulado - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",19925477.063333333,1,2500,"Ondulado",15,null,null,null,19925477.063333333,"N",null,36630997.033231996]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",778384.16280000005,1,500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,{"$f":"+$T$275*H275*12/5","v":276482.05462656001},0.14799999999999999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",778384.16280000005,1,1000,"Ondulado",25,null,null,null,778384.16280000005,"N",null,{"$f":"+$T$275*H276*12/5","v":276482.05462656001}]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",778384.16280000005,1,1500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",778384.16280000005,1,2500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",619854.30249999999,1,500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",619854.30249999999,1,1000,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",619854.30249999999,1,1500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",619854.30249999999,1,2500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",778384.16280000005,1,500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",778384.16280000005,1,1000,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",778384.16280000005,1,1500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",778384.16280000005,1,2500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",619854.30249999999,1,500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",619854.30249999999,1,1000,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",619854.30249999999,1,1500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",619854.30249999999,1,2500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",778384.16280000005,1,500,"Ondulado",25,null,null,null,{"$f":"+I291*H291","v":778384.16280000005},"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",778384.16280000005,1,1000,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",778384.16280000005,1,1500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",778384.16280000005,1,2500,"Ondulado",25,null,null,null,778384.16280000005,"N",null,276482.05462656001]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",619854.30249999999,1,500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",619854.30249999999,1,1000,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",619854.30249999999,1,1500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",619854.30249999999,1,2500,"Ondulado",15,null,null,null,619854.30249999999,"N",null,220172.24824799999]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",25,null,null,null,3086218.5474999999,"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",25,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",25,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",25,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",15,null,null,null,3086218.5474999999,"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",15,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",15,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",15,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",25,null,null,null,3086218.5474999999,"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",25,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",25,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",25,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",15,null,null,null,{"$f":"+I311*H311","v":3086218.5474999999},"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",15,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",15,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",15,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",25,null,null,null,3086218.5474999999,"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",25,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",25,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",25,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",3086218.5474999999,1,500,"Ondulado",15,null,null,null,{"$f":"+I319*H319","v":3086218.5474999999},"N",null,1096224.8280719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3715543.5474999999,1,1000,"Ondulado",15,null,null,null,3715543.5474999999,"N",null,1319761.0680719998]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",4715543.5475000003,1,1500,"Ondulado",15,null,null,null,4715543.5475000003,"N",null,1674961.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5715543.5475000003,1,2500,"Ondulado",15,null,null,null,5715543.5475000003,"N",null,2030161.0680720001]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",460286.44419999997,1,500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",460286.44419999997,1,1000,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",460286.44419999997,1,1500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",460286.44419999997,1,2500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",501741.18971399998,1,500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",501741.18971399998,1,1000,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",501741.18971399998,1,1500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",501741.18971399998,1,2500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",460286.44419999997,1,500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",460286.44419999997,1,1000,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",460286.44419999997,1,1500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",460286.44419999997,1,2500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",501741.18971399998,1,500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",501741.18971399998,1,1000,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",501741.18971399998,1,1500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",501741.18971399998,1,2500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",460286.44419999997,1,500,"Ondulado",25,null,null,null,{"$f":"+I339*H339","v":460286.44419999997},"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",460286.44419999997,1,1000,"Ondulado",25,null,null,null,460286.44419999997,"N",null,{"$f":"+$T$275*H340*12/5","v":163493.74497984}]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",460286.44419999997,1,1500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",460286.44419999997,1,2500,"Ondulado",25,null,null,null,460286.44419999997,"N",null,163493.74497984]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",501741.18971399998,1,500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",501741.18971399998,1,1000,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",501741.18971399998,1,1500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",501741.18971399998,1,2500,"Ondulado",15,null,null,null,501741.18971399998,"N",null,178218.47058641276]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",581400,1,500,"Ondulado",25,null,null,null,581400,"N",null,{"$f":"+$T$347*H347*12","v":188373.59999999998},2.7E-2]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2204366.6666666665,1,1000,"Ondulado",25,null,null,null,2204366.6666666665,"N",null,{"$f":"+$T$347*H348*12","v":714214.79999999993}]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3682433.3333333335,1,1500,"Ondulado",25,null,null,null,3682433.3333333335,"N",null,1193108.3999999999]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",4849100,1,2500,"Ondulado",25,null,null,null,4849100,"N",null,1571108.4]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",581400,1,500,"Ondulado",15,null,null,null,581400,"N",null,188373.59999999998]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2204366.6666666665,1,1000,"Ondulado",15,null,null,null,2204366.6666666665,"N",null,714214.79999999993]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3682433.3333333335,1,1500,"Ondulado",15,null,null,null,3682433.3333333335,"N",null,1193108.3999999999]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",4849100,1,2500,"Ondulado",15,null,null,null,4849100,"N",null,1571108.4]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1555820,1,500,"Ondulado",25,null,null,null,1555820,"N",null,504085.68]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",4382343.333333333,1,1000,"Ondulado",25,null,null,null,4382343.333333333,"N",null,1419879.2399999998]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7420496.666666667,1,1500,"Ondulado",25,null,null,null,7420496.666666667,"N",null,2404240.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",12020496.666666666,1,2500,"Ondulado",25,null,null,null,12020496.666666666,"N",null,3894640.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1555820,1,500,"Ondulado",15,null,null,null,1555820,"N",null,504085.68]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",4382343.333333333,1,1000,"Ondulado",15,null,null,null,4382343.333333333,"N",null,1419879.2399999998]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7420496.666666667,1,1500,"Ondulado",15,null,null,null,7420496.666666667,"N",null,2404240.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",12020496.666666666,1,2500,"Ondulado",15,null,null,null,12020496.666666666,"N",null,3894640.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1555820,1,500,"Ondulado",25,null,null,null,{"$f":"+I363*H363","v":1555820},"N",null,504085.68]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",4382343.333333333,1,1000,"Ondulado",25,null,null,null,4382343.333333333,"N",null,1419879.2399999998]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7420496.666666667,1,1500,"Ondulado",25,null,null,null,7420496.666666667,"N",null,2404240.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",12020496.666666666,1,2500,"Ondulado",25,null,null,null,12020496.666666666,"N",null,3894640.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1555820,1,500,"Ondulado",15,null,null,null,1555820,"N",null,504085.68]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",4382343.333333333,1,1000,"Ondulado",15,null,null,null,4382343.333333333,"N",null,1419879.2399999998]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7420496.666666667,1,1500,"Ondulado",15,null,null,null,7420496.666666667,"N",null,2404240.92]
["TMC 4G","Red Energia","Terreno Ondulado - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",12020496.666666666,1,2500,"Ondulado",15,null,null,null,12020496.666666666,"N",null,3894640.92]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3270466.6666666656,1,500,"Ondulado",25,null,null,null,3270466.6666666656,"N",null,{"$f":"+$T$371*H371*12","v":2315490.3999999966},{"$f":"1-SUM(T155:T370)","v":5.8999999999999941E-2}]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",4538233.3333333312,1,1000,"Ondulado",25,null,null,null,4538233.3333333312,"N",null,{"$f":"+$T$371*H372*12","v":3213069.1999999951}]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6489366.6666666642,1,1500,"Ondulado",25,null,null,null,6489366.6666666642,"N",null,4594471.5999999931]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",7426699.9999999972,1,2500,"Ondulado",25,null,null,null,7426699.9999999972,"N",null,5258103.5999999931]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3270466.6666666656,1,500,"Ondulado",15,null,null,null,3270466.6666666656,"N",null,2315490.3999999966]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",4538233.3333333312,1,1000,"Ondulado",15,null,null,null,4538233.3333333312,"N",null,3213069.1999999951]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6489366.6666666642,1,1500,"Ondulado",15,null,null,null,6489366.6666666642,"N",null,4594471.5999999931]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",7426699.9999999972,1,2500,"Ondulado",15,null,null,null,7426699.9999999972,"N",null,5258103.5999999931]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",4859606.6666666651,1,500,"Ondulado",25,null,null,null,4859606.6666666651,"N",null,3440601.5199999958]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6690503.3333333312,1,1000,"Ondulado",25,null,null,null,6690503.3333333312,"N",null,4736876.3599999938]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",9123109.9999999963,1,1500,"Ondulado",25,null,null,null,9123109.9999999963,"N",null,6459161.8799999915]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",10331109.999999996,1,2500,"Ondulado",25,null,null,null,10331109.999999996,"N",null,7314425.8799999896]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",4859606.6666666651,1,500,"Ondulado",15,null,null,null,4859606.6666666651,"N",null,3440601.5199999958]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6690503.3333333312,1,1000,"Ondulado",15,null,null,null,6690503.3333333312,"N",null,4736876.3599999938]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",9123109.9999999963,1,1500,"Ondulado",15,null,null,null,9123109.9999999963,"N",null,6459161.8799999915]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",10331109.999999996,1,2500,"Ondulado",15,null,null,null,10331109.999999996,"N",null,7314425.8799999896]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",4859606.6666666651,1,500,"Ondulado",25,null,null,null,{"$f":"+I387*H387","v":4859606.6666666651},"N",null,3440601.5199999958]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6690503.3333333312,1,1000,"Ondulado",25,null,null,null,6690503.3333333312,"N",null,4736876.3599999938]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",9123109.9999999963,1,1500,"Ondulado",25,null,null,null,9123109.9999999963,"N",null,6459161.8799999915]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",10331109.999999996,1,2500,"Ondulado",25,null,null,null,10331109.999999996,"N",null,7314425.8799999896]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",4859606.6666666651,1,500,"Ondulado",15,null,null,null,4859606.6666666651,"N",null,3440601.5199999958]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6690503.3333333312,1,1000,"Ondulado",15,null,null,null,6690503.3333333312,"N",null,4736876.3599999938]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",9123109.9999999963,1,1500,"Ondulado",15,null,null,null,9123109.9999999963,"N",null,6459161.8799999915]
["TMC 4G","Red Energia","Terreno Ondulado - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",10331109.999999996,1,2500,"Ondulado",15,null,null,null,10331109.999999996,"N",null,7314425.8799999896]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1749026.3960279999,1,500,"Ondulado",25,null,null,null,1749026.3960279999,"N",null,{"$f":"+$T$275*H395*12/5","v":621254.17586914555}]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2249266.3960279999,1,1000,"Ondulado",25,null,null,null,2249266.3960279999,"N",null,{"$f":"+$T$275*H396*12/5","v":798939.42386914557}]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",2590653.0626946664,1,1500,"Ondulado",25,null,null,null,2590653.0626946664,"N",null,920199.96786914545]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",2590653.0626946664,1,2500,"Ondulado",25,null,null,null,2590653.0626946664,"N",null,920199.96786914545]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1683681.5350666668,1,500,"Ondulado",15,null,null,null,1683681.5350666668,"N",null,598043.68125567993]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2183921.5350666665,1,1000,"Ondulado",15,null,null,null,2183921.5350666665,"N",null,775728.92925567995]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",2525308.2017333335,1,1500,"Ondulado",15,null,null,null,2525308.2017333335,"N",null,896989.47325568018]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",2525308.2017333335,1,2500,"Ondulado",15,null,null,null,2525308.2017333335,"N",null,896989.47325568018]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1940242.3960279999,1,500,"Ondulado",25,null,null,null,1940242.3960279999,"N",null,689174.09906914551]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2590554.3960279999,1,1000,"Ondulado",25,null,null,null,2590554.3960279999,"N",null,920164.92146914569]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",3034357.0626946664,1,1500,"Ondulado",25,null,null,null,3034357.0626946664,"N",null,1077803.6286691453]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",3034357.0626946664,1,2500,"Ondulado",25,null,null,null,3034357.0626946664,"N",null,1077803.6286691453]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1874897.5350666668,1,500,"Ondulado",15,null,null,null,{"$f":"+I407*H407","v":1874897.5350666668},"N",null,665963.60445568]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2525209.5350666665,1,1000,"Ondulado",15,null,null,null,2525209.5350666665,"N",null,896954.42685567995]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",2969012.2017333335,1,1500,"Ondulado",15,null,null,null,2969012.2017333335,"N",null,1054593.1340556801]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",2969012.2017333335,1,2500,"Ondulado",15,null,null,null,2969012.2017333335,"N",null,1054593.1340556801]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1940242.3960279999,1,500,"Ondulado",25,null,null,null,1940242.3960279999,"N",null,689174.09906914551]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2590554.3960279999,1,1000,"Ondulado",25,null,null,null,2590554.3960279999,"N",null,920164.92146914569]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",3034357.0626946664,1,1500,"Ondulado",25,null,null,null,3034357.0626946664,"N",null,1077803.6286691453]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",3034357.0626946664,1,2500,"Ondulado",25,null,null,null,3034357.0626946664,"N",null,1077803.6286691453]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1874897.5350666668,1,500,"Ondulado",15,null,null,null,{"$f":"+I415*H415","v":1874897.5350666668},"N",null,665963.60445568]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2525209.5350666665,1,1000,"Ondulado",15,null,null,null,2525209.5350666665,"N",null,896954.42685567995]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",2969012.2017333335,1,1500,"Ondulado",15,null,null,null,2969012.2017333335,"N",null,1054593.1340556801]
["TMC 4G","Red Energia","Terreno Ondulado - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",2969012.2017333335,1,2500,"Ondulado",15,null,null,null,2969012.2017333335,"N",null,1054593.1340556801]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",2218858.4419999998,1,500,"Ondulado",25,null,null,null,2218858.4419999998,"N",null,788138.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2768858.4419999998,1,1000,"Ondulado",25,null,null,null,2768858.4419999998,"N",null,983498.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3268858.4419999998,1,1500,"Ondulado",25,null,null,null,3268858.4419999998,"N",null,1161098.5185983998]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5268858.4419999998,1,2500,"Ondulado",25,null,null,null,5268858.4419999998,"N",null,1871498.5185983996]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",2059626.4961999999,1,500,"Ondulado",15,null,null,null,2059626.4961999999,"N",null,731579.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2609626.4961999999,1,1000,"Ondulado",15,null,null,null,2609626.4961999999,"N",null,926939.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3109626.4961999999,1,1500,"Ondulado",15,null,null,null,3109626.4961999999,"N",null,1104539.33145024]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5109626.4961999999,1,2500,"Ondulado",15,null,null,null,5109626.4961999999,"N",null,1814939.33145024]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",2218858.4419999998,1,500,"Ondulado",25,null,null,null,2218858.4419999998,"N",null,788138.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2768858.4419999998,1,1000,"Ondulado",25,null,null,null,2768858.4419999998,"N",null,983498.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",3268858.4419999998,1,1500,"Ondulado",25,null,null,null,3268858.4419999998,"N",null,1161098.5185983998]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5268858.4419999998,1,2500,"Ondulado",25,null,null,null,5268858.4419999998,"N",null,1871498.5185983996]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",2059626.4961999999,1,500,"Ondulado",15,null,null,null,2059626.4961999999,"N",null,731579.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2609626.4961999999,1,1000,"Ondulado",15,null,null,null,2609626.4961999999,"N",null,926939.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",3109626.4961999999,1,1500,"Ondulado",15,null,null,null,3109626.4961999999,"N",null,1104539.33145024]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5109626.4961999999,1,2500,"Ondulado",15,null,null,null,5109626.4961999999,"N",null,1814939.33145024]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",2218858.4419999998,1,500,"Ondulado",25,null,null,null,{"$f":"+I435*H435","v":2218858.4419999998},"N",null,788138.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2768858.4419999998,1,1000,"Ondulado",25,null,null,null,2768858.4419999998,"N",null,983498.51859839982]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",3268858.4419999998,1,1500,"Ondulado",25,null,null,null,3268858.4419999998,"N",null,1161098.5185983998]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5268858.4419999998,1,2500,"Ondulado",25,null,null,null,5268858.4419999998,"N",null,1871498.5185983996]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",2059626.4961999999,1,500,"Ondulado",15,null,null,null,2059626.4961999999,"N",null,731579.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2609626.4961999999,1,1000,"Ondulado",15,null,null,null,2609626.4961999999,"N",null,926939.33145023999]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",3109626.4961999999,1,1500,"Ondulado",15,null,null,null,3109626.4961999999,"N",null,1104539.33145024]
["TMC 4G","Red Energia","Terreno Ondulado - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5109626.4961999999,1,2500,"Ondulado",15,null,null,null,5109626.4961999999,"N",null,1814939.33145024]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",7360575.8313333327,1,500,"Plano",25,null,null,null,7360575.8313333327,"N",null,{"$f":"+$T$155*H443*12/5*0.85","v":11501930.217074718},0.76600000000000001]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",15665085.4956,1,1000,"Plano",25,null,null,null,15665085.4956,"N",null,{"$f":"+$T$155*H444*12/5*0.85","v":24478889.198844388}]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",24590377.327733334,1,1500,"Plano",25,null,null,null,24590377.327733334,"N",null,38425907.227409221]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",36358152.9912,1,2500,"Plano",25,null,null,null,36358152.9912,"N",null,56814704.190168768]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",7360575.8313333327,1,500,"Plano",15,null,null,null,7360575.8313333327,"N",null,11501930.217074718]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",15665085.4956,1,1000,"Plano",15,null,null,null,15665085.4956,"N",null,24478889.198844388]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",24590377.327733334,1,1500,"Plano",15,null,null,null,24590377.327733334,"N",null,38425907.227409221]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",36358152.9912,1,2500,"Plano",15,null,null,null,36358152.9912,"N",null,56814704.190168768]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",8424308.1975999996,1,500,"Plano",25,null,null,null,8424308.1975999996,"N",null,13164160.961897664]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",17389033.26186667,1,1000,"Plano",25,null,null,null,17389033.26186667,"N",null,27172798.936323337]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",26987397.460266668,1,1500,"Plano",25,null,null,null,26987397.460266668,"N",null,42171586.767311104]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",38977684.289999999,1,2500,"Plano",25,null,null,null,38977684.289999999,"N",null,60908088.578925602]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",8424308.1975999996,1,500,"Plano",15,null,null,null,8424308.1975999996,"N",null,13164160.961897664]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",17389033.26186667,1,1000,"Plano",15,null,null,null,17389033.26186667,"N",null,27172798.936323337]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",26987397.460266668,1,1500,"Plano",15,null,null,null,26987397.460266668,"N",null,42171586.767311104]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",38977684.289999999,1,2500,"Plano",15,null,null,null,38977684.289999999,"N",null,60908088.578925602]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",8424308.1975999996,1,500,"Plano",25,null,null,null,{"$f":"+I459*H459","v":8424308.1975999996},"N",null,13164160.961897664]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",17389033.26186667,1,1000,"Plano",25,null,null,null,17389033.26186667,"N",null,27172798.936323337]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",26987397.460266668,1,1500,"Plano",25,null,null,null,26987397.460266668,"N",null,42171586.767311104]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",38977684.289999999,1,2500,"Plano",25,null,null,null,38977684.289999999,"N",null,60908088.578925602]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",8424308.1975999996,1,500,"Plano",15,null,null,null,8424308.1975999996,"N",null,13164160.961897664]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",17389033.26186667,1,1000,"Plano",15,null,null,null,17389033.26186667,"N",null,27172798.936323337]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",26987397.460266668,1,1500,"Plano",15,null,null,null,26987397.460266668,"N",null,42171586.767311104]
["TMC 4G","Red Energia","Terreno Plano - Soportes (Postes)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",38977684.289999999,1,2500,"Plano",15,null,null,null,38977684.289999999,"N",null,60908088.578925602]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",9319531.0633333344,1,500,"Plano",25,null,null,null,9319531.0633333344,"N",null,14563072.020807201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",18035709.063333333,1,1000,"Plano",25,null,null,null,18035709.063333333,"N",null,28183320.410727195]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",26053039.73,1,1500,"Plano",25,null,null,null,26053039.73,"N",null,40711522.003687195]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",39083959.729999997,1,2500,"Plano",25,null,null,null,39083959.729999997,"N",null,61074158.832487188]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",8913404.3966666665,1,500,"Plano",15,null,null,null,8913404.3966666665,"N",null,13928442.2464072]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",17223455.73,1,1000,"Plano",15,null,null,null,17223455.73,"N",null,26914060.8619272]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",24834659.73,1,1500,"Plano",15,null,null,null,24834659.73,"N",null,38807632.680487201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",37053326.396666668,1,2500,"Plano",15,null,null,null,37053326.396666668,"N",null,57901009.960487194]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",10160752.263333334,1,500,"Plano",25,null,null,null,10160752.263333334,"N",null,15877597.916775201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",19537145.66333333,1,1000,"Plano",25,null,null,null,19537145.66333333,"N",null,30529525.299351193]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",28005037.530000001,1,1500,"Plano",25,null,null,null,28005037.530000001,"N",null,43761791.845879212]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",41035957.530000001,1,2500,"Plano",25,null,null,null,41035957.530000001,"N",null,64124428.674679205]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",9754625.5966666657,1,500,"Plano",15,null,null,null,9754625.5966666657,"N",null,15242968.142375197]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",18724892.329999998,1,1000,"Plano",15,null,null,null,18724892.329999998,"N",null,29260265.750551201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",26786657.530000001,1,1500,"Plano",15,null,null,null,26786657.530000001,"N",null,41857902.522679202]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",39005324.196666665,1,2500,"Plano",15,null,null,null,39005324.196666665,"N",null,60951279.802679181]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",10160752.263333334,1,500,"Plano",25,null,null,null,{"$f":"+I483*H483","v":10160752.263333334},"N",null,15877597.916775201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",19537145.66333333,1,1000,"Plano",25,null,null,null,19537145.66333333,"N",null,30529525.299351193]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",28005037.530000001,1,1500,"Plano",25,null,null,null,28005037.530000001,"N",null,43761791.845879212]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",41035957.530000001,1,2500,"Plano",25,null,null,null,41035957.530000001,"N",null,64124428.674679205]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",9754625.5966666657,1,500,"Plano",15,null,null,null,9754625.5966666657,"N",null,15242968.142375197]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",18724892.329999998,1,1000,"Plano",15,null,null,null,18724892.329999998,"N",null,29260265.750551201]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",26786657.530000001,1,1500,"Plano",15,null,null,null,26786657.530000001,"N",null,41857902.522679202]
["TMC 4G","Red Energia","Terreno Plano - Cableados Mt","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",39005324.196666665,1,2500,"Plano",15,null,null,null,39005324.196666665,"N",null,60951279.802679181]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5626782.5633333335,1,500,"Plano",25,null,null,null,5626782.5633333335,"N",null,8792635.5047672]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",11004726.563333333,1,1000,"Plano",25,null,null,null,11004726.563333333,"N",null,17196425.916927196]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",15336010.979999999,1,1500,"Plano",25,null,null,null,15336010.979999999,"N",null,23964664.197787203]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",20988136.23,1,2500,"Plano",25,null,null,null,20988136.23,"N",null,32796901.198447198]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5626782.5633333335,1,500,"Plano",15,null,null,null,5626782.5633333335,"N",null,8792635.5047672]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",11004726.563333333,1,1000,"Plano",15,null,null,null,11004726.563333333,"N",null,17196425.916927196]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",15336010.979999999,1,1500,"Plano",15,null,null,null,15336010.979999999,"N",null,23964664.197787203]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",20988136.23,1,2500,"Plano",15,null,null,null,20988136.23,"N",null,32796901.198447198]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6468003.7633333327,1,500,"Plano",25,null,null,null,6468003.7633333327,"N",null,10107161.400735199]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",12506163.163333332,1,1000,"Plano",25,null,null,null,12506163.163333332,"N",null,19542630.805551197]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",17288008.779999997,1,1500,"Plano",25,null,null,null,17288008.779999997,"N",null,27014934.039979193]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",22940134.030000001,1,2500,"Plano",25,null,null,null,22940134.030000001,"N",null,35847171.040639207]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6468003.7633333327,1,500,"Plano",15,null,null,null,{"$f":"+I503*H503","v":6468003.7633333327},"N",null,10107161.400735199]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",12506163.163333332,1,1000,"Plano",15,null,null,null,12506163.163333332,"N",null,19542630.805551197]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",17288008.779999997,1,1500,"Plano",15,null,null,null,17288008.779999997,"N",null,27014934.039979193]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",22940134.030000001,1,2500,"Plano",15,null,null,null,22940134.030000001,"N",null,35847171.040639207]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6468003.7633333327,1,500,"Plano",25,null,null,null,6468003.7633333327,"N",null,10107161.400735199]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",12506163.163333332,1,1000,"Plano",25,null,null,null,12506163.163333332,"N",null,{"$f":"+$T$155*H508*12/5*0.85","v":19542630.805551197}]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",17288008.779999997,1,1500,"Plano",25,null,null,null,17288008.779999997,"N",null,27014934.039979193]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",22940134.030000001,1,2500,"Plano",25,null,null,null,22940134.030000001,"N",null,35847171.040639207]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6468003.7633333327,1,500,"Plano",15,null,null,null,{"$f":"+I511*H511","v":6468003.7633333327},"N",null,10107161.400735199]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",12506163.163333332,1,1000,"Plano",15,null,null,null,12506163.163333332,"N",null,19542630.805551197]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",17288008.779999997,1,1500,"Plano",15,null,null,null,17288008.779999997,"N",null,27014934.039979193]
["TMC 4G","Red Energia","Terreno Plano - Paso Cruceta Lar","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",22940134.030000001,1,2500,"Plano",15,null,null,null,22940134.030000001,"N",null,35847171.040639207]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6691474.0949999997,1,500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",6691474.0949999997,1,1000,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6691474.0949999997,1,1500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6691474.0949999997,1,2500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",6257369.0949999997,1,500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",6257369.0949999997,1,1000,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",6257369.0949999997,1,1500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6257369.0949999997,1,2500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6691474.0949999997,1,500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6691474.0949999997,1,1000,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",6691474.0949999997,1,1500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",6691474.0949999997,1,2500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6257369.0949999997,1,500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",6257369.0949999997,1,1000,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",6257369.0949999997,1,1500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",6257369.0949999997,1,2500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6691474.0949999997,1,500,"Plano",25,null,null,null,{"$f":"+I531*H531","v":6691474.0949999997},"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6691474.0949999997,1,1000,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",6691474.0949999997,1,1500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",6691474.0949999997,1,2500,"Plano",25,null,null,null,6691474.0949999997,"N",null,10456365.0798108]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6257369.0949999997,1,500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",6257369.0949999997,1,1000,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",6257369.0949999997,1,1500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Transformador Kw","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",6257369.0949999997,1,2500,"Plano",15,null,null,null,6257369.0949999997,"N",null,9778015.242610801]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5165519.7299999995,1,500,"Plano",25,null,null,null,5165519.7299999995,"N",null,8071847.7508872002]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",9136071.0633333325,1,1000,"Plano",25,null,null,null,9136071.0633333325,"N",null,14276390.086407198]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",12407775.063333333,1,1500,"Plano",25,null,null,null,12407775.063333333,"N",null,19388885.624967199]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",16480775.063333333,1,2500,"Plano",25,null,null,null,16480775.063333333,"N",null,25753518.344967201]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",5165519.7299999995,1,500,"Plano",15,null,null,null,5165519.7299999995,"N",null,8071847.7508872002]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",9136071.0633333325,1,1000,"Plano",15,null,null,null,9136071.0633333325,"N",null,14276390.086407198]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",12407775.063333333,1,1500,"Plano",15,null,null,null,12407775.063333333,"N",null,19388885.624967199]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",16480775.063333333,1,2500,"Plano",15,null,null,null,16480775.063333333,"N",null,25753518.344967201]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6006740.9299999997,1,500,"Plano",25,null,null,null,6006740.9299999997,"N",null,9386373.6468552016]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",10637507.663333334,1,1000,"Plano",25,null,null,null,10637507.663333334,"N",null,16622594.975031197]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",14359772.863333335,1,1500,"Plano",25,null,null,null,14359772.863333335,"N",null,22439155.4671592]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",18432772.863333333,1,2500,"Plano",25,null,null,null,18432772.863333333,"N",null,28803788.187159203]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",6006740.9299999997,1,500,"Plano",15,null,null,null,6006740.9299999997,"N",null,9386373.6468552016]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",10637507.663333334,1,1000,"Plano",15,null,null,null,10637507.663333334,"N",null,16622594.975031197]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",14359772.863333335,1,1500,"Plano",15,null,null,null,14359772.863333335,"N",null,22439155.4671592]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",18432772.863333333,1,2500,"Plano",15,null,null,null,18432772.863333333,"N",null,28803788.187159203]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6006740.9299999997,1,500,"Plano",25,null,null,null,{"$f":"+I555*H555","v":6006740.9299999997},"N",null,9386373.6468552016]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",10637507.663333334,1,1000,"Plano",25,null,null,null,10637507.663333334,"N",null,16622594.975031197]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",14359772.863333335,1,1500,"Plano",25,null,null,null,14359772.863333335,"N",null,22439155.4671592]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",18432772.863333333,1,2500,"Plano",25,null,null,null,18432772.863333333,"N",null,28803788.187159203]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",6006740.9299999997,1,500,"Plano",15,null,null,null,6006740.9299999997,"N",null,9386373.6468552016]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",10637507.663333334,1,1000,"Plano",15,null,null,null,10637507.663333334,"N",null,16622594.975031197]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",14359772.863333335,1,1500,"Plano",15,null,null,null,14359772.863333335,"N",null,22439155.4671592]
["TMC 4G","Red Energia","Terreno Plano - Parrarayos, Malla","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",18432772.863333333,1,2500,"Plano",15,null,null,null,18432772.863333333,"N",null,28803788.187159203]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",778384.16280000005,1,500,"Plano",25,null,null,null,778384.16280000005,"N",null,{"$f":"+$T$275*H563*12/5*0.85","v":235009.74643257601},0.14799999999999999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",778384.16280000005,1,1000,"Plano",25,null,null,null,778384.16280000005,"N",null,{"$f":"+$T$275*H564*12/5*0.85","v":235009.74643257601}]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",778384.16280000005,1,1500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",778384.16280000005,1,2500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",619854.30249999999,1,500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",619854.30249999999,1,1000,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",619854.30249999999,1,1500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",619854.30249999999,1,2500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",778384.16280000005,1,500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",778384.16280000005,1,1000,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",778384.16280000005,1,1500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",778384.16280000005,1,2500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",619854.30249999999,1,500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",619854.30249999999,1,1000,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",619854.30249999999,1,1500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",619854.30249999999,1,2500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",778384.16280000005,1,500,"Plano",25,null,null,null,{"$f":"+I579*H579","v":778384.16280000005},"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",778384.16280000005,1,1000,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",778384.16280000005,1,1500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",778384.16280000005,1,2500,"Plano",25,null,null,null,778384.16280000005,"N",null,235009.74643257601]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",619854.30249999999,1,500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",619854.30249999999,1,1000,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",619854.30249999999,1,1500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Tramite conexión  y permisos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",619854.30249999999,1,2500,"Plano",15,null,null,null,619854.30249999999,"N",null,187146.41101079999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",25,null,null,null,3086218.5474999999,"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",25,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",25,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",25,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",15,null,null,null,3086218.5474999999,"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",15,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",15,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",15,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",25,null,null,null,3086218.5474999999,"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",25,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",25,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",25,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",15,null,null,null,{"$f":"+I599*H599","v":3086218.5474999999},"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",15,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",15,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",15,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",25,null,null,null,3086218.5474999999,"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",25,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",25,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",25,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",3086218.5474999999,1,500,"Plano",15,null,null,null,{"$f":"+I607*H607","v":3086218.5474999999},"N",null,931791.10386119981]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3715543.5474999999,1,1000,"Plano",15,null,null,null,3715543.5474999999,"N",null,1121796.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",4715543.5475000003,1,1500,"Plano",15,null,null,null,4715543.5475000003,"N",null,1423716.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Asesoria y Certificacion RETIE","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5715543.5475000003,1,2500,"Plano",15,null,null,null,5715543.5475000003,"N",null,1725636.9078611999]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",460286.44419999997,1,500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",460286.44419999997,1,1000,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",460286.44419999997,1,1500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",460286.44419999997,1,2500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",501741.18971399998,1,500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",501741.18971399998,1,1000,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",501741.18971399998,1,1500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",501741.18971399998,1,2500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",460286.44419999997,1,500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",460286.44419999997,1,1000,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",460286.44419999997,1,1500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",460286.44419999997,1,2500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",501741.18971399998,1,500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",501741.18971399998,1,1000,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",501741.18971399998,1,1500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",501741.18971399998,1,2500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",460286.44419999997,1,500,"Plano",25,null,null,null,{"$f":"+I627*H627","v":460286.44419999997},"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",460286.44419999997,1,1000,"Plano",25,null,null,null,460286.44419999997,"N",null,{"$f":"+$T$275*H628*12/5*0.85","v":138969.68323286399}]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",460286.44419999997,1,1500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",460286.44419999997,1,2500,"Plano",25,null,null,null,460286.44419999997,"N",null,138969.68323286399]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",501741.18971399998,1,500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",501741.18971399998,1,1000,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",501741.18971399998,1,1500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Derechos de conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",501741.18971399998,1,2500,"Plano",15,null,null,null,501741.18971399998,"N",null,151485.69999845084]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",494190,1,500,"Plano",25,null,null,null,494190,"N",null,{"$f":"+$T$347*H635*12*0.85","v":136099.92600000001},2.7E-2]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2048711.6666666667,1,1000,"Plano",25,null,null,null,2048711.6666666667,"N",null,{"$f":"+$T$347*H636*12*0.85","v":564215.19300000009}]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3480068.3333333335,1,1500,"Plano",25,null,null,null,3480068.3333333335,"N",null,958410.81900000013]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",4646735,1,2500,"Plano",25,null,null,null,4646735,"N",null,1279710.8190000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",494190,1,500,"Plano",15,null,null,null,494190,"N",null,136099.92600000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2048711.6666666667,1,1000,"Plano",15,null,null,null,2048711.6666666667,"N",null,564215.19300000009]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3480068.3333333335,1,1500,"Plano",15,null,null,null,3480068.3333333335,"N",null,958410.81900000013]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",4646735,1,2500,"Plano",15,null,null,null,4646735,"N",null,1279710.8190000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1442447,1,500,"Plano",25,null,null,null,1442447,"N",null,397249.90380000003]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",4179991.8333333335,1,1000,"Plano",25,null,null,null,4179991.8333333335,"N",null,1151169.7509000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7157422.166666667,1,1500,"Plano",25,null,null,null,7157422.166666667,"N",null,1971154.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",10590755.5,1,2500,"Plano",25,null,null,null,10590755.5,"N",null,2916694.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1442447,1,500,"Plano",15,null,null,null,1442447,"N",null,397249.90380000003]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",4179991.8333333335,1,1000,"Plano",15,null,null,null,4179991.8333333335,"N",null,1151169.7509000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7157422.166666667,1,1500,"Plano",15,null,null,null,7157422.166666667,"N",null,1971154.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",10590755.5,1,2500,"Plano",15,null,null,null,10590755.5,"N",null,2916694.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1442447,1,500,"Plano",25,null,null,null,{"$f":"+I651*H651","v":1442447},"N",null,397249.90380000003]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",4179991.8333333335,1,1000,"Plano",25,null,null,null,4179991.8333333335,"N",null,1151169.7509000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7157422.166666667,1,1500,"Plano",25,null,null,null,7157422.166666667,"N",null,1971154.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",10590755.5,1,2500,"Plano",25,null,null,null,10590755.5,"N",null,2916694.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1442447,1,500,"Plano",15,null,null,null,1442447,"N",null,397249.90380000003]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",4179991.8333333335,1,1000,"Plano",15,null,null,null,4179991.8333333335,"N",null,1151169.7509000001]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7157422.166666667,1,1500,"Plano",15,null,null,null,7157422.166666667,"N",null,1971154.0647]
["TMC 4G","Red Energia","Terreno Plano - Servidumbres","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",10590755.5,1,2500,"Plano",15,null,null,null,10590755.5,"N",null,2916694.0647]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1079896.6666666656,1,500,"Plano",25,null,null,null,1079896.6666666656,"N",null,{"$f":"+$T$371*H659*12*0.85","v":649881.81399999862},{"$f":"1-SUM(T443:T658)","v":5.8999999999999941E-2}]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2198098.3333333316,1,1000,"Plano",25,null,null,null,2198098.3333333316,"N",null,{"$f":"+$T$371*H660*12*0.85","v":1322815.5769999977}]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",5047161.6666666642,1,1500,"Plano",25,null,null,null,5047161.6666666642,"N",null,3037381.8909999952]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6317828.3333333312,1,2500,"Plano",25,null,null,null,6317828.3333333312,"N",null,3802069.0909999949]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1079896.6666666656,1,500,"Plano",15,null,null,null,1079896.6666666656,"N",null,649881.81399999862]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2198098.3333333316,1,1000,"Plano",15,null,null,null,2198098.3333333316,"N",null,1322815.5769999977]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",5047161.6666666642,1,1500,"Plano",15,null,null,null,5047161.6666666642,"N",null,3037381.8909999952]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",6317828.3333333312,1,2500,"Plano",15,null,null,null,6317828.3333333312,"N",null,3802069.0909999949]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1674532.3333333319,1,500,"Plano",25,null,null,null,1674532.3333333319,"N",null,1007733.558199998]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3046994.4999999977,1,1000,"Plano",25,null,null,null,3046994.4999999977,"N",null,1833681.2900999968]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7069576.8333333312,1,1500,"Plano",25,null,null,null,7069576.8333333312,"N",null,4254471.3382999944]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",8006910.1666666642,1,2500,"Plano",25,null,null,null,8006910.1666666642,"N",null,4818558.5382999936]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1674532.3333333319,1,500,"Plano",15,null,null,null,1674532.3333333319,"N",null,1007733.558199998]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",3046994.4999999977,1,1000,"Plano",15,null,null,null,3046994.4999999977,"N",null,1833681.2900999968]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",7069576.8333333312,1,1500,"Plano",15,null,null,null,7069576.8333333312,"N",null,4254471.3382999944]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",8006910.1666666642,1,2500,"Plano",15,null,null,null,8006910.1666666642,"N",null,4818558.5382999936]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1674532.3333333319,1,500,"Plano",25,null,null,null,{"$f":"+I675*H675","v":1674532.3333333319},"N",null,1007733.558199998]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3046994.4999999977,1,1000,"Plano",25,null,null,null,3046994.4999999977,"N",null,1833681.2900999968]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7069576.8333333312,1,1500,"Plano",25,null,null,null,7069576.8333333312,"N",null,4254471.3382999944]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",8006910.1666666642,1,2500,"Plano",25,null,null,null,8006910.1666666642,"N",null,4818558.5382999936]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1674532.3333333319,1,500,"Plano",15,null,null,null,1674532.3333333319,"N",null,1007733.558199998]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",3046994.4999999977,1,1000,"Plano",15,null,null,null,3046994.4999999977,"N",null,1833681.2900999968]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",7069576.8333333312,1,1500,"Plano",15,null,null,null,7069576.8333333312,"N",null,4254471.3382999944]
["TMC 4G","Red Energia","Terreno Plano - Trasiegos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",8006910.1666666642,1,2500,"Plano",15,null,null,null,8006910.1666666642,"N",null,4818558.5382999936]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1653418.3960279999,1,500,"Plano",25,null,null,null,1653418.3960279999,"N",null,{"$f":"+$T$275*H683*12/5*0.85","v":499200.08212877379}]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2078622.3960279999,1,1000,"Plano",25,null,null,null,2078622.3960279999,"N",null,{"$f":"+$T$275*H684*12/5*0.85","v":627577.67380877363}]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",2368801.0626946664,1,1500,"Plano",25,null,null,null,2368801.0626946664,"N",null,715188.4168487736]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",2368801.0626946664,1,2500,"Plano",25,null,null,null,2368801.0626946664,"N",null,715188.4168487736]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",1588073.5350666668,1,500,"Plano",15,null,null,null,1588073.5350666668,"N",null,479471.16170732799]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2013277.5350666668,1,1000,"Plano",15,null,null,null,2013277.5350666668,"N",null,607848.753387328]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",2303456.2017333335,1,1500,"Plano",15,null,null,null,2303456.2017333335,"N",null,695459.49642732798]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",2303456.2017333335,1,2500,"Plano",15,null,null,null,2303456.2017333335,"N",null,695459.49642732798]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1815951.9960279998,1,500,"Plano",25,null,null,null,1815951.9960279998,"N",null,548272.22664077359]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2368717.1960279997,1,1000,"Plano",25,null,null,null,2368717.1960279997,"N",null,715163.09582477354]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",2745949.4626946668,1,1500,"Plano",25,null,null,null,2745949.4626946668,"N",null,829057.06177677365]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",2745949.4626946668,1,2500,"Plano",25,null,null,null,2745949.4626946668,"N",null,829057.06177677365]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",1750607.1350666666,1,500,"Plano",15,null,null,null,{"$f":"+I695*H695","v":1750607.1350666666},"N",null,528543.30621932796]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2303372.3350666668,1,1000,"Plano",15,null,null,null,2303372.3350666668,"N",null,695434.17540332803]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",2680604.6017333334,1,1500,"Plano",15,null,null,null,2680604.6017333334,"N",null,809328.14135532803]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",2680604.6017333334,1,2500,"Plano",15,null,null,null,2680604.6017333334,"N",null,809328.14135532803]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1815951.9960279998,1,500,"Plano",25,null,null,null,1815951.9960279998,"N",null,548272.22664077359]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2368717.1960279997,1,1000,"Plano",25,null,null,null,2368717.1960279997,"N",null,715163.09582477354]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",2745949.4626946668,1,1500,"Plano",25,null,null,null,2745949.4626946668,"N",null,829057.06177677365]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",2745949.4626946668,1,2500,"Plano",25,null,null,null,2745949.4626946668,"N",null,829057.06177677365]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",1750607.1350666666,1,500,"Plano",15,null,null,null,{"$f":"+I703*H703","v":1750607.1350666666},"N",null,528543.30621932796]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2303372.3350666668,1,1000,"Plano",15,null,null,null,2303372.3350666668,"N",null,695434.17540332803]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",2680604.6017333334,1,1500,"Plano",15,null,null,null,2680604.6017333334,"N",null,809328.14135532803]
["TMC 4G","Red Energia","Terreno Plano - Maniobras en conexión","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",2680604.6017333334,1,2500,"Plano",15,null,null,null,2680604.6017333334,"N",null,809328.14135532803]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",2218858.4419999998,1,500,"Plano",25,null,null,null,2218858.4419999998,"N",null,669917.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2768858.4419999998,1,1000,"Plano",25,null,null,null,2768858.4419999998,"N",null,835973.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3268858.4419999998,1,1500,"Plano",25,null,null,null,3268858.4419999998,"N",null,986933.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5268858.4419999998,1,2500,"Plano",25,null,null,null,5268858.4419999998,"N",null,1590773.7408086397]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"CAPEX","Unitario",2059626.4961999999,1,500,"Plano",15,null,null,null,2059626.4961999999,"N",null,621842.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"CAPEX","Unitario",2609626.4961999999,1,1000,"Plano",15,null,null,null,2609626.4961999999,"N",null,787898.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"CAPEX","Unitario",3109626.4961999999,1,1500,"Plano",15,null,null,null,3109626.4961999999,"N",null,938858.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"CAPEX","Unitario",5109626.4961999999,1,2500,"Plano",15,null,null,null,5109626.4961999999,"N",null,1542698.4317327039]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",2218858.4419999998,1,500,"Plano",25,null,null,null,2218858.4419999998,"N",null,669917.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2768858.4419999998,1,1000,"Plano",25,null,null,null,2768858.4419999998,"N",null,835973.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",3268858.4419999998,1,1500,"Plano",25,null,null,null,3268858.4419999998,"N",null,986933.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5268858.4419999998,1,2500,"Plano",25,null,null,null,5268858.4419999998,"N",null,1590773.7408086397]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"CAPEX","Unitario",2059626.4961999999,1,500,"Plano",15,null,null,null,2059626.4961999999,"N",null,621842.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"CAPEX","Unitario",2609626.4961999999,1,1000,"Plano",15,null,null,null,2609626.4961999999,"N",null,787898.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"CAPEX","Unitario",3109626.4961999999,1,1500,"Plano",15,null,null,null,3109626.4961999999,"N",null,938858.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"CAPEX","Unitario",5109626.4961999999,1,2500,"Plano",15,null,null,null,5109626.4961999999,"N",null,1542698.4317327039]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",2218858.4419999998,1,500,"Plano",25,null,null,null,{"$f":"+I723*H723","v":2218858.4419999998},"N",null,669917.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2768858.4419999998,1,1000,"Plano",25,null,null,null,2768858.4419999998,"N",null,835973.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",3268858.4419999998,1,1500,"Plano",25,null,null,null,3268858.4419999998,"N",null,986933.74080863979]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 25 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5268858.4419999998,1,2500,"Plano",25,null,null,null,5268858.4419999998,"N",null,1590773.7408086397]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"CAPEX","Unitario",2059626.4961999999,1,500,"Plano",15,null,null,null,2059626.4961999999,"N",null,621842.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"CAPEX","Unitario",2609626.4961999999,1,1000,"Plano",15,null,null,null,2609626.4961999999,"N",null,787898.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"CAPEX","Unitario",3109626.4961999999,1,1500,"Plano",15,null,null,null,3109626.4961999999,"N",null,938858.43173270393]
["TMC 4G","Red Energia","Terreno Plano - Diseños, planos","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"CAPEX","Unitario",5109626.4961999999,1,2500,"Plano",15,null,null,null,5109626.4961999999,"N",null,1542698.4317327039]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Mensual",2160000,1,500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Mensual",2160000,1,1000,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Mensual",2160000,1,1500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Mensual",2160000,1,2500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Mensual",2160000,1,500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Mensual",2160000,1,1000,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Mensual",2160000,1,1500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Mensual",2160000,1,2500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",2,"OPEX","Mensual",2160000,1,500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",2,"OPEX","Mensual",2160000,1,1000,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",2,"OPEX","Mensual",2160000,1,1500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",2,"OPEX","Mensual",2160000,1,2500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"OPEX","Mensual",2160000,1,500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"OPEX","Mensual",2160000,1,1000,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"OPEX","Mensual",2160000,1,1500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"OPEX","Mensual",2160000,1,2500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",3,"OPEX","Mensual",2160000,1,500,null,25,null,null,null,{"$f":"+I747*H747","v":2160000},"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",3,"OPEX","Mensual",2160000,1,1000,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",3,"OPEX","Mensual",2160000,1,1500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",3,"OPEX","Mensual",2160000,1,2500,null,25,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"OPEX","Mensual",2160000,1,500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"OPEX","Mensual",2160000,1,1000,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"OPEX","Mensual",2160000,1,1500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Valor Consumo De Energia Kwh","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"OPEX","Mensual",2160000,1,2500,null,15,null,null,null,2160000,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",3930901.52,1,500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",3930901.52,1,1000,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",3930901.52,1,1500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",3930901.52,1,2500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",3930901.52,1,500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",3930901.52,1,1000,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",3930901.52,1,1500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",3930901.52,1,2500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",2,"OPEX","Annual",3930901.52,1,500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",2,"OPEX","Annual",3930901.52,1,1000,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",2,"OPEX","Annual",3930901.52,1,1500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",2,"OPEX","Annual",3930901.52,1,2500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"OPEX","Annual",3930901.52,1,500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"OPEX","Annual",3930901.52,1,1000,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"OPEX","Annual",3930901.52,1,1500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"OPEX","Annual",3930901.52,1,2500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",3,"OPEX","Annual",3930901.52,1,500,null,25,null,null,null,{"$f":"+I771*H771","v":3930901.52},"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",3,"OPEX","Annual",3930901.52,1,1000,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",3,"OPEX","Annual",3930901.52,1,1500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",3,"OPEX","Annual",3930901.52,1,2500,null,25,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"OPEX","Annual",3930901.52,1,500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"OPEX","Annual",3930901.52,1,1000,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"OPEX","Annual",3930901.52,1,1500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Transformador","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"OPEX","Annual",3930901.52,1,2500,null,15,null,null,null,3930901.52,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",500000,1,500,null,25,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",500000,1,1000,null,25,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",500000,1,1500,null,25,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",500000,1,2500,null,25,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",500000,1,500,null,15,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",500000,1,1000,null,15,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",500000,1,1500,null,15,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",500000,1,2500,null,15,null,null,null,500000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",2,"OPEX","Annual",650000,1,500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",2,"OPEX","Annual",650000,1,1000,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",2,"OPEX","Annual",650000,1,1500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",2,"OPEX","Annual",650000,1,2500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"OPEX","Annual",650000,1,500,null,15,null,null,null,{"$f":"+I791*H791","v":650000},"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"OPEX","Annual",650000,1,1000,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"OPEX","Annual",650000,1,1500,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"OPEX","Annual",650000,1,2500,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",3,"OPEX","Annual",650000,1,500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",3,"OPEX","Annual",650000,1,1000,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",3,"OPEX","Annual",650000,1,1500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",3,"OPEX","Annual",650000,1,2500,null,25,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"OPEX","Annual",650000,1,500,null,15,null,null,null,{"$f":"+I799*H799","v":650000},"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"OPEX","Annual",650000,1,1000,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"OPEX","Annual",650000,1,1500,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Red De Mt (Postes, Lar)","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"OPEX","Annual",650000,1,2500,null,15,null,null,null,650000,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",3386694.78,1,500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",3386694.78,1,1000,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",3386694.78,1,1500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",3386694.78,1,2500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",3386694.78,1,500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",3386694.78,1,1000,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",3386694.78,1,1500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",3386694.78,1,2500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",2,"OPEX","Annual",3386694.78,1,500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",2,"OPEX","Annual",3386694.78,1,1000,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",2,"OPEX","Annual",3386694.78,1,1500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",2,"OPEX","Annual",3386694.78,1,2500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"OPEX","Annual",3386694.78,1,500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"OPEX","Annual",3386694.78,1,1000,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"OPEX","Annual",3386694.78,1,1500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"OPEX","Annual",3386694.78,1,2500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",3,"OPEX","Annual",3386694.78,1,500,null,25,null,null,null,{"$f":"+I819*H819","v":3386694.78},"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",3,"OPEX","Annual",3386694.78,1,1000,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",3,"OPEX","Annual",3386694.78,1,1500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",3,"OPEX","Annual",3386694.78,1,2500,null,25,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"OPEX","Annual",3386694.78,1,500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"OPEX","Annual",3386694.78,1,1000,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"OPEX","Annual",3386694.78,1,1500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Podas","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"OPEX","Annual",3386694.78,1,2500,null,15,null,null,null,3386694.78,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 25 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",301570.5,1,500,null,25,null,null,null,301570.5,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",786430.40000000014,1,1000,null,25,null,null,null,786430.40000000014,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 25 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",1479422.7,1,1500,null,25,null,null,null,1479422.7,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 25 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",2841216,1,2500,null,25,null,null,null,2841216,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 15 Kw Distancia mts (Ml ): Lr 500",1,"OPEX","Annual",301570.5,1,500,null,15,null,null,null,301570.5,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1000",1,"OPEX","Annual",786430.40000000014,1,1000,null,15,null,null,null,786430.40000000014,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 15 Kw Distancia mts (Ml ): Lr 1500",1,"OPEX","Annual",1479422.7,1,1500,null,15,null,null,null,1479422.7,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 1 15 Kw Distancia mts (Ml ): Lr 2500",1,"OPEX","Annual",2841216,1,2500,null,15,null,null,null,2841216,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",2,"OPEX","Annual",422198.70000000007,1,500,null,25,null,null,null,422198.70000000007,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",2,"OPEX","Annual",1011124.7999999999,1,1000,null,25,null,null,null,1011124.7999999999,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",2,"OPEX","Annual",1643803,1,1500,null,25,null,null,null,1643803,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",2,"OPEX","Annual",3409459.1999999997,1,2500,null,25,null,null,null,3409459.1999999997,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",2,"OPEX","Annual",422198.70000000007,1,500,null,15,null,null,null,422198.70000000007,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",2,"OPEX","Annual",1011124.7999999999,1,1000,null,15,null,null,null,1011124.7999999999,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",2,"OPEX","Annual",1643803,1,1500,null,15,null,null,null,1643803,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",2,"OPEX","Annual",3409459.1999999997,1,2500,null,15,null,null,null,3409459.1999999997,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 500",3,"OPEX","Annual",422198.70000000007,1,500,null,25,null,null,null,{"$f":"+I843*H843","v":422198.70000000007},"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1000",3,"OPEX","Annual",1011124.7999999999,1,1000,null,25,null,null,null,1011124.7999999999,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 1500",3,"OPEX","Annual",1643803,1,1500,null,25,null,null,null,1643803,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 25 Kw Distancia Mt (Ml ): Lr 2500",3,"OPEX","Annual",3409459.1999999997,1,2500,null,25,null,null,null,3409459.1999999997,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 500",3,"OPEX","Annual",422198.70000000007,1,500,null,15,null,null,null,422198.70000000007,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1000",3,"OPEX","Annual",1011124.7999999999,1,1000,null,15,null,null,null,1011124.7999999999,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 1500",3,"OPEX","Annual",1643803,1,1500,null,15,null,null,null,1643803,"N"]
["TMC 4G","Red Energia","Mto Pararrayos, Tierra","Tipo 2 15 Kw Distancia mts (Ml ): Lr 2500",3,"OPEX","Annual",3409459.1999999997,1,2500,null,15,null,null,null,3409459.1999999997,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 10 MHz Sectores 1 ",null,"CAPEX","Unitario",14402.25953337074,{"$f":"+TRM","v":4000},10,null,null,null,1,"S",57609038.133482955,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 10 MHz Sectores 2 ",null,"CAPEX","Unitario",16272.500028537303,4000,10,null,null,null,2,"S",65090000.114149213,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 10 MHz Sectores 3 ",null,"CAPEX","Unitario",18142.240523703858,4000,10,null,null,null,3,"S",72568962.094815433,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 20 MHz Sectores 1 ",null,"CAPEX","Unitario",14525.002620134994,{"$f":"+TRM","v":4000},20,null,null,null,1,"S",{"$f":"+I854*H854","v":58100010.480539978},"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 20 MHz Sectores 2 ",null,"CAPEX","Unitario",16517.986202065807,4000,20,null,null,null,2,"S",66071944.808263227,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 20 MHz Sectores 3 ",null,"CAPEX","Unitario",18516.677443448076,4000,20,null,null,null,3,"S",74066709.773792297,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 30 MHz Sectores 1 ",null,"CAPEX","Unitario",12818.881585522526,4000,30,null,null,null,1,"S",51275526.3420901,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 30 MHz Sectores 2 ",null,"CAPEX","Unitario",15963.165856164855,4000,30,null,null,null,2,"S",63852663.424659416,"N"]
["TMC 4G","4G","Digital EnodeB","Bw = 30 MHz Sectores 3 ",null,"CAPEX","Unitario",19206.245478844718,4000,30,null,null,null,3,"S",76824981.915378869,"N"]
["TMC 4G","4G","Licencias","Bw = 10 MHz Sectores 1 ",null,"CAPEX","Unitario",3065.44,4000,10,null,null,null,1,"S",{"$f":"+I860*H860","v":12261760},"N"]
["TMC 4G","4G","Licencias","Bw = 10 MHz Sectores 2 ",null,"CAPEX","Unitario",6130.88,4000,10,null,null,null,2,"S",{"$f":"+I861*H861","v":24523520},"N"]
["TMC 4G","4G","Licencias","Bw = 10 MHz Sectores 3 ",null,"CAPEX","Unitario",9196.32,4000,10,null,null,null,3,"S",36785280,"N"]
["TMC 4G","4G","Licencias","Bw = 20 MHz Sectores 1 ",null,"CAPEX","Unitario",3065.44,4000,20,null,null,null,1,"S",12261760,"N"]
["TMC 4G","4G","Licencias","Bw = 20 MHz Sectores 2 ",null,"CAPEX","Unitario",6130.88,4000,20,null,null,null,2,"S",24523520,"N"]
["TMC 4G","4G","Licencias","Bw = 20 MHz Sectores 3 ",null,"CAPEX","Unitario",9196.32,4000,20,null,null,null,3,"S",36785280,"N"]
["TMC 4G","4G","Licencias","Bw = 30 MHz Sectores 1 ",null,"CAPEX","Unitario",3065.44,4000,30,null,null,null,1,"S",12261760,"N"]
["TMC 4G","4G","Licencias","Bw = 30 MHz Sectores 2 ",null,"CAPEX","Unitario",6130.88,4000,30,null,null,null,2,"S",24523520,"N"]
["TMC 4G","4G","Licencias","Bw = 30 MHz Sectores 3 ",null,"CAPEX","Unitario",9196.32,4000,30,null,null,null,3,"S",36785280,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 10 MHz Sectores 1 ",null,"CAPEX","Unitario",6673.8,4000,10,null,null,null,1,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 10 MHz Sectores 2 ",null,"CAPEX","Unitario",6673.8,4000,10,null,null,null,2,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 10 MHz Sectores 3 ",null,"CAPEX","Unitario",6673.8,4000,10,null,null,null,3,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 20 MHz Sectores 1 ",null,"CAPEX","Unitario",6673.8,4000,20,null,null,null,1,"S",{"$f":"+I872*H872","v":26695200},"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 20 MHz Sectores 2 ",null,"CAPEX","Unitario",6673.8,4000,20,null,null,null,2,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 20 MHz Sectores 3 ",null,"CAPEX","Unitario",6673.8,4000,20,null,null,null,3,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 30 MHz Sectores 1 ",null,"CAPEX","Unitario",6673.8,4000,30,null,null,null,1,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 30 MHz Sectores 2 ",null,"CAPEX","Unitario",6673.8,4000,30,null,null,null,2,"S",26695200,"N"]
["TMC 4G","4G","Rectificador Y Baterias Para Enodob","Bw = 30 MHz Sectores 3 ",null,"CAPEX","Unitario",6673.8,4000,30,null,null,null,3,"S",26695200,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo1","Bw = 10 MHz   ",1,"CAPEX","Unitario",14587755.857000001,1,10,null,null,null,null,"S",{"$f":"+I878*H878","v":14587755.857000001},"N"]
["TMC 4G","4G","Instalación Enodeb Tipo1","Bw = 20 MHz   ",1,"CAPEX","Unitario",14587755.857000001,1,20,null,null,null,null,"S",14587755.857000001,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo1","Bw = 30 MHz   ",1,"CAPEX","Unitario",14587755.857000001,1,30,null,null,null,null,"S",14587755.857000001,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo2","Bw = 10 MHz   ",2,"CAPEX","Unitario",14587755.857000001,1,10,null,null,null,null,"S",{"$f":"+I881*H881","v":14587755.857000001},"N"]
["TMC 4G","4G","Instalación Enodeb Tipo2","Bw = 20 MHz   ",2,"CAPEX","Unitario",14587755.857000001,1,20,null,null,null,null,"S",14587755.857000001,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo2","Bw = 30 MHz   ",2,"CAPEX","Unitario",14587755.857000001,1,30,null,null,null,null,"S",14587755.857000001,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo3","Bw = 10 MHz   ",3,"CAPEX","Unitario",17114241.47972,1,10,null,null,null,null,"S",{"$f":"+I884*H884","v":17114241.47972},"N"]
["TMC 4G","4G","Instalación Enodeb Tipo3","Bw = 20 MHz   ",3,"CAPEX","Unitario",17114241.47972,1,20,null,null,null,null,"S",17114241.47972,"N"]
["TMC 4G","4G","Instalación Enodeb Tipo3","Bw = 30 MHz   ",3,"CAPEX","Unitario",17114241.47972,1,30,null,null,null,null,"S",17114241.47972,"N"]
["TMC 4G","4G","Antena De Transmision","Diametros De Antena (mts) 1,2  ",null,"CAPEX","Unitario",1375.43,4000,1.2,null,null,null,null,"S",5501720,"N"]
["TMC 4G","4G","Antena De Transmision","Diametros De Antena (mts) 1,8  ",null,"CAPEX","Unitario",1568,4000,1.8,null,null,null,null,"S",6272000,"N"]
["TMC 4G","4G","Antena De Transmision","Diametros De Antena (mts) 2,4  ",null,"CAPEX","Unitario",3702.44,4000,2.4,null,null,null,null,"S",14809760,"N"]
["TMC 4G","4G","Antena De Transmision","Diametros De Antena (mts) 3,7  ",null,"CAPEX","Unitario",5770.3672236503853,4000,3.7,null,null,null,null,"S",23081468.894601543,"N"]
["TMC 4G","4G","Equipos terminales enlace MW - HTSB","28/30 MHz < 10 GHz",null,"CAPEX","Unitario",40652.36,4000,"28/30 MHz < 10 GHz",null,null,null,null,"S",{"$f":"+I891*H891","v":162609440},"N",null,44000000,{"$f":"+S891/4000","v":11000}]
["TMC 4G","4G","Equipos terminales enlace MW - HTSB","28/30 MHz >10 GHz",null,"CAPEX","Unitario",25166.399999999998,4000,"28/30 MHz >10 GHz",null,null,null,null,"S",100665599.99999999,"N"]
["TMC 4G","4G","Equipos terminales enlace MW - HTSB","56 MHz < 10 GHz",null,"CAPEX","Unitario",40652.36,4000,"56 MHz < 10 GHz",null,null,null,null,"S",162609440,"N"]
["TMC 4G","4G","Equipos terminales enlace MW - HTSB","56 MHz > 10 GHz",null,"CAPEX","Unitario",25166.399999999998,4000,"56 MHz > 10 GHz",null,null,null,null,"S",100665599.99999999,"N"]
["TMC 4G","4G","Mto Digital Enodeb Soporte Fabricante /Anual","Tipo 1",1,"OPEX","Annual",2962915.8434979874,1,null,null,null,null,null,"S",2962915.8434979874,"N"]
["TMC 4G","4G","Mto Digital Enodeb Soporte Fabricante /Anual","Tipo 2",2,"OPEX","Annual",3555499.0121975848,1,null,null,null,null,null,"S",3555499.0121975848,"N"]
["TMC 4G","4G","Mto Digital Enodeb Soporte Fabricante /Anual","Tipo 3",3,"OPEX","Annual",6399898.2219556533,1,null,null,null,null,null,"S",6399898.2219556533,"N"]
["TMC 4G","4G","Mto Enlace De Transmision Mw Soporte Fabricante /Anual","Tipo 1",1,"OPEX","Annual",1000000,1,null,null,null,null,null,"S",1000000,"N"]
["TMC 4G","4G","Mto Enlace De Transmision Mw Soporte Fabricante /Anual","Tipo 2",2,"OPEX","Annual",1300000,1,null,null,null,null,null,"S",1300000,"N"]
["TMC 4G","4G","Mto Enlace De Transmision Mw Soporte Fabricante /Anual","Tipo 3",3,"OPEX","Annual",2366000,1,null,null,null,null,null,"S",2366000,"N"]
["TMC 4G","4G","Mto Correctivo Enodeb Estimado / Evento","Tipo 1",1,"OPEX","Evento",3000000,1,null,null,null,null,null,"S",3000000,"N"]
["TMC 4G","4G","Mto Correctivo Enodeb Estimado / Evento","Tipo 2",2,"OPEX","Evento",3900000,1,null,null,null,null,null,"S",3900000,"N"]
["TMC 4G","4G","Mto Correctivo Enodeb Estimado / Evento","Tipo 3",3,"OPEX","Evento",7097999.9999999991,1,null,null,null,null,null,"S",7097999.9999999991,"N"]
["TMC 4G","4G","Mto Correctivo Enlace De Transmision Mw /Evento","Tipo 1",1,"OPEX","Evento",2000000,1,null,null,null,null,null,"S",2000000,"N"]
["TMC 4G","4G","Mto Correctivo Enlace De Transmision Mw /Evento","Tipo 2",2,"OPEX","Evento",2600000,1,null,null,null,null,null,"S",2600000,"N"]
["TMC 4G","4G","Mto Correctivo Enlace De Transmision Mw /Evento","Tipo 3",3,"OPEX","Evento",4732000,1,null,null,null,null,null,"S",4732000,"N"]
["TMC 4G","4G","Planta Electrica","Tipo 1 Kw (Tipos De Plantas) 5 (Kw) ",1,"CAPEX","Unitario",10000,{"$f":"+TRM","v":4000},5,null,null,null,null,"S",{"$f":"+I907*H907","v":40000000},"N"]
["TMC 4G","4G","Planta Electrica","Tipo 1 Kw (Tipos De Plantas) 15 (Kw) ",1,"CAPEX","Unitario",15650.6,4000,15,null,null,null,null,"S",{"$f":"+I908*H908","v":62602400},"N"]
["TMC 4G","4G","Planta Electrica","Tipo 1 Kw (Tipos De Plantas) 25 (Kw) ",1,"CAPEX","Unitario",16749.46,4000,25,null,null,null,null,"S",{"$f":"+I909*H909","v":66997840},"N"]
["TMC 4G","4G","Planta Electrica","Tipo 2 Kw (Tipos De Plantas) 5 (Kw) ",2,"CAPEX","Unitario",10000,4000,5,null,null,null,null,"S",40000000,"N",null,{"$f":"H910*1.1","v":11000}]
["TMC 4G","4G","Planta Electrica","Tipo 2 Kw (Tipos De Plantas) 15 (Kw) ",2,"CAPEX","Unitario",15650.6,4000,15,null,null,null,null,"S",62602400,"N"]
["TMC 4G","4G","Planta Electrica","Tipo 2 Kw (Tipos De Plantas) 25 (Kw) ",2,"CAPEX","Unitario",16749.46,4000,25,null,null,null,null,"S",{"$f":"+I912*H912","v":66997840},"N"]
["TMC 4G","4G","Planta Electrica","Tipo 3 Kw (Tipos De Plantas) 5 (Kw) ",3,"CAPEX","Unitario",10000,4000,5,null,null,null,null,"S",40000000,"N",null,{"$f":"H912*1.1","v":18424.405999999999}]
["TMC 4G","4G","Planta Electrica","Tipo 3 Kw (Tipos De Plantas) 15 (Kw) ",3,"CAPEX","Unitario",15650.6,4000,15,null,null,null,null,"S",62602400,"N"]
["TMC 4G","4G","Planta Electrica","Tipo 3 Kw (Tipos De Plantas) 25 (Kw) ",3,"CAPEX","Unitario",16749.46,4000,25,null,null,null,null,"S",{"$f":"+I915*H915","v":66997840},"N"]
["TMC 4G","4G","Transferencia Y Control","Tipo 1 Kw (Tipos De Plantas) 5 (Kw) ",1,"CAPEX","Unitario",2548,4000,5,null,null,null,null,"S",10192000,"N"]
["TMC 4G","4G","Transferencia Y Control","Tipo 1 Kw (Tipos De Plantas) 15 (Kw) ",1,"CAPEX","Unitario",3014.2857142857142,4000,15,null,null,null,null,"S",12057142.857142856,"N"]
["TMC 4G","4G","Transferencia Y Control","Tipo 2 Kw (Tipos De Plantas) 5 (Kw) ",2,"CAPEX","Unitario",2548,4000,5,null,null,null,null,"S",10192000,"N",null,{"$f":"H920*1.1","v":2802.8}]
["TMC 4G","4G","Transferencia Y Control","Tipo 2 Kw (Tipos De Plantas) 15 (Kw) ",2,"CAPEX","Unitario",3014.2857142857142,4000,15,null,null,null,null,"S",12057142.857142856,"N"]
["TMC 4G","4G","Transferencia Y Control","Tipo 3 Kw (Tipos De Plantas) 5 (Kw) ",3,"CAPEX","Unitario",2548,4000,5,null,null,null,null,"S",10192000,"N"]
["TMC 4G","4G","Transferencia Y Control","Tipo 3 Kw (Tipos De Plantas) 15 (Kw) ",3,"CAPEX","Unitario",3014.2857142857142,4000,15,null,null,null,null,"S",12057142.857142856,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 1 Kw (Tipos De Plantas) 15 Kw (   ) ",1,"OPEX","Annual",2767562,1,15,null,null,null,null,"S",2767562,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 1 Kw (Tipos De Plantas) 25 Kw (   ) ",1,"OPEX","Annual",2767562,1,25,null,null,null,null,"S",2767562,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 2 Kw (Tipos De Plantas) 15 Kw (   ) ",2,"OPEX","Annual",2806562,1,15,null,null,null,null,"S",2806562,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 2 Kw (Tipos De Plantas) 25 Kw (   ) ",2,"OPEX","Annual",2806562,1,25,null,null,null,null,"S",2806562,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 3 Kw (Tipos De Plantas) 15 Kw (   ) ",3,"OPEX","Annual",4743079.1503957789,1,15,null,null,null,null,"S",4743079.1503957789,"N"]
["TMC 4G","4G","Mto Preventivoplanta Electrica / Anual","Tipo 3 Kw (Tipos De Plantas) 25 Kw (   ) ",3,"OPEX","Annual",4743079.1503957789,1,25,null,null,null,null,"S",4743079.1503957789,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 1 Kw (Tipos De Plantas) 15 Kw (   ) ",1,"OPEX","Annual",300000,1,15,null,null,null,null,"S",300000,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 1 Kw (Tipos De Plantas) 25 Kw (   ) ",1,"OPEX","Annual",300000,1,25,null,null,null,null,"S",300000,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 2 Kw (Tipos De Plantas) 15 Kw (   ) ",2,"OPEX","Annual",390000,1,15,null,null,null,null,"S",390000,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 2 Kw (Tipos De Plantas) 25 Kw (   ) ",2,"OPEX","Annual",390000,1,25,null,null,null,null,"S",390000,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 3 Kw (Tipos De Plantas) 15 Kw (   ) ",3,"OPEX","Annual",709799.99999999988,1,15,null,null,null,null,"S",709799.99999999988,"N"]
["TMC 4G","4G","Mto Preventivo Transferencia Y Control / Anual","Tipo 3 Kw (Tipos De Plantas) 25 Kw (   ) ",3,"OPEX","Annual",709799.99999999988,1,25,null,null,null,null,"S",709799.99999999988,"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 1 Kw (Tipos De Plantas) 15 Kw (   ) ",1,"OPEX","Evento",1212899.1954691075,1,15,null,null,null,null,"S",{"$f":"+I934*H934","v":1212899.1954691075},"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 1 Kw (Tipos De Plantas) 25 Kw (   ) ",1,"OPEX","Evento",1212899.1954691075,1,25,null,null,null,null,"S",1212899.1954691075,"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 2 Kw (Tipos De Plantas) 15 Kw (   ) ",2,"OPEX","Evento",873563.66568914952,1,15,null,null,null,null,"S",873563.66568914952,"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 2 Kw (Tipos De Plantas) 25 Kw (   ) ",2,"OPEX","Evento",873563.66568914952,1,25,null,null,null,null,"S",873563.66568914952,"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 3 Kw (Tipos De Plantas) 15 Kw (   ) ",3,"OPEX","Evento",3629396.8161829375,1,15,null,null,null,null,"S",3629396.8161829375,"N"]
["TMC 4G","4G","Mto Correctivo Planta Electrica / Evento","Tipo 3 Kw (Tipos De Plantas) 25 Kw (   ) ",3,"OPEX","Evento",3629396.8161829375,1,25,null,null,null,null,"S",3629396.8161829375,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 1 Kw (Tipos De Plantas) 15 Kw (   ) ",1,"OPEX","Evento",1000000,1,15,null,null,null,null,"S",1000000,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 1 Kw (Tipos De Plantas) 25 Kw (   ) ",1,"OPEX","Evento",1000000,1,25,null,null,null,null,"S",1000000,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 2 Kw (Tipos De Plantas) 15 Kw (   ) ",2,"OPEX","Evento",1300000,1,15,null,null,null,null,"S",1300000,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 2 Kw (Tipos De Plantas) 25 Kw (   ) ",2,"OPEX","Evento",1300000,1,25,null,null,null,null,"S",1300000,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 3 Kw (Tipos De Plantas) 15 Kw (   ) ",3,"OPEX","Evento",2366000,1,15,null,null,null,null,"S",2366000,"N"]
["TMC 4G","4G","Mto Correctivo Transferencia Y Control / Evento","Tipo 3 Kw (Tipos De Plantas) 25 Kw (   ) ",3,"OPEX","Evento",2366000,1,25,null,null,null,null,"S",2366000,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 1 Kw (Tipos De Plantas) 15 Kw (   ) ",1,"OPEX","Mensual",2809113.16,1,15,null,null,null,null,"S",2809113.16,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 1 Kw (Tipos De Plantas) 25 Kw (   ) ",1,"OPEX","Mensual",2809113.16,1,25,null,null,null,null,"S",2809113.16,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 2 Kw (Tipos De Plantas) 15 Kw (   ) ",2,"OPEX","Mensual",6553544.2000000002,1,15,null,null,null,null,"S",6553544.2000000002,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 2 Kw (Tipos De Plantas) 25 Kw (   ) ",2,"OPEX","Mensual",6553544.2000000002,1,25,null,null,null,null,"S",6553544.2000000002,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 3 Kw (Tipos De Plantas) 15 Kw (   ) ",3,"OPEX","Mensual",13296639.02,1,15,null,null,null,null,"S",13296639.02,"N"]
["TMC 4G","4G","Consumo Combustible / Mensual","Tipo 3 Kw (Tipos De Plantas) 25 Kw (   ) ",3,"OPEX","Mensual",13296639.02,1,25,null,null,null,null,"S",13296639.02,"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Instalacion",1,"CAPEX","Unitario",1000000,1,null,null,null,null,null,"S",1000000,"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Instalacion",2,"CAPEX","Unitario",1000000,1,null,null,null,null,null,"S",{"$f":"+I953*H953","v":1000000},"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Instalacion",3,"CAPEX","Unitario",1000000,1,null,null,null,null,null,"S",1000000,"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Panel de control & Perifericos",1,"CAPEX","Unitario",5015.2577999999994,{"$f":"+TRM","v":4000},null,null,null,null,null,"S",20061031.199999999,"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Panel de control & Perifericos",2,"CAPEX","Unitario",5015.2577999999994,{"$f":"+TRM","v":4000},null,null,null,null,null,"S",20061031.199999999,"N"]
["TMC 4G","4G","Sistema De Seguridad Electronica","Panel de control & Perifericos",3,"CAPEX","Unitario",5015.2577999999994,{"$f":"+TRM","v":4000},null,null,null,null,null,"S",20061031.199999999,"N"]
["TMC 4G","4G","Mto Sistema De Seguridad Electronica","Na",null,"OPEX","Annual",9683761.2200000007,1,null,null,null,null,null,"S",9683761.2200000007,"N"]
["TMC 4G","OPEX General","Energia Electrica - menos de 3 meses","Energia Electrica - menos de 3 meses",null,"OPEX","Mensual",8715000,1,"TMC 4G",null,null,null,null,"S",{"$f":"+I959*H959","v":8715000},"N"]
["TMC 4G","OPEX General","Licencias MW MinTIC","Na",null,"OPEX","Mensual",{"$f":"+'Espectro MW'!C9/12","v":1571182.7679744002},1,"TMC 4G",null,null,null,null,"S",{"$f":"+I960*H960","v":1571182.7679744002},"N"]
["TMC 4G","OPEX General","Seguros","Na",null,"OPEX","Mensual",5052.9840000000004,1,"TMC 4G",null,null,null,null,"S",5052.9840000000004,"N"]
["TMC 4G","OPEX General","Monitoreo y Gestión","Monitoreo y Gestión",null,"OPEX","Mensual",190000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",190000,"N"]
["LTE No Lic BH Satelital","LTE No Lic BH Satelital","Plan satelital","250 Gb/mes",null,"OPEX","Mensual",1800000,1,"LTE No Lic BH Satelital",null,null,null,null,null,1800000,"N"]
["LTE No Lic BH Satelital","LTE No Lic BH Satelital","Cargo de activacion","250 Gb/mes",null,"CAPEX","Unitario",190400,1,"LTE No Lic BH Satelital",null,null,null,null,null,190400,"N"]
["LTE No Lic BH Satelital","LTE No Lic BH Satelital","VSAT (con instalacion)","VSAT (con instalacion)",null,"CAPEX","Unitario",2000000,1,"LTE No Lic BH Satelital",null,null,null,null,null,{"$f":"+IF('Parametros tecnológicos'!C26=\"S\",I965*H965,0)","v":2000000},"N"]
["LTE No Lic BH Microondas","LTE No Lic BH Microondas","CPE","CPE",null,"CAPEX","Unitario",500000,1,null,null,null,null,null,null,{"$f":"+H966*Subscriptores","v":1421550000},"N"]
["Repetidora","Repetidora","Energia Solar - Repetidora","Energia Solar - Repetidora",null,"CAPEX","Unitario",{"$f":"+'Parametros tecnológicos'!D34*'Parametros tecnológicos'!D35*'Parametros tecnológicos'!D36","v":0},4000,null,null,null,null,null,null,{"$f":"+H967*I967","v":0},"N"]
["FTTH","FTTH","Splitter óptico","Splitter óptico",null,"CAPEX","Unitario",30000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I968*H968*Splitters","v":0},"N"]
["FTTH","FTTH","OLT","OLT",null,"CAPEX","Unitario",4000,{"$f":"+TRM","v":4000},"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I969*H969","v":16000000},"N"]
["FTTH","FTTH","Firewall & Caché Server","Firewall & Caché Server",null,"CAPEX","Unitario",42000000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I970*H970","v":42000000},"N"]
["FTTH","FTTH","Poste Servidumbre / 5 Años","Poste Servidumbre / 5 Años",null,"CAPEX","Unitario",66000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I971*H971*Cantidad_postes","v":0},"N"]
["FTTH","FTTH","Cable óptico (48 hilos) Troncal/Km (Instalado)","Cable óptico (48 hilos) Troncal/Km (Instalado)",null,"CAPEX","Unitario",3000,{"$f":"+TRM","v":4000},"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I972*H972*Longitud_BackHaul","v":0},"N"]
["FTTH","FTTH","Cable óptico Acometida /Mt","Cable óptico Acometida /Mt",null,"CAPEX","Unitario",2,{"$f":"+TRM","v":4000},"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I973*H973*Subscriptores*LongitudAcometida","v":0},"N"]
["FTTH","FTTH","Pigtail","Pigtail",null,"CAPEX","Unitario",10500,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I974*H974*Subscriptores","v":29852550},"N"]
["FTTH","FTTH","ONT","ONT",null,"CAPEX","Unitario",500000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I975*H975*Subscriptores","v":1421550000},"N"]
["FTTH","FTTH","Costo Energía Eléctrica ","Costo Energía Eléctrica ",null,"CAPEX","Unitario",12960000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I976*H976","v":12960000},"N"]
["FTTH","FTTH","Costo Espectro Radioeléctrico ","Costo Espectro Radioeléctrico ",null,"CAPEX","Unitario",{"$f":"((20*0.1*Subscriptores)/8)*(10000000*5+0.2*10000000*5)/30","v":1421550000},1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I977*H977","v":1421550000},"N"]
["FTTH","FTTH","Costo Transporte (Mbps)","Costo Transporte (Mbps)",null,"OPEX","Unitario",{"$f":"+(20*0.1*Subscriptores)*30000","v":170586000},1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I978*H978","v":170586000},"N"]
["FTTH","FTTH","Materiales instalación FTTH","Materiales instalación FTTH",null,"CAPEX","Unitario",50000,1,"LTE No Lic BH Satelital",null,null,null,null,"S",{"$f":"+I979*H979*Subscriptores","v":142155000},"N"]

{"sheet":"Resultados","index":4,"n_rows":5,"n_cols":2,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
["Resultados"]
[]
["Total",{"$f":"+SUM(B4:B5)","v":1631031498.4730749}]
["CAPEX",{"$f":"+SUM(Modelo!$B$19:$B$101)","v":640850139.35676837}]
["OPEX",{"$f":"+SUM(Modelo!G19:DV101)","v":990181359.11630642}]

{"sheet":"Tablas Espectro MW","index":5,"n_rows":46,"n_cols":2,"rows_kept":46,"cut":false,"hidden":false,"merged":[]}
["Calculo del Valor Anual de Contraprestaciones (VAC)"]
["Basado en Resolución 2734 de 2019"]
[]
["Valores del factor de valoración de banda Fv "]
[]
["Frecuencia de enlace F [MHz] ","Fv [1/MHz] "]
["3 < F = 1.000 ",1]
["1.000 < F = 3.000 ",0.8]
["3.000 < F = 3.700 ",0.7]
["3.700 < F = 7100 ",0.61199999999999999]
["7.100 < F = 14.000 ",0.54400000000000004]
["14.000 < F = 20.000 ",0.47599999999999998]
["20.000 < F = 30.000 ",0.40799999999999997]
["30.000 < F = 70.000 ",3.7499999999999999E-2]
["70.000 < F = 300.000 ",5.4999999999999997E-3]
[]
["Valores del factor de priorización (Fp) "]
[]
["Ubicación de cada sitio del enlace ","Factor de Priorización Fp "]
["Departamentos priorizados ",0.1]
["Áreas no identificadas como cabeceras municipales ",0.7]
["Cabeceras municipales que no se ubican en departamentos priorizados ",0.8]
["Enlaces con fecha anterior al 1 de enero de 2020 en la Columna 2C del Cuadro de Características Técnicas de Red ",0.8]
[]
["Departamentos priorizados "]
[]
["Código DANE del departamento ","Departamento "]
[27,"Chocó "]
[44,"La Guajira "]
[94,"Guainía "]
[97,"Vaupés "]
[99,"Vichada "]
[19,"Cauca "]
[95,"Guaviare "]
[18,"Caquetá "]
[70,"Sucre "]
[23,"Córdoba "]
[86,"Putumayo "]
[91,"Amazonas "]
[null,"Otro"]
["Valores del factor de distancia Fd "]
[]
["Descripción del criterio ","Condición "]
["Satisface la distancia mínima del CNABF ",0.9]
["Enlaces con fecha anterior al 1 de enero de 2020 en la Columna 2C del Cuadro de Características Técnicas de Red ",0.9]
["NO Satisface la distancia mínima del CNABF ",1.1000000000000001]

{"sheet":"Datos","index":6,"n_rows":11,"n_cols":2,"rows_kept":11,"cut":false,"hidden":true,"merged":[]}
["Resumen"]
[]
["Fecha inicio",{"$f":"+TODAY()","v":"2020-06-26"}]
["WACC"]
["VPN"]
[]
["Utilizado"]
["S"]
["N"]
["Dias"]
[31]